﻿


{"id":217615,"date":"2023-11-19T07:55:07","date_gmt":"2023-11-19T06:55:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=217615"},"modified":"2023-11-15T23:48:09","modified_gmt":"2023-11-15T22:48:09","slug":"adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/","title":{"rendered":"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!&#8221;"},"content":{"rendered":"<h2>Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva<br \/>\n<!--more--><\/h2>\n<p>Un recente articolo apparso su <strong>\u201cInternazionale\u201d<\/strong> racconta dei guerriglieri delle <strong>Forze Armate Rivoluzionarie<\/strong> della\u00a0<strong>Colombia<\/strong>\u00a0che si reinventano come guide turistiche <strong>\u201csostituendo\u201d i remi ai fucili<\/strong>.<br \/>\nL\u2019articolo ha riportato alla mente di un <strong>operatore Ai.Bi. <\/strong>un abbinamento di qualche anno fa.<\/p>\n<h3>L\u2019adozione di quattro fratellini<\/h3>\n<p>Una futura famiglia adottiva si trovava a colloquio per l\u2019abbinamento con cui avrebbe accolto di l\u00ec a poco <strong>quattro fratellini colombiani<\/strong>.<br \/>\n<strong>Un\u2019accoglienza di per se straordinaria<\/strong>: adottare un gruppo di fratelli cos\u00ec numeroso non \u00e8 da tutti, bisogna sentire di avere le risorse per affrontare la complessit\u00e0 e la ricchezza di un gruppo di fratelli e diventare in un attimo, una famiglia di sei componenti, non pi\u00f9 solo due.<\/p>\n<h3>\u201cUn gruppetto di guerriglieri\u201d<\/h3>\n<p>I fratelli venivano inoltre da una storia particolare, erano nati da <strong>un incontro d\u2019amore tra due guerriglieri delle FARC<\/strong>, che poco dopo, dovettero scappare per aver subito minacce di morte.<br \/>\nAccettato l\u2019abbinamento, il futuro pap\u00e0 adottivo si rivolse al referente di sede e disse sorridente e sarcastico: <strong>\u201cStiamo accogliendo in casa un gruppetto di guerriglieri!\u201d<\/strong><br \/>\nI ragazzini si sono rivelati dolcissimi e hanno completato ormai una <strong>bellissima famiglia adottiva<\/strong>.<br \/>\nIl pap\u00e0, che aveva dimenticato il simpatico aneddoto, ha recentemente commentato: \u201c I piccoli guerriglieri durante le vacanze estive stanno lavorano come camerieri in una rinomata pizzeria della nostra zona, e il nostro pi\u00f9 grande l\u2019anno prossimo porter\u00e0 la resistenza delle FARC in <strong>Danimarca<\/strong>, per un anno di <strong>intercultura<\/strong>\u201d.<\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una coppia italiana adotta quattro fratellini colombiani, frutto dell&rsquo;amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos&igrave; una bellissima famiglia adottiva<\/p>\n","protected":false},"author":133,"featured_media":217616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[372],"class_list":["post-217615","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozioni-internazionali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale. \u201cStiamo accogliendo un gruppo di guerriglieri&quot;<\/title>\n<meta name=\"description\" content=\"Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!&quot;\" \/>\n<meta property=\"og:description\" content=\"Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-19T06:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Adozione-Internazionale-FARC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!&#8221;\",\"datePublished\":\"2023-11-19T06:55:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Adozione-Internazionale-FARC.jpg\",\"keywords\":[\"adozioni internazionali\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/\",\"name\":\"Adozione Internazionale. \u201cStiamo accogliendo un gruppo di guerriglieri\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Adozione-Internazionale-FARC.jpg\",\"datePublished\":\"2023-11-19T06:55:07+00:00\",\"description\":\"Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Adozione-Internazionale-FARC.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Adozione-Internazionale-FARC.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale. \u201cStiamo accogliendo un gruppo di guerriglieri\"","description":"Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!\"","og_description":"Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-11-19T06:55:07+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Adozione-Internazionale-FARC.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!&#8221;","datePublished":"2023-11-19T06:55:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/"},"wordCount":315,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Adozione-Internazionale-FARC.jpg","keywords":["adozioni internazionali"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/","name":"Adozione Internazionale. \u201cStiamo accogliendo un gruppo di guerriglieri\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Adozione-Internazionale-FARC.jpg","datePublished":"2023-11-19T06:55:07+00:00","description":"Una coppia italiana adotta quattro fratellini colombiani, frutto dell\u2019amore di due membri delle FARC (Forze Armate Rivoluzionarie della Colombia): nasce cos\u00ec una bellissima famiglia adottiva","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Adozione-Internazionale-FARC.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Adozione-Internazionale-FARC.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-stiamo-accogliendo-gruppetto-guerriglieri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale. \u201cStiamo accogliendo in casa un gruppetto di guerriglieri!&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:50:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=217615"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/217616"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=217615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=217615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=217615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}