﻿{"id":217867,"date":"2023-11-27T14:46:56","date_gmt":"2023-11-27T13:46:56","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=217867"},"modified":"2023-11-27T14:46:56","modified_gmt":"2023-11-27T13:46:56","slug":"ultima-data-dichiarazione-redditi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/","title":{"rendered":"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5&#215;1000 ad Ai.Bi."},"content":{"rendered":"<h2>Entro il mese di novembre scadono i termini per la presentazione del modello Redditi, ultimo appuntamento per la dichiarazione dei redditi 2023. L\u2019ultima occasione anche per destinare il 5&#215;1000 ad Ai.Bi. in favore dei bambini abbandonati<\/h2>\n<p><!--more--><\/p>\n<p><strong>Gioved\u00ec 30 novembre<\/strong> si chiuder\u00e0 definitivamente la \u201cstagione\u201d della dichiarazione dei redditi 2023, relativa all\u2019anno 2022. Ultimo all\u2019appello, infatti, \u00e8 il termine per la presentazione del \u201c<strong>modello Redditi<\/strong>\u201d, necessario per le partite Iva (anche nel caso in cui si abbiano redditi pari a zero per il periodo d\u2019imposta 2022) e i lavoratori autonomi, ma utilizzato anche per chi deve apportare una correzione relativa la modello 730 gi\u00e0 presentato, oppure per quei lavoratori dipendenti e pensionati che non abbiamo fatto in tempo a presentare entro i termini il loro 730.<\/p>\n<h3>I bambini prime vittime delle emergenze. Dona il tuo 5&#215;1000 ad Ai.Bi.<\/h3>\n<p>\u00c8, quindi, il 30 novembre, anche l\u2019ultima possibilit\u00e0 per <strong>destinare il 5&#215;1000 ad Ai.Bi.<\/strong> Un contributo fondamentale per continuare a portare avanti tutte le attivit\u00e0 dell\u2019Associazione in aiuto dei bambini abbandonati, nella ferma convinzione che, come recita lo slogan della campagna scelto per quest\u2019anno: \u201c<strong>i bambini sono le prime vittime delle emergenze<\/strong>\u201d, di qualunque natura esse siano. \u201cDa 40 anni Ai.Bi. c\u2019\u00e8!\u201d.<br \/>\nVa ricordato che il 5 x 1000 \u00e8 una piccola percentuale delle tasse che ciascuno deve pagare e che andrebbe comunque versata. Non si tratta, quindi, di un pagamento \u201cin pi\u00f9\u201d, ma della <strong>possibilit\u00e0 di scegliere a chi destinare<\/strong> una parte di quanto dovuto allo Stato.<br \/>\nA <a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/5xmille\/\">questa pagina<\/a> del sito di Ai.Bi. si possono trovare tutte le informazioni per approfondire l\u2019argomento e per vedere dei piccoli esempi concreti di cosa significhi il 5&#215;1000 per tanti bambini in difficolt\u00e0.<\/p>\n<h3>Le novit\u00e0 della dichiarazione dei redditi 2024<\/h3>\n<p>Tornando pi\u00f9 direttamente alla questione tasse, il 2023 dovrebbe anche essere l\u2019ultimo anno nel quale la scadenza della presentazione del modello Redditi \u00e8 alla fine di novembre. Tra i vari cambiamenti che verranno introdotti a partire dal 2024, infatti, c\u2019\u00e8 anche quello che <strong>allinea le date di presentazione<\/strong> di questo modello con il 730, che andranno presentate indistintamente entro il 30 di settembre di ogni anno.<br \/>\nQuello che non cambier\u00e0, sar\u00e0 la possibilit\u00e0 di scegliere di <strong>destinare il proprio 5 x 1000: Ai.Bi.<\/strong>: oggi come in futuro i bambini abbandonati avranno sempre bisogno di qualcuno che si schieri al loro fianco. Come Amici dei Bambini fa ormai da oltre 40 anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entro il mese di novembre scadono i termini per la presentazione del modello Redditi, ultimo appuntamento per la dichiarazione dei redditi 2023. L&rsquo;ultima occasione anche per destinare il 5&times;1000 ad Ai.Bi. in favore dei bambini abbandonati<\/p>\n","protected":false},"author":102,"featured_media":217872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[665,922,829],"class_list":["post-217867","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-5xmille","tag-dichiarazione-redditi","tag-tasse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>30 novembre. Ultima data per la dichiarazione dei redditi<\/title>\n<meta name=\"description\" content=\"Entro il mese di novembre scadono i termini per la presentazione dell&#039;ultima dichiarazione dei redditi. Ultima occasione per destinare il 5x1000 ad Ai.Bi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5x1000 ad Ai.Bi.\" \/>\n<meta property=\"og:description\" content=\"Entro il mese di novembre scadono i termini per la presentazione dell&#039;ultima dichiarazione dei redditi. Ultima occasione per destinare il 5x1000 ad Ai.Bi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T13:46:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/dichiarazione-dei-redditi-novembre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5&#215;1000 ad Ai.Bi.\",\"datePublished\":\"2023-11-27T13:46:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/dichiarazione-dei-redditi-novembre.jpg\",\"keywords\":[\"5xmille\",\"dichiarazione redditi\",\"tasse\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/\",\"name\":\"30 novembre. Ultima data per la dichiarazione dei redditi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/dichiarazione-dei-redditi-novembre.jpg\",\"datePublished\":\"2023-11-27T13:46:56+00:00\",\"description\":\"Entro il mese di novembre scadono i termini per la presentazione dell'ultima dichiarazione dei redditi. Ultima occasione per destinare il 5x1000 ad Ai.Bi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/dichiarazione-dei-redditi-novembre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/dichiarazione-dei-redditi-novembre.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ultima-data-dichiarazione-redditi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5&#215;1000 ad Ai.Bi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"30 novembre. Ultima data per la dichiarazione dei redditi","description":"Entro il mese di novembre scadono i termini per la presentazione dell'ultima dichiarazione dei redditi. Ultima occasione per destinare il 5x1000 ad Ai.Bi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/","og_locale":"it_IT","og_type":"article","og_title":"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5x1000 ad Ai.Bi.","og_description":"Entro il mese di novembre scadono i termini per la presentazione dell'ultima dichiarazione dei redditi. Ultima occasione per destinare il 5x1000 ad Ai.Bi.","og_url":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-11-27T13:46:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/dichiarazione-dei-redditi-novembre.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5&#215;1000 ad Ai.Bi.","datePublished":"2023-11-27T13:46:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/"},"wordCount":404,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/dichiarazione-dei-redditi-novembre.jpg","keywords":["5xmille","dichiarazione redditi","tasse"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/","url":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/","name":"30 novembre. Ultima data per la dichiarazione dei redditi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/dichiarazione-dei-redditi-novembre.jpg","datePublished":"2023-11-27T13:46:56+00:00","description":"Entro il mese di novembre scadono i termini per la presentazione dell'ultima dichiarazione dei redditi. Ultima occasione per destinare il 5x1000 ad Ai.Bi.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/dichiarazione-dei-redditi-novembre.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/dichiarazione-dei-redditi-novembre.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ultima-data-dichiarazione-redditi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"30 novembre. Ultima data per la dichiarazione dei redditi. E per devolvere il 5&#215;1000 ad Ai.Bi."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:33:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=217867"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/217872"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=217867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=217867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=217867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}