﻿


{"id":217925,"date":"2023-11-29T07:30:34","date_gmt":"2023-11-29T06:30:34","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=217925"},"modified":"2023-11-30T09:13:16","modified_gmt":"2023-11-30T08:13:16","slug":"congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/","title":{"rendered":"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene"},"content":{"rendered":"<h2>La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza<!--more--><\/h2>\n<p>Il <strong>Natale si avvicina<\/strong> e i <strong>bambini degli orfanotrofi Fed e Sodas<\/strong>, in <strong>Congo<\/strong>, hanno messo in mostra la loro creativit\u00e0 e il loro affetto nei disegni che hanno realizzato per gli auguri per i loro sostenitori a distanza.<br \/>\n<strong>Un gesto di gratitudine e di speranza che ha coinvolto tutti con entusiasmo e impegno.<\/strong><br \/>\nLa preparazione dei disegni \u00e8 stata un momento di grande gioia per i bambini, che hanno potuto esprimere la loro fantasia e il loro talento artistico. Il personale di Ai.Bi., l&#8217;associazione che si occupa di sostenere i due orfanotrofi, ha assistito alla nascita delle opere, che sono state tutte diverse e originali.<\/p>\n<div id='gallery-1' class='gallery galleryid-217925 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/congo-regalo-natale-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Regalo-Natale-5.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Regalo-Natale-5.jpg 480w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Regalo-Natale-5-225x300.jpg 225w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Regalo-Natale-5-113x150.jpg 113w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/congo-natale-regalo-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regalo-4-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regalo-4-768x1024.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regalo-4-225x300.jpg 225w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regalo-4-113x150.jpg 113w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regalo-4-1152x1536.jpg 1152w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regalo-4.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&#8220;Gi\u00e0 gli scorsi anni ci eravamo accorti dell\u2019attenzione e importanza che i bambini danno a questa attivit\u00e0, ma quest\u2019anno \u00e8 stato speciale&#8221;, racconta il personale di Ai.Bi. &#8220;Dopo aver spiegato come utilizzare il foglio, in alto si scrive il nome del bambino e del sostenitore e abbiamo spiegato che \u00e8 scritto in italiano, i primo 30 minuti sono stati dedicati alla fantasia, un vero e proprio brainstorming tra i vari bambini, per trovare l\u2019ispirazione e per condividere le idee, dopodich\u00e9 un gran silenzio, la concentrazione era comune a tutti&#8221;.<br \/>\nI disegni sono stati realizzati con matite colorate, pennarelli, pastelli e collage.<\/p>\n<div id='gallery-2' class='gallery galleryid-217925 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/congo-natale-regali-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3-1200x900.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3-1200x900.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3-400x300.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3-150x113.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3-768x576.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3-1536x1152.jpg 1536w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-3.jpg 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/natale-congo-regali-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2-1200x900.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2-1200x900.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2-400x300.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2-150x113.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2-768x576.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2-1536x1152.jpg 1536w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Natale-Congo-regali-2.jpg 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/congo-natale-regali-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1-1200x900.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1-1200x900.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1-400x300.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1-150x113.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1-768x576.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1-1536x1152.jpg 1536w, https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali-1.jpg 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Il personale di Ai.Bi. ha visto in anteprima i disegni e meritano tutti un grande applauso. I bambini sono stati bravissimi e hanno dimostrato di avere un cuore grande e una voglia di comunicare con chi li aiuta a crescere e a studiare.<br \/>\nI disegni saranno inviati ai relativi sostenitori a distanza, che potranno apprezzare il gesto dei bambini e sentirsi ancora pi\u00f9 vicini a loro. Un modo per rafforzare il legame tra chi dona e chi riceve, e per diffondere il messaggio di pace e solidariet\u00e0 che il Natale porta con s\u00e9.<\/p>\n<h3>L\u2019Adozione a Distanza in Repubblica Democratica del Congo<\/h3>\n<p>Anche questa particolare attivit\u00e0 \u00e8 resa possibile grazie ai generosi contributi di tutti coloro che aderiscono al progetto di Ai.Bi. \u201c<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/adozione-a-distanza-in-congo\/\">Adotta a distanza i bambini<\/a> degli orfanotrofi del Congo\u201d: bastano 82 centesimi al giorno.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\" https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Congo\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Per richiedere informazioni sull\u2019Adozione a Distanza <a href=\"#infosad\"><strong>clicca qui<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare&nbsp;&nbsp;i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l&rsquo;Adozione a Distanza<\/p>\n","protected":false},"author":133,"featured_media":217926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[645,671],"class_list":["post-217925","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-fed","tag-sodas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene<\/title>\n<meta name=\"description\" content=\"La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene\" \/>\n<meta property=\"og:description\" content=\"La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-29T06:30:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-30T08:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene\",\"datePublished\":\"2023-11-29T06:30:34+00:00\",\"dateModified\":\"2023-11-30T08:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/\"},\"wordCount\":440,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Congo-Natale-regali.jpg\",\"keywords\":[\"Fed\",\"Sodas\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/\",\"name\":\"Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Congo-Natale-regali.jpg\",\"datePublished\":\"2023-11-29T06:30:34+00:00\",\"dateModified\":\"2023-11-30T08:13:16+00:00\",\"description\":\"La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Congo-Natale-regali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Congo-Natale-regali.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene","description":"La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/","og_locale":"it_IT","og_type":"article","og_title":"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene","og_description":"La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza","og_url":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-11-29T06:30:34+00:00","article_modified_time":"2023-11-30T08:13:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene","datePublished":"2023-11-29T06:30:34+00:00","dateModified":"2023-11-30T08:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/"},"wordCount":440,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali.jpg","keywords":["Fed","Sodas"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/","url":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/","name":"Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali.jpg","datePublished":"2023-11-29T06:30:34+00:00","dateModified":"2023-11-30T08:13:16+00:00","description":"La gioia dei bambini ospiti degli orfanotrofi Fed e Sodas nel disegnare\u00a0\u00a0i biglietti di auguri di Natale destinati per chi li sta sostenendo da lontano. Un gesto di gratitudine per chi ha scelto di aiutare questi bambini attraverso l\u2019Adozione a Distanza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Congo-Natale-regali.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/congo-regalo-natale-bambini-orfanotrofi-fed-sodas-sostiene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Repubblica Democratica del Congo. Un regalo di Natale speciale dai bambini degli orfanotrofi Fed e Sodas per chi li sostiene"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:46:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=217925"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/217926"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=217925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=217925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=217925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}