﻿


{"id":218409,"date":"2023-12-21T08:00:51","date_gmt":"2023-12-21T07:00:51","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=218409"},"modified":"2023-12-20T17:27:49","modified_gmt":"2023-12-20T16:27:49","slug":"peru-vita-umana-inizia-concepimento","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/","title":{"rendered":"Per\u00f9. La vita umana inizia dal concepimento!"},"content":{"rendered":"<h2>Con una decisione storica, il Congresso del Per\u00f9 riconosce il diritto alla vita a partire dal concepimento, momento nel quale ogni individuo ha diritto \u201call\u2019integrit\u00e0, alla vita e alla dignit\u00e0\u201d<strong><br \/>\n<\/strong><\/h2>\n<p><!--more--><\/p>\n<p>Decisione storica del <strong>Per\u00f9<\/strong>, che segna una decisiva vittoria per i movimenti pro-Vita e per la difesa dei diritti dei bambini, anche prima della loro nascita. Il Per\u00f9, infatti, \u00e8 il primo Paese del Sudamerica ad aver dichiarato \u201cdi fatto<strong>\u201d illegale l\u2019aborto<\/strong>, approvando un disegno di legge in cui viene riconosciuto come la vita umana (e la personalit\u00e0 giuridica di un individuo) <strong>inizi fin dal concepimento<\/strong> e non pi\u00f9 dalla data di nascita, com\u2019era secondo la legislazione precedente.<\/p>\n<h3>L\u2019affermazione del diritto alla vita<\/h3>\n<p>La decisione del Congresso, approvata con 72 voti a favore contro 26 contrari, afferma che \u201cil nascituro ha una chiara identit\u00e0 genetica e quindi ha diritto all\u2019integrit\u00e0, alla vita e alla dignit\u00e0\u201d a partire dal concepimento. Unica eccezione prevista il cosiddetto \u201caborto terapeutico\u201d, che rimane tutelato dal Codice di Diritto Penale.<br \/>\nSecondo quanto riportato dal sito del Congresso, la legge nono mira a creare nuovi diritti, ma a estendere quelli esistenti e a <strong>riconoscerli a tutti gli individui partendo dal concepimento<\/strong>, in quanto l\u2019essere concepito \u00e8 gi\u00e0 \u201csoggetto di diritto in tutto ci\u00f2 che lo favorisce\u201d.<br \/>\nSostanzialmente, precisa ancora il Congresso, viene riconosciuto in modo chiaro e scevro da dubbi il diritto alla vita, da cui discendono tutti gli altri diritti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una decisione storica, il Congresso del Per&ugrave; riconosce il diritto alla vita a partire dal concepimento, momento nel quale ogni individuo ha diritto &ldquo;all&rsquo;integrit&agrave;, alla vita e alla dignit&agrave;&rdquo;<\/p>\n","protected":false},"author":102,"featured_media":218411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[515,539],"class_list":["post-218409","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-aborto","tag-peru"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Per\u00f9. La vita umana inizia dal concepimento!<\/title>\n<meta name=\"description\" content=\"Il Congresso del Per\u00f9 dichiara illegale l&#039;aborto e riconosce il diritto alla vita a partire dal concepimento, momento da cui ogni individuo ha diritto alla vita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per\u00f9. La vita umana inizia dal concepimento!\" \/>\n<meta property=\"og:description\" content=\"Il Congresso del Per\u00f9 dichiara illegale l&#039;aborto e riconosce il diritto alla vita a partire dal concepimento, momento da cui ogni individuo ha diritto alla vita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T07:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/12\/Peru-aborto-concepimento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Per\u00f9. La vita umana inizia dal concepimento!\",\"datePublished\":\"2023-12-21T07:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/\"},\"wordCount\":243,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/12\\\/Peru-aborto-concepimento.jpg\",\"keywords\":[\"aborto\",\"Per\u00f9\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/\",\"name\":\"Per\u00f9. La vita umana inizia dal concepimento!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/12\\\/Peru-aborto-concepimento.jpg\",\"datePublished\":\"2023-12-21T07:00:51+00:00\",\"description\":\"Il Congresso del Per\u00f9 dichiara illegale l'aborto e riconosce il diritto alla vita a partire dal concepimento, momento da cui ogni individuo ha diritto alla vita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/12\\\/Peru-aborto-concepimento.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/12\\\/Peru-aborto-concepimento.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-vita-umana-inizia-concepimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Per\u00f9. La vita umana inizia dal concepimento!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Per\u00f9. La vita umana inizia dal concepimento!","description":"Il Congresso del Per\u00f9 dichiara illegale l'aborto e riconosce il diritto alla vita a partire dal concepimento, momento da cui ogni individuo ha diritto alla vita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/","og_locale":"it_IT","og_type":"article","og_title":"Per\u00f9. La vita umana inizia dal concepimento!","og_description":"Il Congresso del Per\u00f9 dichiara illegale l'aborto e riconosce il diritto alla vita a partire dal concepimento, momento da cui ogni individuo ha diritto alla vita","og_url":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-12-21T07:00:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/12\/Peru-aborto-concepimento.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Per\u00f9. La vita umana inizia dal concepimento!","datePublished":"2023-12-21T07:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/"},"wordCount":243,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/12\/Peru-aborto-concepimento.jpg","keywords":["aborto","Per\u00f9"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/","url":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/","name":"Per\u00f9. La vita umana inizia dal concepimento!","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/12\/Peru-aborto-concepimento.jpg","datePublished":"2023-12-21T07:00:51+00:00","description":"Il Congresso del Per\u00f9 dichiara illegale l'aborto e riconosce il diritto alla vita a partire dal concepimento, momento da cui ogni individuo ha diritto alla vita","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/12\/Peru-aborto-concepimento.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/12\/Peru-aborto-concepimento.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/peru-vita-umana-inizia-concepimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Per\u00f9. La vita umana inizia dal concepimento!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:25:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=218409"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/218411"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=218409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=218409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=218409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}