﻿


{"id":218672,"date":"2024-01-05T11:05:11","date_gmt":"2024-01-05T10:05:11","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=218672"},"modified":"2024-01-06T10:24:56","modified_gmt":"2024-01-06T09:24:56","slug":"pensioni-pagamenti-arrivo-rivalutazione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/","title":{"rendered":"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%"},"content":{"rendered":"<h2>L\u2019INPS ha confermato che i pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti e contengono gli aumenti garantiti dalla rivalutazione al costo della vita e all\u2019adeguamento del nuovo sistema a tre aliquote<\/h2>\n<p><!--more--><\/p>\n<p>Sono partiti mercoled\u00ec 3 gennaio i primi pagamenti delle \u201cnuove\u201d pensioni, rivalutate al costo della vita e adeguate al nuovo <strong>sistema delle tre aliquote<\/strong> varato dal governo in sostituzione del precedente a quattro aliquote.<\/p>\n<h3>L\u2019incremento delle pensioni garantito dalla rivalutazione al costo della vita<\/h3>\n<p>Per quanto riguarda la rivalutazione, in base all\u2019inflazione \u00e8 stato calcolato un incremento del <strong>5,4%,<\/strong> che verr\u00e0 riconosciuto al 100% a tutti gli assegni fino a 4 volte il minimo, ovvero fino a 2.272,76. Per fare un esempio di cifre, un assegno lordo di 1500 euro da gennaio 2024 <strong>salir\u00e0 a 1581 euro<\/strong> (sempre lorde).<br \/>\nSuperato il limite di 4 volte il minimo, la percentuale della rivalutazione scende: per assegni fino a <strong>2.839,70 euro<\/strong>, l\u2019aumento previsto verr\u00e0 preso in considerazione <strong>all\u201985%<\/strong>. Dunque, di fatto, per questa fascia di pensioni la rivalutazione \u00e8 del 4,59%. Per fare anche in questo caso un esempio pratico: un assegno lordo di 2500 euro passer\u00e0 a essere di <strong>2614 euro<\/strong>.<br \/>\nA salire, gli assegni fino a 3.407,64 euro verranno rivalutati al <strong>53%<\/strong> (aumento effettivo del 2,862%), mentre quelli da 6 a 8 volte il minimo, ovvero fino a 4.543,52 euro, avranno una rivalutazione del <strong>47%<\/strong> (aumento effettivo: 2,538%.).<br \/>\nLa rivalutazione scende al <strong>37%<\/strong> per gli assegni fino a 5.679,40 euro (aumento effettivo: 1.998%) e si attesta, infine, al <strong>22%<\/strong> per tutti gli altri importi superiori a 10 volte il minimo, per un aumento effettivo dell\u20191,188%. Quest\u2019ultima fascia \u00e8 quella che vede la maggiore novit\u00e0, con l\u2019abbassamento della rivalutazione al 22%, appunto, anzich\u00e9 del 32% come \u00e8 stato fino allo scorso anno.<br \/>\nQuale che sia l\u2019importo e la relativa\u00a0 rivalutazione, l\u2019INPS ha comunicato che <strong>non dovrebbero esserci ritardi nell\u2019erogazione<\/strong>, con i primi pagamenti che sono gi\u00e0 partiti alla data del 3 gennaio.<\/p>\n<h3>La rimodulazione al nuovo sistema a tre aliquote<\/h3>\n<p>Oltre alla rivalutazione, come detto all\u2019inizio, a partire da gennaio le pensioni subiscono la rimodulazione dovuta al <strong>nuovo sistema a tre aliquote<\/strong>, che riguarda tutte le persone fisiche che percepiscono un reddito. In questo caso, calcolare a quanto ammonta l\u2019aumento (comunque contenuto) non \u00e8 semplice: la variazione, infatti, riguarda l\u2019accorpamento di quelli che nel sistema in vigore fino a dicembre 2023 erano i primi due scaglioni. Dunque, <strong>dai 15mila ai 28mila euro<\/strong> di reddito l\u2019aliquota Irpef sar\u00e0 una sola, fissata al <strong>23%<\/strong>. Le altre due riguardano i redditi tra 28mila e 50mila euro, la cui aliquota Irpef \u00e8 del <strong>35%<\/strong>, e quelli superiori a 50mila euro che verseranno il <strong>43%<\/strong> di Irpef. Per questi ultimi, per\u00f2, \u00e8 previsto un taglio lineare delle detrazioni che, di fatto, annuller\u00e0 l\u2019effetto della riforma.<br \/>\nProvando a fare dei calcoli, per chi ha un reddito lordo annuo di 25mila euro, il guadagno sar\u00e0 intorno ai <strong>200 euro annui<\/strong>, che salgono a circa <strong>260<\/strong> per redditi fino a 28 mila.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;INPS ha confermato che i pagamenti degli assegni delle pensioni di gennaio sono gi&agrave; partiti e contengono gli aumenti garantiti dalla rivalutazione al costo della vita e all&rsquo;adeguamento del nuovo sistema a tre aliquote<\/p>\n","protected":false},"author":102,"featured_media":218674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[1081,942,829],"class_list":["post-218672","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-inflazione","tag-pensioni","tag-tasse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pensioni: primi pagamenti in arrivo con la rivalutazione al 5,4%<\/title>\n<meta name=\"description\" content=\"I pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti, con gli aumenti per la rivalutazione all&#039;inflazione e al nuovo sistema a tre aliquote\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%\" \/>\n<meta property=\"og:description\" content=\"I pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti, con gli aumenti per la rivalutazione all&#039;inflazione e al nuovo sistema a tre aliquote\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-05T10:05:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-06T09:24:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/rivalutazione-pensioni-gennaio-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%\",\"datePublished\":\"2024-01-05T10:05:11+00:00\",\"dateModified\":\"2024-01-06T09:24:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/\"},\"wordCount\":478,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/rivalutazione-pensioni-gennaio-2024.jpg\",\"keywords\":[\"inflazione\",\"pensioni\",\"tasse\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/\",\"name\":\"Pensioni: primi pagamenti in arrivo con la rivalutazione al 5,4%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/rivalutazione-pensioni-gennaio-2024.jpg\",\"datePublished\":\"2024-01-05T10:05:11+00:00\",\"dateModified\":\"2024-01-06T09:24:56+00:00\",\"description\":\"I pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti, con gli aumenti per la rivalutazione all'inflazione e al nuovo sistema a tre aliquote\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/rivalutazione-pensioni-gennaio-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/rivalutazione-pensioni-gennaio-2024.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pensioni-pagamenti-arrivo-rivalutazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pensioni: primi pagamenti in arrivo con la rivalutazione al 5,4%","description":"I pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti, con gli aumenti per la rivalutazione all'inflazione e al nuovo sistema a tre aliquote","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/","og_locale":"it_IT","og_type":"article","og_title":"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%","og_description":"I pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti, con gli aumenti per la rivalutazione all'inflazione e al nuovo sistema a tre aliquote","og_url":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-01-05T10:05:11+00:00","article_modified_time":"2024-01-06T09:24:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/rivalutazione-pensioni-gennaio-2024.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%","datePublished":"2024-01-05T10:05:11+00:00","dateModified":"2024-01-06T09:24:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/"},"wordCount":478,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/rivalutazione-pensioni-gennaio-2024.jpg","keywords":["inflazione","pensioni","tasse"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/","url":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/","name":"Pensioni: primi pagamenti in arrivo con la rivalutazione al 5,4%","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/rivalutazione-pensioni-gennaio-2024.jpg","datePublished":"2024-01-05T10:05:11+00:00","dateModified":"2024-01-06T09:24:56+00:00","description":"I pagamenti degli assegni delle pensioni di gennaio sono gi\u00e0 partiti, con gli aumenti per la rivalutazione all'inflazione e al nuovo sistema a tre aliquote","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/rivalutazione-pensioni-gennaio-2024.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/rivalutazione-pensioni-gennaio-2024.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/pensioni-pagamenti-arrivo-rivalutazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Pensioni: primi pagamenti gi\u00e0 in arrivo con la rivalutazione al 5,4%"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:34:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=218672"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/218674"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=218672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=218672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=218672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}