﻿


{"id":218683,"date":"2024-01-07T07:55:09","date_gmt":"2024-01-07T06:55:09","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=218683"},"modified":"2024-01-05T14:50:16","modified_gmt":"2024-01-05T13:50:16","slug":"vita-cambiate-sempre-adozione-distanza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/","title":{"rendered":"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza"},"content":{"rendered":"<h2>Daisy a 12 anni \u00e8 rimasta incinta, salvata dallo zio da un matrimonio forzato e combinato, con il sostegno del progetto &#8220;Adotta a Distanza i bambini di un orfanotrofio in Kenya&#8221;, ha avuto suo figlio e oggi si impegna per crescere con lui e cambiare il loro futuro in meglio<\/h2>\n<p><!--more--><\/p>\n<p>Daisy aveva solo 12 anni e frequentava il sesto anno di scuola quando rimase incinta. Una situazione gi\u00e0 di per s\u00e9 complicata da affrontare a quell\u2019et\u00e0, ma <strong>decisamente drammatica<\/strong> nel momento in cui il pap\u00e0 della ragazzina non volle accettare in alcun modo la situazione e decise che l\u2019unica soluzione per \u201cguadagnarci qualcosa\u201d sarebbe stata quella di dare la figlia in sposa a un uomo, in cambio di una dote di qualche mucca.<br \/>\nIl padre \u00a0prese accordi in tal senso con un uomo anziano ma, fortunatamente, lo zio della bambina, fratello proprio del pap\u00e0, venuto a conoscenza della decisione riusc\u00ec a intervenire e, con l\u2019aiuto della mamma della piccola, a incaricare una signora affinch\u00e9 si interfacciasse con l\u2019amministrazione locale e l\u2019ufficio per i bambini, riuscendo a sottrarre Daisy dal suo destino gi\u00e0 scritto.<\/p>\n<h3>Un sostegno per un nuovo futuro<\/h3>\n<p>La ragazza \u00e8 stata cos\u00ec portata all\u2019orfanotrofio Shelter, dove ha dato alla luce il figlio.<br \/>\nNel frattempo, la mamma di Daisy, proprio per aver aiutato la figlia, \u00e8 stata cacciata di casa dal marito, venendo per\u00f2 aiutata dal cognato a costruire una piccola casa per lei e i figli.<\/p>\n<p>Con fatica e pazienza <strong>le cose sono migliorate<\/strong>: Daisy ha potuto iscriversi alla scuola primaverile di Hope e continuare gli studi, sostenere gli esami primari nazionali finali e iscriversi alla scuola superiore nel 2022. Oggi la ragazza ha 17 anni, frequenter\u00e0 la terza classe l&#8217;anno prossimo e durante le vacanze scolastiche torna a casa dalla famiglia, dove <strong>ritrova suo figlio e continua a costruire con lui un legame<\/strong> di giorno in giorno pi\u00f9 forte.<br \/>\nGrazie al sostegno del progetto di Ai.Bi. \u201c<strong><a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Kenya\">Adotta a Distanza i bambini di un orfanotrofio in Kenya<\/a><\/strong>\u201d, Daisy \u00e8 tra i bambini che verranno reintegrati nelle loro famiglie. Recentemente \u00e8 stata intrapresa una visita proprio alla famiglia e sono stati avviati i colloqui e i preparativi per\u00a0 il rientro di Daisy a casa. La ragazza, da parte sua, ha assicurato che, grazie all&#8217;educazione che sta ricevendo, \u00e8 disposta a <strong>dare il massimo per poter migliorare sempre di pi\u00f9 la situazione per il futuro<\/strong>: per lei, suo figlio e tutta la sua famiglia.<\/p>\n<h3>L&#8217;Adozione a Distanza in Kenya<\/h3>\n<p>Anche tu puoi aiutare tanti minori abbandonati, decidendo di aderire al progetto di Ai.Bi. \u201c<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Kenya\">Adotta a Distanza i bambini di un orfanotrofio in Kenya<\/a>\u201d, bastano 0,82 centesimi al giorno.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\" https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Kenya\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Per richiedere informazioni sull&#8217;Adozione a Distanza\u00a0<a href=\"https:\/\/zimbra.teleposta.it\/#infosad\">clicca qui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daisy a 12 anni &egrave; rimasta incinta, salvata dallo zio da un matrimonio forzato e combinato, con il sostegno del progetto &ldquo;Adotta a Distanza i bambini di un orfanotrofio in Kenya&rdquo;, ha avuto suo figlio e oggi si impegna per crescere con lui e cambiare il loro futuro in meglio<\/p>\n","protected":false},"author":102,"featured_media":218685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[454,306,640],"class_list":["post-218683","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-adozione-a-distanza","tag-kenya","tag-shelter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza<\/title>\n<meta name=\"description\" content=\"Rimasta incinta a 12 anni e salvata da un matrimonio forzato Daisy con l&#039;aiuto dell&#039;Adozione a Distanza prova a costruire per lei e il figlio un futuro migliore\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza\" \/>\n<meta property=\"og:description\" content=\"Rimasta incinta a 12 anni e salvata da un matrimonio forzato Daisy con l&#039;aiuto dell&#039;Adozione a Distanza prova a costruire per lei e il figlio un futuro migliore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-07T06:55:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/adozione-a-distanza-daisy-figlio-kenya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza\",\"datePublished\":\"2024-01-07T06:55:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/\"},\"wordCount\":473,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/adozione-a-distanza-daisy-figlio-kenya.jpg\",\"keywords\":[\"adozione a distanza\",\"Kenya\",\"Shelter\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/\",\"name\":\"Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/adozione-a-distanza-daisy-figlio-kenya.jpg\",\"datePublished\":\"2024-01-07T06:55:09+00:00\",\"description\":\"Rimasta incinta a 12 anni e salvata da un matrimonio forzato Daisy con l'aiuto dell'Adozione a Distanza prova a costruire per lei e il figlio un futuro migliore\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/adozione-a-distanza-daisy-figlio-kenya.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/adozione-a-distanza-daisy-figlio-kenya.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vita-cambiate-sempre-adozione-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza","description":"Rimasta incinta a 12 anni e salvata da un matrimonio forzato Daisy con l'aiuto dell'Adozione a Distanza prova a costruire per lei e il figlio un futuro migliore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza","og_description":"Rimasta incinta a 12 anni e salvata da un matrimonio forzato Daisy con l'aiuto dell'Adozione a Distanza prova a costruire per lei e il figlio un futuro migliore","og_url":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-01-07T06:55:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/adozione-a-distanza-daisy-figlio-kenya.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza","datePublished":"2024-01-07T06:55:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/"},"wordCount":473,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/adozione-a-distanza-daisy-figlio-kenya.jpg","keywords":["adozione a distanza","Kenya","Shelter"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/","url":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/","name":"Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/adozione-a-distanza-daisy-figlio-kenya.jpg","datePublished":"2024-01-07T06:55:09+00:00","description":"Rimasta incinta a 12 anni e salvata da un matrimonio forzato Daisy con l'aiuto dell'Adozione a Distanza prova a costruire per lei e il figlio un futuro migliore","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/adozione-a-distanza-daisy-figlio-kenya.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/adozione-a-distanza-daisy-figlio-kenya.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/vita-cambiate-sempre-adozione-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. Una vita (anzi due) cambiate per sempre dall\u2019Adozione a Distanza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:04:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=218683"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/218685"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=218683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=218683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=218683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}