﻿


{"id":218954,"date":"2024-01-16T11:00:50","date_gmt":"2024-01-16T10:00:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=218954"},"modified":"2024-01-16T16:27:55","modified_gmt":"2024-01-16T15:27:55","slug":"congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/","title":{"rendered":"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas"},"content":{"rendered":"<h2>Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto &#8220;Adotta a distanza i bambini di un orfanotrofio&#8221;<!--more--><\/h2>\n<p>Ogni mese, <strong>Ai.Bi.<\/strong> porta avanti le attivit\u00e0 relativa all\u2019acquisto degli <strong>alimenti per gli orfanotrofi Fed e Sodas<\/strong>, in <strong>Congo<\/strong>.<\/p>\n<h3>Le attivit\u00e0 di Ai.Bi. con il personale degli orfanotrofi<\/h3>\n<p>In un paese dove la povert\u00e0, la guerra e le malattie rendono difficile la sopravvivenza di migliaia di bambini, l\u2019associazione opera da anni per garantire loro un\u2019infanzia dignitosa e sicura. Tra le sue iniziative, c\u2019\u00e8 quella di fornire mensilmente degli alimenti di base agli <strong>orfanotrofi Fed e Sodas<\/strong>.<br \/>\nIl lavoro dell\u2019equipe con i responsabili dei centri prosegue in armonia e gli acquisti si svolgono al meglio possibile. Il prezzo di alcuni prodotti alimentari \u00e8 leggermente diminuito, permettendo di aumentare le quantit\u00e0, ma per altri prodotti il costo si \u00e8 alzato e, di conseguenza le quantit\u00e0 sono diminuite.<br \/>\nQuello che \u00e8 certo \u00e8 che non sono previsti periodi in cui gli alimenti mancheranno all\u2019interno dei due orfanotrofi. Purtroppo \u00e8 la variet\u00e0 degli alimenti a diminuire, un po\u2019 per carenze e un po\u2019 per i prezzi aumentati.<\/p>\n<h3>La storia di Maitrise all\u2019orfanotrofio Sodas<\/h3>\n<p><strong>Maitrise<\/strong>, un piccolo bimbo di 4 anni, accolto all\u2019orfanotrofio Sodas, ci ricorda per\u00f2 la sua storia di vita passata spesso a digiuno con gravissima malnutrizione. Arrivato a Sodas lo scorso anno, era stato ricoverato in ospedale per pi\u00f9 di 7 giorni, sotto la supervisione di un medico e di una nutrizionista. Dopo aver ricevuto le cure necessarie, Maitrise \u00e8 tornato all\u2019orfanotrofio, dove ha iniziato un percorso di recupero fisico e psicologico, grazie all\u2019affetto e al sostegno degli educatori e degli altri bambini.<br \/>\n<strong>Adesso Maitrise sta benone<\/strong>.<br \/>\nLo si pu\u00f2 vedere nella foto in alto, accanto ai sacchi con farina e fagioli, bidoni di olio e pesce secco, che sono stati consegnati dall\u2019Associazione.<\/p>\n<p>Il suo sorriso esprime la gioia immensa che prova, per questo mese non conoscer\u00e0 giorni di digiuno, per lui l\u2019incubo della fame \u00e8 purtroppo ancora presente nei suoi ricordi. Ma grazie al progetto di Ai.Bi., Maitrise ha ritrovato la speranza di una vita migliore, in cui potr\u00e0 crescere sano e felice.<\/p>\n<p><strong>L\u2019Adozione a Distanza in Repubblica Democratica del Congo<\/strong><\/p>\n<p>Anche questa particolare attivit\u00e0 \u00e8 resa possibile grazie ai generosi contributi di tutti coloro che aderiscono al progetto di Ai.Bi. \u201cAdotta a distanza i bambini degli orfanotrofi del Congo\u201d: bastano 82 centesimi al giorno.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Per richiedere informazioni sull\u2019Adozione a Distanza <a href=\"#infosad\">clicca qui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante le difficolt&agrave;, l&rsquo;impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto &ldquo;Adotta a distanza i bambini di un orfanotrofio&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":218956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[645,671],"class_list":["post-218954","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-fed","tag-sodas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo. La lotta alla denutrizione per i bambini degli orfanotrofi<\/title>\n<meta name=\"description\" content=\"Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto &quot;Adotta a distanza i bambini di un orfanotrofio&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas\" \/>\n<meta property=\"og:description\" content=\"Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto &quot;Adotta a distanza i bambini di un orfanotrofio&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T10:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T15:27:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Congo-Maitrise-alimenti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas\",\"datePublished\":\"2024-01-16T10:00:50+00:00\",\"dateModified\":\"2024-01-16T15:27:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/\"},\"wordCount\":456,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/Congo-Maitrise-alimenti.jpg\",\"keywords\":[\"Fed\",\"Sodas\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/\",\"name\":\"Congo. La lotta alla denutrizione per i bambini degli orfanotrofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/Congo-Maitrise-alimenti.jpg\",\"datePublished\":\"2024-01-16T10:00:50+00:00\",\"dateModified\":\"2024-01-16T15:27:55+00:00\",\"description\":\"Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto \\\"Adotta a distanza i bambini di un orfanotrofio\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/Congo-Maitrise-alimenti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/01\\\/Congo-Maitrise-alimenti.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo. La lotta alla denutrizione per i bambini degli orfanotrofi","description":"Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto \"Adotta a distanza i bambini di un orfanotrofio\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/","og_locale":"it_IT","og_type":"article","og_title":"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas","og_description":"Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto \"Adotta a distanza i bambini di un orfanotrofio\"","og_url":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-01-16T10:00:50+00:00","article_modified_time":"2024-01-16T15:27:55+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Congo-Maitrise-alimenti.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas","datePublished":"2024-01-16T10:00:50+00:00","dateModified":"2024-01-16T15:27:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/"},"wordCount":456,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Congo-Maitrise-alimenti.jpg","keywords":["Fed","Sodas"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/","url":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/","name":"Congo. La lotta alla denutrizione per i bambini degli orfanotrofi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Congo-Maitrise-alimenti.jpg","datePublished":"2024-01-16T10:00:50+00:00","dateModified":"2024-01-16T15:27:55+00:00","description":"Nonostante le difficolt\u00e0, l\u2019impegno di Ai.Bi. nel garantire una nutrizione adeguata ai bambini accolti negli orfanotrofi in Congo prosegue con costanza grazie ai generosi sostenitori del progetto \"Adotta a distanza i bambini di un orfanotrofio\"","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Congo-Maitrise-alimenti.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Congo-Maitrise-alimenti.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/congo-lotta-denutrizione-bambini-orfanotrofi-fed-sodas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Repubblica Democratica del Congo. La lotta alla denutrizione per i bambini accolti negli orfanotrofi Fed e Sodas"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:46:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=218954"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/218954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/218956"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=218954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=218954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=218954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}