﻿


{"id":219534,"date":"2024-02-07T15:59:21","date_gmt":"2024-02-07T14:59:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=219534"},"modified":"2024-02-07T16:04:01","modified_gmt":"2024-02-07T15:04:01","slug":"famiglie-italiane-riforma-isee","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/","title":{"rendered":"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee"},"content":{"rendered":"<h2>Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative<\/h2>\n<p><!--more--><\/p>\n<p>L\u2019<strong>Isee<\/strong>, l\u2019indicatore della situazione economica equivalente, \u00e8 lo strumento che determina l\u2019accesso a molte <strong>prestazioni sociali e agevolazioni fiscali per le famiglie<\/strong>. Ma \u00e8 anche uno strumento che <strong>necessita di una profonda revisione<\/strong>, perch\u00e9 non rispecchia la reale condizione di molti nuclei familiari, soprattutto quelli con pi\u00f9 figli. Questo \u00e8 il messaggio che arriva forte e chiaro dall\u2019associazionismo familiare, che da anni denuncia le criticit\u00e0 e le distorsioni dell\u2019Isee, e che ora trova una disponibilit\u00e0 al dialogo da parte del governo.<\/p>\n<h3>L\u2019intervento sull\u2019Isee<\/h3>\n<p>Il viceministro del lavoro e delle politiche sociali <strong>Maria Teresa Bellucci<\/strong>, infatti, ha dichiarato di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Una dichiarazione accolta con soddisfazione dal Forum delle Famiglie, che ha annunciato di avere pronto un dossier con le proposte per migliorare l\u2019Isee, e che ha organizzato un convegno su Assegno unico, fisco e politiche familiari per il 14 febbraio a Roma.<br \/>\nIl problema dell\u2019Isee \u00e8 diventato ancora pi\u00f9 evidente con l\u2019introduzione dell\u2019<strong>Assegno unico universale<\/strong>, il beneficio che dal marzo 2022 ha sostituito una serie di misure a sostegno delle famiglie con figli. L\u2019Assegno unico, infatti, entra nel calcolo dell\u2019Isee come reddito, e questo comporta un aumento del valore dell\u2019indicatore, con il rischio di perdere altre agevolazioni.<\/p>\n<h3>Il questionario<\/h3>\n<p>Secondo un questionario dell\u2019Osservatorio politico di Famiglie numerose, <strong>9 famiglie su 10 hanno visto aumentare il loro Isee<\/strong>, e<strong> 6 su 10 temono di perdere altre agevolazioni<\/strong>. Le criticit\u00e0 riguardano anche il fatto che l\u2019Isee considera il reddito lordo e non il netto, che le scale di equivalenza non tengono conto del peso dei figli, che la casa di propriet\u00e0 ha un peso eccessivo. Sono nodi che il governo deve sciogliere, secondo il presidente dell\u2019Associazione nazionale famiglie numerose Alfredo Caltabiano, che chiede un tavolo tecnico. A incidere sull\u2019Isee, inoltre, sono anche le regole della composizione del nucleo familiare, che penalizzano i single e i giovani, come osserva il presidente nazionale delle Acli Emiliano Manfredonia.<\/p>\n<h3>La dichiarazione del Forum delle Associazioni Familiari<\/h3>\n<p><strong>Adriano Bordignon<\/strong>, presidente nazionale del <strong>Forum delle Associazioni Familiari<\/strong> si \u00e8 espresso molto favorevolmente a questa apertura: \u201cCogliamo con grande soddisfazione la disponibilit\u00e0 del viceministro Bellucci a rivedere i meccanismi di calcolo dell\u2019Isee, uno strumento che mostra evidenti limiti. Le famiglie vivono gi\u00e0 adesso in una situazione di precariet\u00e0: gli effetti dell\u2019Assegno unico 2022 sull\u2019Isee 2024 non possono determinare ulteriori svantaggi\u201d.<br \/>\nIl Forum delle Associazioni Familiari ha gi\u00e0 pronto un dossier in cui sono presentate le criticit\u00e0 raccolte in campagne di ascolto e anche alcune possibili proposte.<\/p>\n<p><strong>[Fonte: Avvenire]<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont&agrave; del Governo di voler intervenire sull&rsquo;Isee per renderlo pi&ugrave; adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi&agrave; al lavoro per presentare proposte operative<\/p>\n","protected":false},"author":133,"featured_media":219535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[297],"class_list":["post-219534","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-famiglia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una buona notizia per le famiglie italiane: al via la riforma dell\u2019ISEE<\/title>\n<meta name=\"description\" content=\"Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee\" \/>\n<meta property=\"og:description\" content=\"Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T14:59:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T15:04:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee\",\"datePublished\":\"2024-02-07T14:59:21+00:00\",\"dateModified\":\"2024-02-07T15:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/\"},\"wordCount\":483,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee.jpg\",\"keywords\":[\"famiglia\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/\",\"name\":\"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019ISEE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee.jpg\",\"datePublished\":\"2024-02-07T14:59:21+00:00\",\"dateModified\":\"2024-02-07T15:04:01+00:00\",\"description\":\"Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/famiglie-italiane-riforma-isee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019ISEE","description":"Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/","og_locale":"it_IT","og_type":"article","og_title":"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee","og_description":"Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative","og_url":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-02-07T14:59:21+00:00","article_modified_time":"2024-02-07T15:04:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee","datePublished":"2024-02-07T14:59:21+00:00","dateModified":"2024-02-07T15:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/"},"wordCount":483,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee.jpg","keywords":["famiglia"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/","url":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/","name":"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019ISEE","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee.jpg","datePublished":"2024-02-07T14:59:21+00:00","dateModified":"2024-02-07T15:04:01+00:00","description":"Il viceministro del lavoro e delle politiche sociali, Maria Teresa Bellucci dichiara la volont\u00e0 del Governo di voler intervenire sull\u2019Isee per renderlo pi\u00f9 adeguato alla situazione economica delle famiglie. Il Forum delle Associazioni Familiari gi\u00e0 al lavoro per presentare proposte operative","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/famiglie-italiane-riforma-isee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Una buona notizia per le famiglie italiane: al via la riforma dell\u2019Isee"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:05:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/219534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=219534"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/219534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/219535"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=219534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=219534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=219534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}