﻿


{"id":219826,"date":"2024-02-18T08:00:22","date_gmt":"2024-02-18T07:00:22","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=219826"},"modified":"2024-03-21T10:50:56","modified_gmt":"2024-03-21T09:50:56","slug":"adozione-adottata-nonni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/","title":{"rendered":"&#8220;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&#8221;"},"content":{"rendered":"<h2>Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente<!--more--><\/h2>\n<p>\u201cMamma, parlami di te ora che rivedi la tua storia al contrario. In questi giorni, mentre io e mio marito corriamo tra una formazione e un colloquio per essere dichiarati idonei all\u2019adozione, forse inconsciamente stai facendo un salto indietro in un tempo buio che adesso puoi abitare di nuovo.<br \/>\nQuel tempo senza ricordo, illuminato quando i nonni sono venuti a prenderti, adesso forse si accende di nuovo. Anche io ci sto pensando, sai, cosa credi?! Ricordo ancora quando mi hai detto di\u00a0<strong>essere stata adottata<\/strong>\u00a0dai nonni.<br \/>\nRimasi un po\u2019 sorpresa, pensavo che anche tu come me fossi uscita dalla pancia di una mamma, cio\u00e8, della nonna.\u00a0<strong>Le nostre vite si sono intrecciate<\/strong>\u00a0in questo modo e se non ci fosse stato quel tuo\u00a0<strong>abbandono<\/strong>\u00a0e poi la tua\u00a0<strong>adozione<\/strong>, chiss\u00e0\u2026<br \/>\nAh, che terremoto sotterraneo deve essere,\u00a0<strong>ritornare figlio<\/strong>. Lo immagino,\u00a0<strong>ora che mi appresto a diventare mamma<\/strong>, per il\u00a0<strong>bambino che ci attende<\/strong>\u00a0e provo a immaginarlo anche per te, per quello che deve essere stato, tanti anni fa. Forse si cade, si sprofonda con l\u2019abbandono ma c\u2019\u00e8 modo di rialzarsi.<br \/>\nTrovare la famiglia che ti accoglie \u00e8 una faglia che si apre nel cuore e solo l\u2019amore ti permette di riconoscere mamma e pap\u00e0. Sar\u00e0 stato cos\u00ec, anche per te?<br \/>\nNella\u00a0<strong>bambina abbandonata che accoglieremo come figlia<\/strong>\u00a0&#8211; s\u00ec, credo proprio che sar\u00e0 femmina! &#8211; rivedrai te stessa, lo so, ogni volta che la prenderai in braccio. E quella catena d\u2019amore che mai si potr\u00e0 spezzare.\u201d<\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n<p style=\"text-align: center;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un&rsquo;occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente<\/p>\n","protected":false},"author":133,"featured_media":219827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279],"class_list":["post-219826","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&quot;<\/title>\n<meta name=\"description\" content=\"Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&quot;\" \/>\n<meta property=\"og:description\" content=\"Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-18T07:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T09:50:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Adozione-madre-figlia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"&#8220;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&#8221;\",\"datePublished\":\"2024-02-18T07:00:22+00:00\",\"dateModified\":\"2024-03-21T09:50:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Adozione-madre-figlia.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/\",\"name\":\"\\\"Ricordo ancora quando mi hai detto di essere stata adottata dai nonni\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Adozione-madre-figlia.jpg\",\"datePublished\":\"2024-02-18T07:00:22+00:00\",\"dateModified\":\"2024-03-21T09:50:56+00:00\",\"description\":\"Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Adozione-madre-figlia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Adozione-madre-figlia.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-adottata-nonni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Ricordo ancora quando mi hai detto di essere stata adottata dai nonni\"","description":"Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/","og_locale":"it_IT","og_type":"article","og_title":"\"Ricordo ancora quando mi hai detto di essere stata adottata dai nonni\"","og_description":"Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente","og_url":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-02-18T07:00:22+00:00","article_modified_time":"2024-03-21T09:50:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Adozione-madre-figlia.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"&#8220;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&#8221;","datePublished":"2024-02-18T07:00:22+00:00","dateModified":"2024-03-21T09:50:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/"},"wordCount":341,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Adozione-madre-figlia.jpg","keywords":["adozione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/","url":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/","name":"\"Ricordo ancora quando mi hai detto di essere stata adottata dai nonni\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Adozione-madre-figlia.jpg","datePublished":"2024-02-18T07:00:22+00:00","dateModified":"2024-03-21T09:50:56+00:00","description":"Mentre si prepara a intraprendere un percorso di adozione, una donna scrive una lettera alla propria madre, a sua volta figlia adottiva. Un\u2019occasione per riflettere sulle rispettive storie e su come queste si intreccino e si riflettano reciprocamente","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Adozione-madre-figlia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Adozione-madre-figlia.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-adottata-nonni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"&#8220;Ricordo ancora quando mi hai detto di essere stata adottata dai nonni&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:50:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/219826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=219826"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/219826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/219827"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=219826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=219826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=219826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}