﻿


{"id":219963,"date":"2024-02-21T08:00:21","date_gmt":"2024-02-21T07:00:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=219963"},"modified":"2024-02-20T23:41:56","modified_gmt":"2024-02-20T22:41:56","slug":"prima-casa-isee-riforma","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/","title":{"rendered":"Quanto peser\u00e0 la prima casa nell&#8217;Isee? In arrivo la riforma"},"content":{"rendered":"<h2>Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali<\/h2>\n<p><!--more-->Il governo sta lavorando a <strong>una riforma dell\u2019Isee<\/strong>, l\u2019indicatore che misura la situazione economica delle famiglie e che regola l\u2019accesso a molti servizi e prestazioni sociali. L\u2019obiettivo \u00e8 rendere lo <strong>strumento pi\u00f9 equo e adeguato alle esigenze delle famiglie<\/strong>, soprattutto in un momento di crisi demografica e di difficolt\u00e0 economica.<\/p>\n<h3>Un tavolo di lavoro con il Forum delle associazioni familiari<\/h3>\n<p>Per farlo, il governo ha istituito un tavolo di lavoro interministeriale, che coinvolge i viceministri del Lavoro e delle Politiche sociali, <strong>Maria Teresa Bellucci<\/strong>, e dell\u2019Economia e delle Finanze, <strong>Maurizio Leo<\/strong>, e il presidente del <strong>Forum delle associazioni familiari<\/strong>, <strong>Adriano Bordignon<\/strong>. Il tavolo si riunir\u00e0 nei prossimi giorni per esaminare e rivedere alcuni aspetti della disciplina Isee che hanno un impatto negativo sulla vita delle famiglie.<\/p>\n<h3>Abbassare il peso della prima casa<\/h3>\n<p>Tra le priorit\u00e0, c\u2019\u00e8 quella di <strong>ridurre il peso che la prima casa ha attualmente sull\u2019Isee<\/strong>. Infatti, il valore della prima casa entra nel calcolo del patrimonio immobiliare, che a sua volta incide sul reddito equivalente. Questo penalizza le famiglie che possiedono una casa di modesto valore, ma che si trovano in una zona ad alta pressione immobiliare, o che hanno ereditato una casa di famiglia. Il governo vorrebbe quindi introdurre una soglia di esclusione o una riduzione del valore della prima casa ai fini dell\u2019Isee, per evitare che questo elemento distorca la reale situazione economica delle famiglie.<br \/>\nIl tavolo di lavoro interministeriale dovr\u00e0 anche individuare le eventuali coperture per la riforma dell\u2019Isee, che potrebbe comportare una riduzione delle entrate per lo Stato e per gli enti locali. La norma di riferimento dell\u2019Isee \u00e8 il <strong>Decreto del Presidente del Consiglio dei ministri 159\/2013<\/strong>, che ha introdotto l\u2019attuale disciplina dell\u2019indicatore. L\u2019Isee serve a valutare e confrontare la situazione economica delle famiglie, tenendo conto del reddito, del patrimonio e della composizione del nucleo familiare.<br \/>\nLa riforma dell\u2019Isee \u00e8 una richiesta che il <strong>Forum delle associazioni familiari<\/strong> porta avanti da molti anni, segnalando i numerosi limiti dello strumento, soprattutto in merito alle scale di equivalenza utilizzate, all\u2019utilizzo dei redditi netti anzich\u00e9 lordi, e alla complessit\u00e0 della procedura di presentazione della Dichiarazione sostitutiva unica (DSU). Il Forum ha espresso soddisfazione per la disponibilit\u00e0 dei viceministri a affrontare questo nodo cos\u00ec importante per le famiglie e a lavorare in sinergia per individuare le possibili soluzioni.<\/p>\n<h3>Gli interventi a sostegno delle famiglie<\/h3>\n<p>La riforma dell\u2019Isee si inserisce in un quadro pi\u00f9 ampio di interventi che il governo sta portando avanti per sostenere le famiglie, tra cui la riforma fiscale, l\u2019assegno unico, e il bonus prima casa per i giovani. Quest\u2019ultimo, in particolare, \u00e8 stato oggetto di un emendamento al <strong>decreto Milleproroghe<\/strong>, che prevede che il <strong>bonus<\/strong> sia riconosciuto solo per i preliminari registrati entro la fine del 2023. Chi, invece, ha gi\u00e0 pagato le imposte a inizio 2024 ma aveva diritto ai bonus, potr\u00e0 ottenere un credito di imposta da utilizzare nel corso del 2025.<\/p>\n<h3>L\u2019esclusione dei titoli di Stato<\/h3>\n<p>Infine, la legge di bilancio 2024 ha previsto l\u2019esclusione dal calcolo dell\u2019Isee, fino a un valore complessivo di <strong>50mila euro<\/strong>, dei titoli di Stato e dei prodotti finanziari di raccolta del risparmio con obbligo di rimborso assistito dalla garanzia dello Stato. Tuttavia, l\u2019Inps ha chiarito che l\u2019entrata in vigore di questa disposizione non \u00e8 immediata, in quanto subordinata all\u2019approvazione delle modifiche al regolamento sull\u2019Isee. Resta, quindi, immutata la disciplina dell\u2019Isee relativa al patrimonio mobiliare, con l\u2019obbligo di indicare nella DSU presentata da gennaio 2024 tutti i rapporti finanziari in possesso delle famiglie al 31 dicembre 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi&ugrave; equo il calcolo dell&rsquo;Isee. La prima casa peser&agrave; di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali<\/p>\n","protected":false},"author":133,"featured_media":219964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-219963","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quanto peser\u00e0 la prima casa nell&#039;Isee? In arrivo la riforma<\/title>\n<meta name=\"description\" content=\"Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quanto peser\u00e0 la prima casa nell&#039;Isee? In arrivo la riforma\" \/>\n<meta property=\"og:description\" content=\"Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-21T07:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee-prima-casa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Quanto peser\u00e0 la prima casa nell&#8217;Isee? In arrivo la riforma\",\"datePublished\":\"2024-02-21T07:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/\"},\"wordCount\":642,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee-prima-casa.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/\",\"name\":\"Quanto peser\u00e0 la prima casa nell'Isee? In arrivo la riforma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee-prima-casa.jpg\",\"datePublished\":\"2024-02-21T07:00:21+00:00\",\"description\":\"Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee-prima-casa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/Riforma-Isee-prima-casa.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/prima-casa-isee-riforma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quanto peser\u00e0 la prima casa nell&#8217;Isee? In arrivo la riforma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quanto peser\u00e0 la prima casa nell'Isee? In arrivo la riforma","description":"Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/","og_locale":"it_IT","og_type":"article","og_title":"Quanto peser\u00e0 la prima casa nell'Isee? In arrivo la riforma","og_description":"Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali","og_url":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-02-21T07:00:21+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee-prima-casa.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Quanto peser\u00e0 la prima casa nell&#8217;Isee? In arrivo la riforma","datePublished":"2024-02-21T07:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/"},"wordCount":642,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee-prima-casa.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/","url":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/","name":"Quanto peser\u00e0 la prima casa nell'Isee? In arrivo la riforma","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee-prima-casa.jpg","datePublished":"2024-02-21T07:00:21+00:00","description":"Un tavolo di lavoro interministeriale con il Forum delle associazioni familiari per render pi\u00f9 equo il calcolo dell\u2019Isee. La prima casa peser\u00e0 di meno sulla situazione economica delle famiglie che richiedono servizi e prestazioni sociali","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee-prima-casa.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/Riforma-Isee-prima-casa.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/prima-casa-isee-riforma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Quanto peser\u00e0 la prima casa nell&#8217;Isee? In arrivo la riforma"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:46:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/219963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=219963"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/219963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/219964"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=219963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=219963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=219963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}