﻿


{"id":220199,"date":"2024-02-29T08:40:54","date_gmt":"2024-02-29T07:40:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=220199"},"modified":"2024-03-21T10:46:20","modified_gmt":"2024-03-21T09:46:20","slug":"adozione-africa-adottare-bambini-grandi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/","title":{"rendered":"Adozione in Africa &#8220;Ancora adesso consiglio a chiunque di adottare bambini grandi&#8221;. Ecco perch\u00e9."},"content":{"rendered":"<h2><strong>&#8220;Quelle in Africa s<\/strong>ono state le tre settimane pi\u00f9 belle della nostra vita, con una quotidianit\u00e0 che si creava e il rapporto genitori &#8211; figlio che nasceva piano piano, in un residence semplice, ma adeguato a farci da nido in quel periodo di luna di miele a tre&#8221;<!--more--><\/h2>\n<p>La storia ha inizio quanto Elisa, oggi madre adottiva, e suo marito erano in cerca della loro nuova abitazione, ancora da coppia ma <strong>intenzionata ad allargare la famiglia<\/strong>. &#8220;I figli tardavano ad arrivare e il tempo passava &#8211; raccontano &#8211; ma non abbiamo mai pensato ad altri metodi per diventare genitori se non l&#8217;adozione&#8221;.<br \/>\nElisa era pi\u00f9 rassegnata e meno ottimista del marito, che, invece: &#8220;Ha saputo farmi guardare il bicchiere mezzo pieno&#8221;.<br \/>\n&#8220;Mentre eravamo alla ricerca della nostra nuova abitazione &#8211; prosegue Elisa &#8211; ci siamo imbattuti in un appartamento di dimensioni anche troppo ampie per i nostri bisogni e, ragionando ad alta voce, durante la visita, ho detto: &#8220;Avremo uno studio per ciascuno&#8221;. Ma mio marito mi ha preso la mano e ha sentenziato: <strong>&#8220;In una cameretta noi ci dobbiamo mettere nostro figlio&#8221;<\/strong>.<\/p>\n<h3>&#8230;e cos\u00ec \u00e8 stato.<\/h3>\n<p>Prosegue il racconto: &#8220;Dodici anni fa abbiamo conosciuto Emanuel e abbiamo capito che <strong>solo con lui, la nostra casa diventava tale!<br \/>\n<\/strong>Con quella frase, mio marito ha suscitato in me di nuovo il desiderio di diventare madre, che per un po&#8217; si era spento. Lui ci ha sempre creduto e si \u00e8 dato da fare per tutta la documentazione necessaria, per arrivare il prima possibile da nostro figlio.<br \/>\nAbbiamo conosciuto Emanuel che aveva gi\u00e0 compiuto 8 anni, ma ancora adesso consiglio a chiunque di adottare bambini &#8220;cos\u00ec grandi&#8221; per tutta la consapevolezza e\u00a0<strong>la voglia che hanno di diventare figli<\/strong>!<br \/>\nIl nostro bambino si \u00e8 presentato a noi, accompagnato dal referente dell&#8217;istituto, con &#8220;il vestito pi\u00f9 bello&#8221;, anche se di due taglie pi\u00f9 grande e palesemente non suo, ma ci ha fatto sapere solo dopo, nel tempo, che lo ha fatto perch\u00e9 &#8220;faceva eleganza&#8221; e ci teneva a presentarsi al meglio a mamma e pap\u00e0&#8221;.<\/p>\n<h3>Nostro figlio sperava di essere perfetto per noi<\/h3>\n<p>&#8220;Emanuel voleva dimostrare spavalderia, per apparire il figlio ideale, ma dentro era tutto emozionato e, appena lo abbiamo abbracciato e stretto a noi, \u00e8 rimasto impietrito, perch\u00e9 <strong>non avvezzo a ricevere abbracci.<\/strong> Abbiamo capito di aver esagerato, con la nostra foga caratteriale, il calore meridionale e la gioia del momento.<br \/>\nIl giorno dopo era gi\u00e0 meno &#8220;immobile&#8221; nei nostri confronti. La settimana successiva era lui che <strong>veniva a cercarci per ricevere le coccole<\/strong>.<br \/>\n<strong>Sono state le tre settimane pi\u00f9 belle della nostra vita quelle in Africa<\/strong>, con una quotidianit\u00e0 che si creava e il rapporto genitori &#8211; figlio che nasceva piano piano, in un residence semplice, ma adeguato a farci da nido in quel periodo di luna di miele a 3.<br \/>\nTornati a casa, \u00e8 stato nostro figlio ad aprire la porta e a pulirsi le scarpe su uno zerbino (fatto produrre apposta da dei parenti) in cui era scritto &#8220;benvenuto&#8221; nella sua lingua madre.<br \/>\nSappiamo che ha gradito perch\u00e9 ci ha esibito<strong> il sorriso pi\u00f9 grande che avessimo mai visto sul suo bel visetto <\/strong>e si \u00e8 diretto in camera sua, come sapesse dove si trovava, proprio quella che mio marito, a suo tempo, aveva previsto per lui&#8221;!<\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n<p style=\"text-align: center;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Quelle in Africa sono state le tre settimane pi&ugrave; belle della nostra vita, con una quotidianit&agrave; che si creava e il rapporto genitori &ndash; figlio che nasceva piano piano, in un residence semplice, ma adeguato a farci da nido in quel periodo di luna di miele a tre&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":220226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279],"class_list":["post-220199","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione in Africa: &quot;Consiglio ancora di adottare bambini grandi&quot;<\/title>\n<meta name=\"description\" content=\"Adozione, famiglia che nasce: &quot;Sono state le 3 settimane pi\u00f9 belle della nostra vita quelle in Africa, con il rapporto genitori-figlio che nasceva piano piano&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione in Africa &quot;Ancora adesso consiglio a chiunque di adottare bambini grandi&quot;. Ecco perch\u00e9.\" \/>\n<meta property=\"og:description\" content=\"Adozione, famiglia che nasce: &quot;Sono state le 3 settimane pi\u00f9 belle della nostra vita quelle in Africa, con il rapporto genitori-figlio che nasceva piano piano&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T07:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T09:46:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/adozione-questa-cameretta-nostro-figlio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione in Africa &#8220;Ancora adesso consiglio a chiunque di adottare bambini grandi&#8221;. Ecco perch\u00e9.\",\"datePublished\":\"2024-02-29T07:40:54+00:00\",\"dateModified\":\"2024-03-21T09:46:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/\"},\"wordCount\":596,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/adozione-questa-cameretta-nostro-figlio.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/\",\"name\":\"Adozione in Africa: \\\"Consiglio ancora di adottare bambini grandi\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/adozione-questa-cameretta-nostro-figlio.jpg\",\"datePublished\":\"2024-02-29T07:40:54+00:00\",\"dateModified\":\"2024-03-21T09:46:20+00:00\",\"description\":\"Adozione, famiglia che nasce: \\\"Sono state le 3 settimane pi\u00f9 belle della nostra vita quelle in Africa, con il rapporto genitori-figlio che nasceva piano piano\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/adozione-questa-cameretta-nostro-figlio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/02\\\/adozione-questa-cameretta-nostro-figlio.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-africa-adottare-bambini-grandi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione in Africa &#8220;Ancora adesso consiglio a chiunque di adottare bambini grandi&#8221;. Ecco perch\u00e9.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione in Africa: \"Consiglio ancora di adottare bambini grandi\"","description":"Adozione, famiglia che nasce: \"Sono state le 3 settimane pi\u00f9 belle della nostra vita quelle in Africa, con il rapporto genitori-figlio che nasceva piano piano\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione in Africa \"Ancora adesso consiglio a chiunque di adottare bambini grandi\". Ecco perch\u00e9.","og_description":"Adozione, famiglia che nasce: \"Sono state le 3 settimane pi\u00f9 belle della nostra vita quelle in Africa, con il rapporto genitori-figlio che nasceva piano piano\"","og_url":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-02-29T07:40:54+00:00","article_modified_time":"2024-03-21T09:46:20+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/adozione-questa-cameretta-nostro-figlio.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione in Africa &#8220;Ancora adesso consiglio a chiunque di adottare bambini grandi&#8221;. Ecco perch\u00e9.","datePublished":"2024-02-29T07:40:54+00:00","dateModified":"2024-03-21T09:46:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/"},"wordCount":596,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/adozione-questa-cameretta-nostro-figlio.jpg","keywords":["adozione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/","url":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/","name":"Adozione in Africa: \"Consiglio ancora di adottare bambini grandi\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/adozione-questa-cameretta-nostro-figlio.jpg","datePublished":"2024-02-29T07:40:54+00:00","dateModified":"2024-03-21T09:46:20+00:00","description":"Adozione, famiglia che nasce: \"Sono state le 3 settimane pi\u00f9 belle della nostra vita quelle in Africa, con il rapporto genitori-figlio che nasceva piano piano\"","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/adozione-questa-cameretta-nostro-figlio.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/02\/adozione-questa-cameretta-nostro-figlio.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-africa-adottare-bambini-grandi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione in Africa &#8220;Ancora adesso consiglio a chiunque di adottare bambini grandi&#8221;. Ecco perch\u00e9."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:49:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/220199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=220199"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/220199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/220226"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=220199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=220199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=220199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}