﻿


{"id":221068,"date":"2024-04-07T07:55:12","date_gmt":"2024-04-07T05:55:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=221068"},"modified":"2024-04-11T15:33:39","modified_gmt":"2024-04-11T13:33:39","slug":"adozione-internazionale-peru-sospesi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/","title":{"rendered":"Adozione Internazionale. &#8220;In Per\u00f9 ci sentivamo sospesi&#8230; poi siete arrivati voi due&#8221;"},"content":{"rendered":"<h2>\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell&#8217;addio<!--more--><\/h2>\n<p>\u201cNon vedevo l\u2019ora di fare un giro in macchina con il mio pap\u00e0!\u201d e mentre esclamava gioioso queste parole, Juan saltava sul sedile della macchina davanti agli occhi emozionati e increduli del pap\u00e0.<br \/>\n\u201cEravamo appena atterrati dal Per\u00f9, avevamo mangiato una pizza, un po\u2019 stanchi per il fuso orario, e quando si \u00e8 trattato di andare a casa a dormire Juan, il figlio pi\u00f9 grande, espresse questo desiderio: <strong>pap\u00e0, facciamo un giro in macchina io e te!<\/strong>\u201d.<\/p>\n<h3>Il racconto durante gli incontri informativi di Ai.Bi.<\/h3>\n<p>Il racconto e il ricordo di Antonio prosegue, carico di dettagli ed emozioni che ancora sono vive nove anni dopo dal rientro in Italia con i due figli, Juan e Salvador, all\u2019epoca di 9 e 6 anni.<br \/>\nAntonio e sua moglie Peggy spesso offrono disponibilit\u00e0 a raccontare la loro esperienza durante gli incontri informativi di Ai.Bi., a Roma, alla coppie che si stanno avvicinando all\u2019adozione. Episodi come questo dicono gi\u00e0 molto dei bambini che attendono in istituto l\u2019arrivo di una famiglia tutta per loro e per sempre.<br \/>\n\u201cMi piace esprimere il punto di vista del pap\u00e0 nell\u2019adozione anche perch\u00e9 pap\u00e0 e mamma hanno in comune gli stessi percorsi, le stesse emozioni in questa particolare \u2018gravidanza\u2019 &#8211; dice Antonio -. Dagli esperti sappiamo che\u00a0solitamente i bambini mostrano difficolt\u00e0 con la mamma, all\u2019inizio, mentre conoscono poco il padre, la figura maschile, proprio perch\u00e9 di solito negli istituti vi sono tate ed educatrici. E cos\u00ec anche i primi giorni di affiatamento in Per\u00f9, Juan e Salvador hanno conosciuto un pap\u00e0 che all\u2019inizio era come un fratello maggiore che amava giocare con loro.<\/p>\n<h3>Un percorso di genitorialit\u00e0 particolare<\/h3>\n<p>\u201c<strong>I nostri figli desideravano tanto una famiglia<\/strong>, ce lo hanno detto &#8211; continua Antonio &#8211; e il fatto di essere grandicelli, quindi consapevoli della loro situazione, ha aiutato molto nella costruzione della famiglia: erano e sono stati parte attiva anche del crescere dell\u2019attaccamento, che quindi si \u00e8 sviluppato in modo naturale\u201d.<br \/>\nAntonio e Peggy, durante gli incontri, segnalano anche il fatto che \u201c<strong>i genitori adottivi hanno la fortuna di fare un percorso di genitorialit\u00e0 particolare<\/strong>, si preparano, sono propensi a chiedere aiuto durante la crescita dei figli. Questo \u00e8 un valore aggiunto &#8211; dicono &#8211; : chiedere aiuto se hai difficolt\u00e0 con i figli \u00e8 ancora un tab\u00f9 per molti perch\u00e9 si sentono giudicati. L\u2019adozione ti fa passare tutte queste paure\u201d.<br \/>\nOggi i figli di Antonio e Peggy si avvicinano all\u2019adolescenza e tanta strada \u00e8 stata percorsa dal giorno in cui lasciarono in loro hogar in un paesino vicino a Lima.<br \/>\n\u201cEra un bellissimo istituto, quasi una casa famiglia in un edificio in stile coloniale portoghese immerso nella campagna &#8211; ricorda la coppia &#8211; : erano accolti una ventina di bambini seguiti da 5 o 6 educatrici. Possiamo dire che i nostri figli sono stati cresciuti in un luogo sereno, per quanto fossero senza una famiglia\u201d.<br \/>\nE infatti Antonio ricorda che tempo fa i bambini dissero che <strong>in Per\u00f9 \u201csi sentivano sospesi\u201d<\/strong>, caratteristica che accomuna a tutti i bambini che vivono in istituti o centri di accoglienza, anche quando sono strutture curate e dotate di molti servizi per l\u2019infanzia in cui non mancano mai cibo o vestiti.<\/p>\n<h3>La partenza<\/h3>\n<p>\u201cQuando arriva il momento dell\u2019adozione, dei saluti perch\u00e9 si lascia la casa famiglia, c\u2019\u00e8 una specie di rito &#8211; ricorda Antonio &#8211; I genitori, una volta arrivati, alloggiano per alcuni giorni in un appartamentino accanto all\u2019istituto\u00a0per facilitare l\u2019ambientamento dei bambini che a poco a poco lasciano le loro abitudini.<br \/>\nPer noi il processo di distacco \u00e8 avvenuto bene: ci siamo subito messi a giocare, abbiamo fatto un giro nel paesino per fare la spesa e comprare alcuni accessori per sistemare le biciclette del centro che erano tutte malconce e che abbiamo aggiustato insieme. Poi di solito, la sera prima di lasciare la casa, si organizza una cena e una festa tutti insieme; noi abbiamo anche giocato a tombola\u201d.<br \/>\nL\u2019affiatamento della famiglia, che ha trascorso poco pi\u00f9 di un mese in Per\u00f9, \u00e8 proseguito a Lima in cui i ritmi della famiglia iniziavano a prendere forma.<br \/>\nUn ricordo di quelle sere riguarda invece il figlio pi\u00f9 piccolo:<br \/>\n\u201cI bambini erano entrambi un po\u2019 agitati i primi giorni, per i molti cambiamenti. Ma era Salvador che di notte si alzava, si affacciava alla porta della nostra camera da letto e veniva a vedere se c\u2019eravamo ancora\u201d.<\/p>\n<h3>Sostieni il progetto Fondo accoglienza bambini abbandonati<\/h3>\n<p>Con una donazione al\u00a0<strong>Fondo accoglienza bambini abbandonati<\/strong>\u00a0anche tu potrai aiutare tanti minori a mantenere viva la speranza di poter \u201crinascere\u201d figli amati e accolti da una famiglia.<br \/>\nScopri come,\u00a0cliccando\u00a0<strong><a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;caus=3870\">qui.<\/a><\/strong><\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a <a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;I nostri figli desideravano tanto una famiglia&rdquo;. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell&rsquo;addio<\/p>\n","protected":false},"author":133,"featured_media":221069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279],"class_list":["post-221068","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale. &quot;In Per\u00f9 ci sentivamo sospesi...&quot;<\/title>\n<meta name=\"description\" content=\"\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell&#039;addio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale. &quot;In Per\u00f9 ci sentivamo sospesi... poi siete arrivati voi due&quot;\" \/>\n<meta property=\"og:description\" content=\"\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell&#039;addio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-07T05:55:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T13:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/adozione-peru.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione Internazionale. &#8220;In Per\u00f9 ci sentivamo sospesi&#8230; poi siete arrivati voi due&#8221;\",\"datePublished\":\"2024-04-07T05:55:12+00:00\",\"dateModified\":\"2024-04-11T13:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/\"},\"wordCount\":852,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/adozione-peru.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/\",\"name\":\"Adozione Internazionale. \\\"In Per\u00f9 ci sentivamo sospesi...\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/adozione-peru.jpg\",\"datePublished\":\"2024-04-07T05:55:12+00:00\",\"dateModified\":\"2024-04-11T13:33:39+00:00\",\"description\":\"\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell'addio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/adozione-peru.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/adozione-peru.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-peru-sospesi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale. &#8220;In Per\u00f9 ci sentivamo sospesi&#8230; poi siete arrivati voi due&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale. \"In Per\u00f9 ci sentivamo sospesi...\"","description":"\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell'addio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale. \"In Per\u00f9 ci sentivamo sospesi... poi siete arrivati voi due\"","og_description":"\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell'addio","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-04-07T05:55:12+00:00","article_modified_time":"2024-04-11T13:33:39+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/adozione-peru.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione Internazionale. &#8220;In Per\u00f9 ci sentivamo sospesi&#8230; poi siete arrivati voi due&#8221;","datePublished":"2024-04-07T05:55:12+00:00","dateModified":"2024-04-11T13:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/"},"wordCount":852,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/adozione-peru.jpg","keywords":["adozione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/","name":"Adozione Internazionale. \"In Per\u00f9 ci sentivamo sospesi...\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/adozione-peru.jpg","datePublished":"2024-04-07T05:55:12+00:00","dateModified":"2024-04-11T13:33:39+00:00","description":"\u201cI nostri figli desideravano tanto una famiglia\u201d. Una testimonianza carica di emozioni, quella di una coppia che ha dato a due bambini peruviani un posto nel mondo. Il rito dell'addio","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/adozione-peru.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/adozione-peru.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-peru-sospesi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale. &#8220;In Per\u00f9 ci sentivamo sospesi&#8230; poi siete arrivati voi due&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:57:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/221068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=221068"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/221068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/221069"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=221068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=221068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=221068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}