﻿{"id":22118,"date":"2011-05-02T14:52:39","date_gmt":"2011-05-02T13:52:39","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=22118"},"modified":"2011-05-03T11:44:29","modified_gmt":"2011-05-03T10:44:29","slug":"adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/","title":{"rendered":"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-22119\" style=\"margin: 5px;\" title=\"austria_kafala\" src=\"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Il commissario per i diritti umani del Consiglio d&#8217;Europa, Thomas Hammarberg, pubblicando un documento sull\u2019adozione dei minori dal punto di vista dei diritti umani ha chiesto <strong><em>\u201cnorme pi\u00f9 severe\u201d<\/em> per l&#8217;accreditamento delle agenzie di adozione<\/strong>. Hammarberg ha inoltre ribadito l\u2019importanza di aver maggiori garanzie nelle procedure ed una particolare attenzione per le adozioni nel periodo immediatamente successivo a gravi emergenze.<\/p>\n<p><em>\u201cGli Stati membri dovrebbero garantire <strong>una migliore tutela dei minori nel processo di adozione.<\/strong> A dispetto degli accordi internazionali, le realt\u00e0 dell\u2019adozione sono ancora molto diverse tra i Paesi europei dando origine a gravi preoccupazioni per quanto riguarda i diritti umani\u201d<\/em>.<\/p>\n<p>Il commissario per i diritti umani del Consiglio d&#8217;Europa, sottolinea anche la <strong><em>\u201cnecessit\u00e0 di garanzie procedurali\u201d<\/em><\/strong>, raccomanda che le adozioni internazionali abbiano luogo <em>\u201csolo quando non esistono adeguate alternative nazionali, e all&#8217;interno di normative internazionali concordate\u201d<\/em>, e chiede <strong><em>\u201cnorme pi\u00f9 severe\u201d<\/em><\/strong> <strong>per l&#8217;accreditamento delle agenzie di adozione.<\/strong><\/p>\n<p>Particolare attenzione viene richiesta per le <strong>adozioni nel periodo immediatamente successivo a gravi emergenze<\/strong>, al fine di impedire eventuali abusi e violazioni di obblighi internazionali: <em>\u201cAnche se negli ultimi anni questo principio \u00e8 stato generalmente seguito dai Paesi europei riceventi, le adozioni degli haitiani dopo il terremoto del gennaio 2010 ha dimostrato la fragilit\u00e0 della sua applicazione\u201d<\/em>.<\/p>\n<p>Fondamentale per Hammarberg <em>\u201cimparare da questa esperienza\u201d<\/em> per <strong><em>\u201csalvaguardare i diritti dei bambini\u201d<\/em> <\/strong>in futuro e <em>\u201cgarantire conformit\u00e0 con gli standard internazionali\u201d.<\/em><\/p>\n<p><em>(Fonte: <a href=\"https:\/\/wcd.coe.int\/wcd\/ViewDoc.jsp?Ref=PR376(2011)&amp;Language=lanEnglish&amp;Ver=original&amp;BackColorInternet=F5CA75&amp;BackColorIntranet=F5CA75&amp;BackColorLogged=A9BACE\">Consiglio d&#8217;Europa<\/a>)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il commissario per i diritti umani del Consiglio d&#8217;Europa, Thomas Hammarberg, pubblicando un documento sull\u2019adozione dei minori dal punto di vista dei diritti umani ha chiesto <strong><em>\u201cnorme pi\u00f9 severe\u201d<\/em> per l&#8217;accreditamento degli enti di adozione<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l\u2019accreditamento-degli-enti\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-22118","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l\u2019accreditamento-degli-enti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti\" \/>\n<meta property=\"og:description\" content=\"Il commissario per i diritti umani del Consiglio d&#039;Europa, Thomas Hammarberg, pubblicando un documento sull\u2019adozione dei minori dal punto di vista dei diritti umani ha chiesto \u201cnorme pi\u00f9 severe\u201d per l&#039;accreditamento degli enti di adozione. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l\u2019accreditamento-degli-enti\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-02T13:52:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-05-03T10:44:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti\",\"datePublished\":\"2011-05-02T13:52:39+00:00\",\"dateModified\":\"2011-05-03T10:44:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/\"},\"wordCount\":249,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/austria_kafala5.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/\",\"name\":\"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/austria_kafala5.jpg\",\"datePublished\":\"2011-05-02T13:52:39+00:00\",\"dateModified\":\"2011-05-03T10:44:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/austria_kafala5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/austria_kafala5.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l\u2019accreditamento-degli-enti\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti","og_description":"Il commissario per i diritti umani del Consiglio d'Europa, Thomas Hammarberg, pubblicando un documento sull\u2019adozione dei minori dal punto di vista dei diritti umani ha chiesto \u201cnorme pi\u00f9 severe\u201d per l'accreditamento degli enti di adozione. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l\u2019accreditamento-degli-enti\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-05-02T13:52:39+00:00","article_modified_time":"2011-05-03T10:44:29+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti","datePublished":"2011-05-02T13:52:39+00:00","dateModified":"2011-05-03T10:44:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/"},"wordCount":249,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/","name":"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg","datePublished":"2011-05-02T13:52:39+00:00","dateModified":"2011-05-03T10:44:29+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/austria_kafala5.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-ue-servono-norme-piu-severe-per-l%e2%80%99accreditamento-degli-enti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Internazionali, UE: servono norme pi\u00f9 severe per l\u2019accreditamento degli enti"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:10:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/22118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=22118"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/22118\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=22118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=22118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=22118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}