﻿


{"id":221309,"date":"2024-04-10T07:55:02","date_gmt":"2024-04-10T05:55:02","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=221309"},"modified":"2024-04-11T16:53:44","modified_gmt":"2024-04-11T14:53:44","slug":"genitori-accetterei-subito-senza-pensare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/","title":{"rendered":"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!"},"content":{"rendered":"<h2>I bambini vedono ci\u00f2 che succede, incrociano anche se fugacemente i genitori (per altri) e sanno o percepiscono cosa sta per accadere&#8230;non per loro: alcuni sono solo incuriositi, altri vogliono sbirciare , i pi\u00f9 grandi se ne vanno infastiditi, perch\u00e9 &#8220;non \u00e8 affare loro&#8230;anche se in fondo vorrebbero&#8221;<br \/>\n<!--more--><\/h2>\n<p>\u00c8 successo di nuovo e credo succeder\u00e0 ancora. Lo vedo spesso quando accompagno le coppie in istituto, per l&#8217;affiatamento col proprio figlio. A fronte di due occhi scintillanti, pieni di gioia ed orgogliosi,\u00a0della bimba che vive il suo momento:\u00a0finalmente mamma e pap\u00e0 sono qui per lei, ne scorgo tanti, troppi, tristi, sconsolati, senza speranza che piangono, o che fissano il vuoto\u00a0<strong>pregando arrivi presto anche per loro il momento di incontrare i propri genitori<\/strong>.<br \/>\nO altri occhi ancora, che si riempiono di rabbia, mentre osservano la scena di amore che si sprigiona nella saletta dedicata a questi momenti di &#8220;formazione della famiglia&#8221;: sono di chi \u00e8 in questa condizione di sospensione da tanto tempo e\u00a0<strong>vorrebbe che arrivassero due persone a salvarli, &#8230;ma questo sogno tarda a realizzarsi<\/strong>\u00a0e l&#8217;unica cosa che riescono a fare \u00e8 provare invidia per il fortunato!.<\/p>\n<h3>Le procedure in una stanza, i sentimenti nel resto della palazzina<\/h3>\n<p>Per via del tipo di procedura da rispettare, gli istituti si dotano di stanze appositamente rivolte a questo scopo: l&#8217;incontro e l&#8217;affiatamento tra i genitori che provengono dall&#8217;estero e il bambino abbinato, che non pu\u00f2 uscire dalla struttura. Sono<strong>\u00a0luoghi deputati alla formazione del rapporto tra questi sconosciuti, che una pratica adottiva ha reso famiglia<\/strong>, ma che necessita di un po&#8217; di tempo, per concretizzarsi davvero.<br \/>\nGli incontri, che avvengono con determinate tempistiche, devono essere valutati con accuratezza, per dare al bambino e alla coppia straniera, il tempo e il modo per un graduale avvicinamento. Quindi anche il personale interno viene precettato per soddisfare certe esigente contingenti, per fare ci\u00f2 che serve, nel momento in cui viene vissuta questa pratica.<br \/>\n<strong>Se tanta cura viene riservata per l&#8217;avvio della nuova famiglia, non altrettanti pensieri vengono fatti per gli altri piccoli ospiti dell&#8217;istituto!<br \/>\n<\/strong>L&#8217;edificio spesso non permette di evitare il passaggio della coppia nei locali frequentati dagli altri piccoli, che qui hanno trovato casa, temporaneamente, ma che a volte ci restano per sempre!<\/p>\n<p><strong>L&#8217;impegno di Ai.Bi. per rispondere alle domande dei bambini che attendono<\/strong><\/p>\n<p>Questa volta \u00e8 successo che un bel bimbo si \u00e8 fatto avanti, per salutare e abbracciare la madre (della fortunata amichetta che presto se ne andr\u00e0 coi propri genitori).<strong>\u00a0Desideroso di un&#8217;attenzione particolare tutta per s\u00e9,<\/strong>\u00a0\u00e8 entrato nella stanza e si \u00e8 avvicinata alla nostra mamma italiana, che ha ricambiato il sorriso e ha accolto tra le braccia questo bimbo intraprendente, mentre la figlia era impegnata col padre a costruire un puzzle. Ma ovviamente la figlioletta adottiva, subito ha &#8220;marcato il territorio&#8221; allontanandolo\u00a0e facendo ben vedere che la mamma \u00e8 la sua, dicendo qualche cosa al bimbo, che se ne \u00e8 andato.<br \/>\nIo che conosco la lingua ho evitato di tradurre ai genitori,\u00a0ma ho seguito il bimbo nel corridoio, l&#8217;ho visto allontanarsi e scrollare le spalle, finch\u00e9 ho perso le sue tracce, perch\u00e9 si \u00e8 rintanato nella sua cameretta, dove me lo immagino a piangere.<br \/>\n<strong>Ho provato il suo dolore e la speranza ancora viva, che piano piano scema<\/strong>\u00a0e finisce per dargli solo la forza per sopravvivere ancora,\u00a0un giorno in pi\u00f9\u00a0in attesa, in solitudine,\u00a0<strong>desiderando la mamma che non pu\u00f2 avere.<\/strong><\/p>\n<h3>In bilico tra gioia e dolore<\/h3>\n<p>Giuro che \u00e8 difficile, che non riesco a darmi una spiegazione del perch\u00e9 tanto dolore debba essere rinchiuso in quattro mura gelide, che dovrebbero essere una casa provvisoria e invece resta\u00a0casa\u00a0per sempre.<br \/>\nSono tornata velocemente a supportare la coppia che rappresento e che \u00e8 riuscita ad adottare, ma il giorno dopo ho chiamato la direttrice, per sapere come stava quel bimbetto. Mi ha &#8220;rassicurata&#8221; riferendomi che l&#8217;educatrice gli ha parlato e lui, dopo un po&#8217; si \u00e8 rassegnato, dicendole amaramente: &#8220;Io <strong>due genitori cos\u00ec li accetterei subito<\/strong>, senza neanche pensarci&#8221;<\/p>\n<p style=\"font-weight: 400;\"><strong>Desk Adozione internazionale estero Ai.Bi.<\/strong><\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p style=\"font-weight: 400;\">Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a <a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>I bambini vedono ci&ograve; che succede, incrociano anche se fugacemente i genitori (per altri) e sanno o percepiscono cosa sta per accadere&hellip;non per loro: alcuni sono solo incuriositi, altri vogliono sbirciare , i pi&ugrave; grandi se ne vanno infastiditi, perch&eacute; &ldquo;non &egrave; affare loro&hellip;anche se in fondo vorrebbero&rdquo;<\/p>\n","protected":false},"author":145,"featured_media":206596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347],"class_list":["post-221309","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!<\/title>\n<meta name=\"description\" content=\"Il racconto di una referente Ai.Bi. per l&#039;adozione internazionale, in bilico tra la gioia di una nuova famiglia che nasce e il dolore di chi &quot;non vede arrivare&quot; dei genitori\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!\" \/>\n<meta property=\"og:description\" content=\"Il racconto di una referente Ai.Bi. per l&#039;adozione internazionale, in bilico tra la gioia di una nuova famiglia che nasce e il dolore di chi &quot;non vede arrivare&quot; dei genitori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-10T05:55:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T14:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Apaolin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Apaolin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/\"},\"author\":{\"name\":\"Apaolin\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/9e560347b42f3f6e06eeb61bac51c5b3\"},\"headline\":\"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!\",\"datePublished\":\"2024-04-10T05:55:02+00:00\",\"dateModified\":\"2024-04-11T14:53:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/\"},\"wordCount\":725,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/\",\"name\":\"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"datePublished\":\"2024-04-10T05:55:02+00:00\",\"dateModified\":\"2024-04-11T14:53:44+00:00\",\"description\":\"Il racconto di una referente Ai.Bi. per l'adozione internazionale, in bilico tra la gioia di una nuova famiglia che nasce e il dolore di chi \\\"non vede arrivare\\\" dei genitori\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-accetterei-subito-senza-pensare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/9e560347b42f3f6e06eeb61bac51c5b3\",\"name\":\"Apaolin\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/apaolin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!","description":"Il racconto di una referente Ai.Bi. per l'adozione internazionale, in bilico tra la gioia di una nuova famiglia che nasce e il dolore di chi \"non vede arrivare\" dei genitori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!","og_description":"Il racconto di una referente Ai.Bi. per l'adozione internazionale, in bilico tra la gioia di una nuova famiglia che nasce e il dolore di chi \"non vede arrivare\" dei genitori","og_url":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-04-10T05:55:02+00:00","article_modified_time":"2024-04-11T14:53:44+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","type":"image\/jpeg"}],"author":"Apaolin","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Apaolin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/"},"author":{"name":"Apaolin","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/9e560347b42f3f6e06eeb61bac51c5b3"},"headline":"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!","datePublished":"2024-04-10T05:55:02+00:00","dateModified":"2024-04-11T14:53:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/"},"wordCount":725,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","keywords":["Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/","url":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/","name":"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","datePublished":"2024-04-10T05:55:02+00:00","dateModified":"2024-04-11T14:53:44+00:00","description":"Il racconto di una referente Ai.Bi. per l'adozione internazionale, in bilico tra la gioia di una nuova famiglia che nasce e il dolore di chi \"non vede arrivare\" dei genitori","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/genitori-accetterei-subito-senza-pensare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione: due genitori cos\u00ec io li accetterei subito, senza neanche pensarci!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/9e560347b42f3f6e06eeb61bac51c5b3","name":"Apaolin","url":"https:\/\/www.aibi.it\/ita\/author\/apaolin\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/221309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/145"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=221309"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/221309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/206596"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=221309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=221309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=221309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}