﻿


{"id":221679,"date":"2024-04-25T08:00:22","date_gmt":"2024-04-25T06:00:22","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=221679"},"modified":"2024-04-26T14:16:33","modified_gmt":"2024-04-26T12:16:33","slug":"tessere-relazioni-positive-futuro-donne-mamme","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/","title":{"rendered":"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme"},"content":{"rendered":"<h2>Marted\u00ec 30 aprile, ci sar\u00e0 un Open Day dalle 10.30 alle 18.30, per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 sviluppate con il contributo di Fondazione di Comunit\u00e0 Milano per creare reti di comunit\u00e0 e di aiuto reciproco sul territorio<\/h2>\n<p><!--more--><\/p>\n<p>A Milano, nello specifico nel quartiere di Affori, a nord della citt\u00e0, sta per essere avviato un nuovo progetto di Amici dei Bambini a <strong>sostegno di donne, mamme e ragazze<\/strong>, grazie al contributo di <strong>Fondazione di Comunit\u00e0 Milano<\/strong>.<br \/>\nCuore dell\u2019attivit\u00e0 \u00e8 lo <strong>sportello Ben-ESSERE DONNA<\/strong>, un servizio gratuito di ascolto e supporto psicologico per le donne e le mamme in difficolt\u00e0, che sar\u00e0 attivo tutti i mercoled\u00ec mattina, previo appuntamento chiamando il numero 375.6215269 o mandando una mail a <a href=\"mailto:affori@aibi.it\">affori@aibi.it<\/a>.<\/p>\n<h3>Fare rete per affrontare meglio il futuro<\/h3>\n<p>Attorno a questa attivit\u00e0, il progetto si articola con una serie di altre iniziative tutte pensate con l\u2019obiettivo di <strong>creare reti di comunit\u00e0 e di aiuto reciproco sul territorio<\/strong>. In particolare, saranno attivate delle consulenze con professionisti sui temi della cura e dell\u2019educazione della prima infanzia. Ma non solo, perch\u00e9, proprio per incentivare il senso di \u201ccomunit\u00e0\u201d e la condivisione di bisogni ed esperienze, all\u2019interno del progetto sono previsti dei momenti pi\u00f9 conviviali come il \u201c<strong>Caff\u00e8 delle mamme<\/strong>\u201d, per scambiarsi opinioni o anche per fare semplicemente una chiacchierata in amicizia, o <strong>attivit\u00e0 di yoga<\/strong> per mamme e bambini. Tutto con l\u2019intento di mettere a disposizione di donne, mamme e ragazze dei <strong>momenti di condivisione<\/strong> per creare una <strong>comunit\u00e0 pi\u00f9 coesa e sicura.<br \/>\n<\/strong>\u00c8 prevista anche la creazione di uno <strong>spazio ludico creativo<\/strong> per intrattenere i pi\u00f9 piccoli nei momenti in cui gli operatori si occupano delle loro mamme.<br \/>\nPer presentare tutto questo a chiunque sia interessato, per <strong>marted\u00ec 30 aprile<\/strong> \u00e8 in programma un open day dello spazio di <strong>viale Affori, 12, a Milano<\/strong>, presso il Centro Servizi alla Famiglia Fidarsi della Vita.<br \/>\n<strong>Dalle 10.30 alle 18.30<\/strong> si troveranno operatori di Ai.Bi., responsabili e volontari che illustreranno le caratteristiche di un progetto importante per la citt\u00e0 di Milano e tutte le donne e le mamme.<\/p>\n<h3>Sostieni progetto &#8220;Educare il Domani&#8221;<\/h3>\n<p>Questa iniziativa si inserisce nel pi\u00f9 ampio contesto del progetto \u201cEducare il Domani\u201d di Ai.Bi. volto a contrastare la povert\u00e0 educativa che affligge oltre 3,5 milioni di minori in Italia.<br \/>\nPer sostenere il progetto \u201cEducare il Domani\u201d clicca <a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;caus=3784\"><strong>QUI<\/strong><\/a>.<br \/>\nSe vuoi fare di pi\u00f9 e stare vicino ogni giorno ai bambini e i ragazzi dei nostri Pan di Zucchero, ricevere informazione periodiche sulle attivit\u00e0, puoi attivare un\u2019Adozione a Distanza.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*221096-start*\/\n#btnsx-221096{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-221096 .btnsx-text-primary{font-size:21px;line-height:21px;font-style:normal;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-221096:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-221096{background-color:#ef7b0b!important;}\n#btnsx-221096:hover{background-color:#eab20b!important;}\n#btnsx-221096{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-221096:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-221096{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-221096:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*221096-end*\/\n<\/style><div id=\"btnsx-221096-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-221096-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Italia\" id=\"btnsx-221096\" target=\"_self\" class=\"btnsx-btn btnsx-btn-embossed\" >\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>E ricorda: come ogni donazione, anche le<strong> Adozioni a Distanza di Ai.Bi. <\/strong>godono delle seguenti <a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a><br \/>\nPer richiedere informazioni sull\u2019Adozione a Distanza <a href=\"https:\/\/zimbra.teleposta.it\/#infosad\">clicca qui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted&igrave; 30 aprile, ci sar&agrave; un Open Day dalle 10.30 alle 18.30, per il lancio del progetto &ldquo;Relazioni Positive&rdquo;. Uno sportello Ben-ESSERE donna e altre attivit&agrave; sviluppate con il contributo di Fondazione di Comunit&agrave; Milano per creare reti di comunit&agrave; e di aiuto reciproco sul territorio<\/p>\n","protected":false},"author":102,"featured_media":221728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[1094,1011],"class_list":["post-221679","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-educare-il-domani","tag-progetti-in-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme<\/title>\n<meta name=\"description\" content=\"Marted\u00ec 30 aprile, Open Day per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 per creare reti di comunit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme\" \/>\n<meta property=\"og:description\" content=\"Marted\u00ec 30 aprile, Open Day per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 per creare reti di comunit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T06:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T12:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/Relazioni-positive-immagine-news.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme\",\"datePublished\":\"2024-04-25T06:00:22+00:00\",\"dateModified\":\"2024-04-26T12:16:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/Relazioni-positive-immagine-news.jpg\",\"keywords\":[\"educare il domani\",\"progetti in italia\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/\",\"name\":\"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/Relazioni-positive-immagine-news.jpg\",\"datePublished\":\"2024-04-25T06:00:22+00:00\",\"dateModified\":\"2024-04-26T12:16:33+00:00\",\"description\":\"Marted\u00ec 30 aprile, Open Day per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 per creare reti di comunit\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/Relazioni-positive-immagine-news.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/04\\\/Relazioni-positive-immagine-news.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tessere-relazioni-positive-futuro-donne-mamme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme","description":"Marted\u00ec 30 aprile, Open Day per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 per creare reti di comunit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/","og_locale":"it_IT","og_type":"article","og_title":"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme","og_description":"Marted\u00ec 30 aprile, Open Day per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 per creare reti di comunit\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-04-25T06:00:22+00:00","article_modified_time":"2024-04-26T12:16:33+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/Relazioni-positive-immagine-news.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme","datePublished":"2024-04-25T06:00:22+00:00","dateModified":"2024-04-26T12:16:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/"},"wordCount":472,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/Relazioni-positive-immagine-news.jpg","keywords":["educare il domani","progetti in italia"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/","url":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/","name":"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/Relazioni-positive-immagine-news.jpg","datePublished":"2024-04-25T06:00:22+00:00","dateModified":"2024-04-26T12:16:33+00:00","description":"Marted\u00ec 30 aprile, Open Day per il lancio del progetto \u201cRelazioni Positive\u201d. Uno sportello Ben-ESSERE donna e altre attivit\u00e0 per creare reti di comunit\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/Relazioni-positive-immagine-news.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/04\/Relazioni-positive-immagine-news.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/tessere-relazioni-positive-futuro-donne-mamme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Milano. Tessere \u201crelazioni positive\u201d per il futuro di donne e mamme"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:11:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/221679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=221679"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/221679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/221728"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=221679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=221679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=221679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}