﻿


{"id":222963,"date":"2024-06-06T07:30:14","date_gmt":"2024-06-06T05:30:14","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=222963"},"modified":"2024-06-11T13:19:18","modified_gmt":"2024-06-11T11:19:18","slug":"ghana-georgina-scomparsa-casa-mamma","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/","title":{"rendered":"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0"},"content":{"rendered":"<h2>Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli &#8220;scomparsi&#8221;<\/h2>\n<p><!--more-->Dopo innumerevoli sforzi e tante ricerche nelle zone periferiche di Kasoa (cittadina nel distretto di Awutu Senya, nella regione centrale del Ghana), gli operatori di Ai.Bi. hanno finalmente localizzato la casa in cui Georgina viveva con la sua famiglia, prima della sua scomparsa e del suo conseguente approdo all&#8217;orfanotrofio <strong>Royal Seed Home<\/strong> in cui tutt&#8217;ora si trova.<br \/>\n\u00c8 bene ribadire come assistenti sociali e operatori si dedichino con grande cura al lavoro di reinserimento in famiglia dei minori trovati (e accolti temporaneamente negli istituti). Non solo, il team di Ai.Bi. nel Paese, anche una volta effettuato il ricongiungimento, segue con particolare zelo il nucleo familiare ricostituito, attuando monitoraggi costanti e offrendo consigli e servizi adeguati per la crescita completa dei bambini reintegrati in famiglia.<\/p>\n<h3>L&#8217;accoglienza di Georgina, finalmente a casa.<\/h3>\n<p>Nel caso di Georgina, le ricerche, durate parecchio tempo, hanno portato a individuare una zia. Non \u00e8 stato un lavoro semplice, perch\u00e9 erano diversi mesi che la famiglia non aveva pi\u00f9 notizie della bambina, la quale, fortunatamente, da parte sua, \u00e8 riuscita a dare delle preziose indicazioni che hanno aiutato gli operatori ad orientare le ricerche e individuare il nucleo familiare, residente in un villaggio molto isolato dove la miseria \u00e8 ad altissimi livelli.<\/p>\n<h3>Dopo il silenzio, le urla di gioia<\/h3>\n<p>Secondo un caro amico del padre di Georgina, la scomparsa della bambina ha causato la malattia di entrambi i genitori negli ultimi mesi e anche traumi psicologici importanti, legati al timore che potesse esserle successo qualcosa di molto grave. Entrambi i genitori, dopo diversi tentativi andati a vuoto di ritrovare la figlia, avevano perso le speranze di poterla riabbracciare e temevano potesse addirittura essere morta. Fortunatamente non \u00e8 stato cos\u00ec e quando, nonostante la famiglia sia indigente, la zia ha acconsentito a riaccogliere la piccola, il suo ritorno (avvenuto con la collaborazione e il monitoraggio del DSW- Department of Social Welfare) \u00e8 stato un momento di grande festa per tutti, compresi i bambini delle famiglie vicine che sono venuti per festeggiare il suo ritorno a casa.<br \/>\nPer tutti i protagonisti di questa vicenda si \u00e8 trattato di una bella storia, che oggi vale la pena raccontare. Ma con la consapevolezza che il lavoro da fare \u00e8 ancora tanto e che moltissimi bambini mancano all&#8217;appello delle loro famiglie, lontane da qualche parte, che magari a loro volta cercano informazioni che non riescono ad avere.<\/p>\n<h3>L\u2019attesa di Blessing e David<\/h3>\n<p>Negli orfanotrofi in Ghana, Blessing e David stanno ancora aspettando <strong>chi possa accompagnarli nel loro cammino di speranza e di emancipazione <\/strong>attraverso un\u2019<strong>Adozione a Distanza.<\/strong><br \/>\nLeggi la storia di <strong><a href=\"https:\/\/www.aibi.it\/ita\/ghana-aiuto-blessing-futuro\/\">Blessing<\/a><\/strong> e quella di <a href=\"https:\/\/www.aibi.it\/ita\/ghana-abbandono-david-orfanotrofio\/\"><strong>David<\/strong><\/a>.<\/p>\n<h3>Sostieni le attivit\u00e0 di Ai.Bi. in Ghana<\/h3>\n<p><strong>Ogni settimana arrivano nuovi bambini accolti nell\u2019orfanotrofio<\/strong> <strong>Royal Seed Home<\/strong> e ognuno di loro ha bisogno del tuo aiuto.<br \/>\nPer contribuire alle attivit\u00e0 promosse da Ai.Bi. in Ghana con una donazione, clicca <strong><a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">qui<\/a><\/strong>.<br \/>\nSe vuoi fare di pi\u00f9 e stare vicino ogni giorno ai bambini dell\u2019orfanotrofio <strong>Royal Seed Home<\/strong> e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto \u201cAdotta a distanza i bambini di un orfanotrofio\u201d.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Infine se vuoi creare con <strong>Blessing<\/strong> o con <strong>David<\/strong> un rapporto unico ed esclusivo per accompagnarli attivamente nella loro crescita, puoi adottare a distanza una di loro. Riceverai il suo dossier, potrai scriverle, ricevere le sue foto e mandarle le tue, chiedere e ricevere aggiornamenti periodici, pensare a regali aggiuntivi per momenti particolari. E, perch\u00e9 no, andare anche a trovarla.<br \/>\nPer richiedere informazioni sull\u2019Adozione a Distanza\u00a0<a href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a>.<br \/>\nE ricorda: come ogni donazione, anche <strong>le Adozioni a Distanza\u00a0di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una bella storia a lieto fine scritta grazie al progetto &ldquo;Adotta a Distanza i bambini di un orfanotrofio in Ghana&rdquo;. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all&rsquo;appello e che sono nelle liste degli &ldquo;scomparsi&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":222964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[1012],"class_list":["post-222963","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-royal-seed-home"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana. Georgina era scomparsa da casa\u2026<\/title>\n<meta name=\"description\" content=\"Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli &quot;scomparsi&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0\" \/>\n<meta property=\"og:description\" content=\"Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli &quot;scomparsi&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T05:30:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T11:19:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Ghana-Georgina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0\",\"datePublished\":\"2024-06-06T05:30:14+00:00\",\"dateModified\":\"2024-06-11T11:19:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Ghana-Georgina.jpg\",\"keywords\":[\"Royal Seed Home\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/\",\"name\":\"Ghana. Georgina era scomparsa da casa\u2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Ghana-Georgina.jpg\",\"datePublished\":\"2024-06-06T05:30:14+00:00\",\"dateModified\":\"2024-06-11T11:19:18+00:00\",\"description\":\"Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli \\\"scomparsi\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Ghana-Georgina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Ghana-Georgina.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-georgina-scomparsa-casa-mamma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana. Georgina era scomparsa da casa\u2026","description":"Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli \"scomparsi\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0","og_description":"Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli \"scomparsi\"","og_url":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-06-06T05:30:14+00:00","article_modified_time":"2024-06-11T11:19:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Ghana-Georgina.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0","datePublished":"2024-06-06T05:30:14+00:00","dateModified":"2024-06-11T11:19:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/"},"wordCount":668,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Ghana-Georgina.jpg","keywords":["Royal Seed Home"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/","url":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/","name":"Ghana. Georgina era scomparsa da casa\u2026","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Ghana-Georgina.jpg","datePublished":"2024-06-06T05:30:14+00:00","dateModified":"2024-06-11T11:19:18+00:00","description":"Una bella storia a lieto fine scritta grazie al progetto \u201cAdotta a Distanza i bambini di un orfanotrofio in Ghana\u201d. Ma dopo aver festeggiato, si torna a cercare tutti gli altri bambini che mancano all\u2019appello e che sono nelle liste degli \"scomparsi\"","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Ghana-Georgina.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Ghana-Georgina.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-georgina-scomparsa-casa-mamma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Ghana. Georgina era scomparsa da casa\u2026 Ora \u00e8 tornata dalla mamma\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:04:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/222963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=222963"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/222963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/222964"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=222963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=222963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=222963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}