﻿


{"id":223139,"date":"2024-06-13T07:40:53","date_gmt":"2024-06-13T05:40:53","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=223139"},"modified":"2024-06-17T14:09:48","modified_gmt":"2024-06-17T12:09:48","slug":"matrimonio-solidale-aiutare-bambini-abbandonati","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/","title":{"rendered":"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0"},"content":{"rendered":"<h2>Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati<!--more--><\/h2>\n<p>Comunemente\u00a0<strong>la<\/strong><strong>\u00a0<\/strong><strong>tarda primavera e l&#8217;inizio dell&#8217;autunno<\/strong>\u00a0sono considerati la &#8220;stagione dei matrimoni&#8221; perch\u00e9 le giornate sono ancora belle, lunghe e luminose, il clima \u00e8 mite ma non esageratamente caldo.<br \/>\nTra i vari dettagli da curare per rendere unico il grande giorno ci sono sicuramente le bomboniere.<br \/>\nSono sempre pi\u00f9 gli sposi, soprattutto tra i giovanissimi, che per il giorno pi\u00f9 importante della loro vita rivolgono un pensiero a chi ha pi\u00f9 bisogno scegliendo <strong>liste nozze e bomboniere solidali<\/strong>.<\/p>\n<h3>Bomboniere di Ai.Bi. per i bambini abbandonati<\/h3>\n<p>E allora, quale scelta pi\u00f9 adatta delle <strong>bomboniere solidali<\/strong> di\u00a0<strong>Amici dei Bambini<\/strong>\u00a0per far\u00a0<strong>rinascere figli<\/strong> i tanti bambini abbandonati nel mondo, sostenendo in tal modo una delle tante attivit\u00e0 della associazione nei vari paesi in cui opera?!<br \/>\n<strong>Un bambino abbandonato \u00e8 anche un bambino dimenticato<\/strong>. Non ha nessuno che pensi a lui con affetto.<br \/>\n\u00c8 bello, quindi, durante un giorno di festa come pu\u00f2 essere un matrimonio, far s\u00ec che festeggiati e ospiti di questo giorno speciale pensino a lui. <strong>Si sentir\u00e0 meno solo!<\/strong><br \/>\nBomboniere <strong>uniche<\/strong>, <strong>eleganti<\/strong>, <strong>esclusive<\/strong> e <strong>solidali<\/strong>, che raccontano storie di nuovi inizi, di bambine e bambini accolti negli orfanotrofi di tutto il mondo che, finalmente, incontrano una famiglia che li ami.<br \/>\nDiverse sono le proposte solidali sul sito dell\u2019associazione ma per una scelta speciale, Ai.Bi. propone la\u00a0<a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/bomboniera\/bomboniera-adozione-a-distanza\/\"><strong>Bomboniera Adozione a Distanza<\/strong><\/a>, un dono ricco di significato per costruire una vita insieme, tessera dopo tessera.<\/p>\n<h3>Il puzzle solidale<\/h3>\n<p>La\u00a0<strong><a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/bomboniera\/bomboniera-adozione-a-distanza\/\">Bomboniera Solidale Adozione a Distanza\u00a0<\/a><\/strong>\u00e8 infatti un\u00a0<strong>puzzle solidale<\/strong>, che assicurer\u00e0\u00a0almeno un anno di\u00a0<strong>Adozione a Distanza<\/strong>\u00a0ai bambini abbandonati in un orfanotrofio in Africa o Bolivia, o ai bambini vittime della guerra in Ucraina.<br \/>\nSecondo il numero di invitati \u00e8 possibile scegliere fra\u00a0tre soluzioni:<\/p>\n<ol>\n<li>48 tessere, per sostenere il progetto scelto per 1 anno (48 bomboniere);<\/li>\n<li>96 tessere per sostenere il progetto scelto per 2 anni (96 bomboniere);<\/li>\n<li>192 tessere per sostenere il progetto scelto per 3 anni (192 bomboniere).<\/li>\n<\/ol>\n<p>Ciascun inviato ricever\u00e0 una bomboniera contenente una tessera, unica ed esclusiva, del puzzle scelto applicata su un grazioso cartoncino che riporta l\u2019immagine intera, una frase augurale, la descrizione del progetto sostenuto, la data dell\u2019evento e il nome degli sposi.<\/p>\n<h3>Il servizio di confezionamento<\/h3>\n<p>\u00c8 possibile inoltre richiedere anche il servizio di confezionamento e aggiungere quindi il sacchettino con i confetti e il nastro del colore preferito tra quelli proposti.<br \/>\nScegliendo la\u00a0<a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/bomboniera\/bomboniera-adozione-a-distanza\/\"><strong>Bomboniera Adozione a Distanza<\/strong><\/a><strong>,<\/strong>\u00a0si diventa a tutti gli effetti un\u00a0<strong>Sostenitore a Distanza di Ai.Bi.<\/strong>\u00a0e si potranno seguire direttamente le attivit\u00e0 di progetto realizzate e ricevere informazioni periodiche e aggiornate.<\/p>\n<h3>Un contributo ai progetti di Cooperazione Internazionale<\/h3>\n<p>Questa scelta contribuisce a realizzare concretamente i\u00a0<strong>progetti di cooperazione<\/strong>\u00a0che l\u2019associazione attiva nel mondo, facendo s\u00ec che il\u00a0<strong>proprio giorno speciale non sia solo un momento di gioia privata<\/strong>, ma un\u2019occasione per aiutare i bambini abbandonati e condividere con ogni invitato una scelta sentita e pensata in cui ciascuno possa sentirsi partecipe e possa, perch\u00e9 no, seguire l\u2019esempio di solidariet\u00e0.<br \/>\nLe\u00a0<strong>bomboniere solidali<\/strong>\u00a0sono tutte disponibili sulla\u00a0<a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/collezione\/matrimonio\/\"><strong>pagina dedicata del sito\u00a0<\/strong><\/a>e si possono richiedere a fronte di una donazione minima che, come tutte le donazioni ad Ai.Bi., gode delle agevolazioni fiscali previste per le Onlus e le ONG.<\/p>\n<h3>Informazioni<\/h3>\n<p>Per qualsiasi ulteriore informazione puoi contattarci al n.\u00a002.98822359\u00a0oppure via mail all\u2019indirizzo\u00a0<a href=\"mailto:bomboniere@aibi.it\"><strong>bomboniere@aibi.it<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perch&eacute; regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar&agrave; non solo apprezzato, ma a lungo ricordato dagli invitati<\/p>\n","protected":false},"author":133,"featured_media":223140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[914],"class_list":["post-223139","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bomboniere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Matrimonio solidale:\u00a0il \u201cS\u00ec\u201d che aiuta i bambini abbandonati<\/title>\n<meta name=\"description\" content=\"Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0\" \/>\n<meta property=\"og:description\" content=\"Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-13T05:40:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T12:09:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Bomboniere-Sad-matrimonio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0\",\"datePublished\":\"2024-06-13T05:40:53+00:00\",\"dateModified\":\"2024-06-17T12:09:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/\"},\"wordCount\":588,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Bomboniere-Sad-matrimonio.jpg\",\"keywords\":[\"bomboniere\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/\",\"name\":\"Matrimonio solidale:\u00a0il \u201cS\u00ec\u201d che aiuta i bambini abbandonati\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Bomboniere-Sad-matrimonio.jpg\",\"datePublished\":\"2024-06-13T05:40:53+00:00\",\"dateModified\":\"2024-06-17T12:09:48+00:00\",\"description\":\"Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Bomboniere-Sad-matrimonio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/Bomboniere-Sad-matrimonio.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/matrimonio-solidale-aiutare-bambini-abbandonati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Matrimonio solidale:\u00a0il \u201cS\u00ec\u201d che aiuta i bambini abbandonati","description":"Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/","og_locale":"it_IT","og_type":"article","og_title":"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0","og_description":"Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati","og_url":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-06-13T05:40:53+00:00","article_modified_time":"2024-06-17T12:09:48+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Bomboniere-Sad-matrimonio.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0","datePublished":"2024-06-13T05:40:53+00:00","dateModified":"2024-06-17T12:09:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/"},"wordCount":588,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Bomboniere-Sad-matrimonio.jpg","keywords":["bomboniere"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/","url":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/","name":"Matrimonio solidale:\u00a0il \u201cS\u00ec\u201d che aiuta i bambini abbandonati","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Bomboniere-Sad-matrimonio.jpg","datePublished":"2024-06-13T05:40:53+00:00","dateModified":"2024-06-17T12:09:48+00:00","description":"Perch\u00e9 regalare una bomboniera solidale di Ai.Bi. per il matrimonio? Un dono unico ed esclusivo che sar\u00e0 non solo apprezzato, ma a lungo ricordato dagli invitati","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Bomboniere-Sad-matrimonio.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/Bomboniere-Sad-matrimonio.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/matrimonio-solidale-aiutare-bambini-abbandonati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Matrimonio solidale:\u00a0quando il \u201cS\u00ec, lo voglio\u201d significa anche aiutare i bambini abbandonati\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:58:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/223139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=223139"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/223139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/223140"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=223139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=223139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=223139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}