﻿


{"id":223633,"date":"2024-07-05T07:30:48","date_gmt":"2024-07-05T05:30:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=223633"},"modified":"2024-09-04T11:49:54","modified_gmt":"2024-09-04T09:49:54","slug":"ghana-prince-rabbia-dolore-abbandono","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/","title":{"rendered":"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono"},"content":{"rendered":"<h2>Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via<br \/>\n<!--more--><\/h2>\n<p><strong>Prince<\/strong>, un bambino di 12 anni che ne compir\u00e0 13 a settembre, porta nel cuore il <strong>peso di un&#8217;infanzia interrotta<\/strong>.<br \/>\nLa sua storia \u00e8 quella di un abbandono improvviso: lasciato solo al mercato Adabraka di Accra dalla madre, dopo che lei gli aveva chiesto di fare degli acquisti.<br \/>\nDopo aver seguito il compito, ha cercato sua mamma ma lei era sparita.<br \/>\nLa polizia lo ha trovato e affidato alle cure della Domestic Violence and Victims Support Unit del Ghana Police Service. Nella stessa giornata \u00e8 stato trasferito all&#8217;orfanotrofio\u00a0<strong>Royal Seed Home<\/strong>, dove ora riceve protezione e affetto, e dove pu\u00f2 frequentare una scuola.<br \/>\nIl bambino ricorda di avere\u00a0<strong>sei fratelli<\/strong>, anche se gli \u00e8 rimasto nella memoria il nome di uno solo di loro. La madre \u00e8 ancora introvabile, ma il desiderio di Prince di riunirsi con la sua famiglia rimane forte.<br \/>\nAll&#8217;orfanotrofio, Prince ha mostrato segni di rabbia, naturale reazione al suo dolore, ma ha anche una grande voglia di comunicare e condividere.<\/p>\n<h3>Adotta a distanza un bambino ancora in attesa<\/h3>\n<p>Adottare a Distanza \u00e8 un gesto <strong>meraviglioso di vicinanza e sostegno<\/strong> verso un bambino in grave difficolt\u00e0 familiare. Con <strong>50 euro al mese<\/strong> potrai garantire al minore la possibilit\u00e0 di crescere serenamente e di studiare. Riceverai la sua foto e potrai, se lo desideri, intraprendere con lui uno scambio di corrispondenza, tenendoti informato sui suoi progressi e sulle sue necessit\u00e0, relazionandoti direttamente con i nostri operatori presenti nel Paese per avere aggiornamenti o, qualora lo desiderassi, inviare pensierini \u201cextra\u201d nei momenti importanti della sua vita, come nel giorno del suo compleanno.<br \/>\nPensaci. Il tuo aiuto \u00e8 davvero prezioso.<\/p>\n<h6>Quella che vedi in copertina non \u00e8 la foto reale di Prince. Per motivi di privacy non possiamo mostrarla al pubblico. L\u2019immagine \u00e8 stata generata con l\u2019Intelligenza Artificiale.<\/h6>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza un bambino come Prince<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un&rsquo;Adozione a Distanza potrai contribuire a restituirgli la gioia dell&rsquo;infanzia che rabbia e tristezza gli hanno portata via<\/p>\n","protected":false},"author":133,"featured_media":224595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[261],"tags":[511],"class_list":["post-223633","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozioni-a-distanza-realizzate","tag-ghana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana. Prince vive la rabbia e il dolore dell\u2019abbandono<\/title>\n<meta name=\"description\" content=\"Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono\" \/>\n<meta property=\"og:description\" content=\"Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T05:30:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T09:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/07\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono\",\"datePublished\":\"2024-07-05T05:30:48+00:00\",\"dateModified\":\"2024-09-04T09:49:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/\"},\"wordCount\":363,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/07\\\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg\",\"keywords\":[\"Ghana\"],\"articleSection\":[\"Adozioni a Distanza Realizzate\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/\",\"name\":\"Ghana. Prince vive la rabbia e il dolore dell\u2019abbandono\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/07\\\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg\",\"datePublished\":\"2024-07-05T05:30:48+00:00\",\"dateModified\":\"2024-09-04T09:49:54+00:00\",\"description\":\"Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/07\\\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/07\\\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-prince-rabbia-dolore-abbandono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozioni a Distanza Realizzate\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozioni-a-distanza-realizzate\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana. Prince vive la rabbia e il dolore dell\u2019abbandono","description":"Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono","og_description":"Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via","og_url":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-07-05T05:30:48+00:00","article_modified_time":"2024-09-04T09:49:54+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/07\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono","datePublished":"2024-07-05T05:30:48+00:00","dateModified":"2024-09-04T09:49:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/"},"wordCount":363,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/07\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg","keywords":["Ghana"],"articleSection":["Adozioni a Distanza Realizzate"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/","url":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/","name":"Ghana. Prince vive la rabbia e il dolore dell\u2019abbandono","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/07\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg","datePublished":"2024-07-05T05:30:48+00:00","dateModified":"2024-09-04T09:49:54+00:00","description":"Prince, 12 anni, afferma di avere 6 fratelli ma di ricordare solo un nome. Con un\u2019Adozione a Distanza potrai contribuire a restituirgli la gioia dell\u2019infanzia che rabbia e tristezza gli hanno portata via","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/07\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/07\/Appelli-Adozione-a-Distanza-Realizzata-Ghana-Prince.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-prince-rabbia-dolore-abbandono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozioni a Distanza Realizzate","item":"https:\/\/www.aibi.it\/ita\/category\/adozioni-a-distanza-realizzate\/"},{"@type":"ListItem","position":3,"name":"Ghana. Abbandonato dalla madre al mercato di Accra, ora, Prince vive la rabbia e il dolore dell\u2019abbandono"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:04:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/223633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=223633"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/223633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/224595"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=223633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=223633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=223633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}