﻿


{"id":224215,"date":"2024-08-02T08:00:45","date_gmt":"2024-08-02T06:00:45","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=224215"},"modified":"2024-08-01T16:16:22","modified_gmt":"2024-08-01T14:16:22","slug":"burundi-educazione-sostegno-bambini-orfanotrofi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/","title":{"rendered":"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura"},"content":{"rendered":"<h2>Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline<\/h2>\n<p><!--more--><\/p>\n<p>Attraverso il progetto finanziato dalla <strong>CAI, SPEM Sosenere l&#8217;istruzione, la protezione e gli spostamenti dei bambini vulnerabili in Africa orientale<\/strong>,\u00a0\u00a0Ai.Bi. offre istruzione e protezione a 410 bambini vulnerabili del\u00a0<strong>Burundi<\/strong>, in partenariato con l\u2019Ong locale,\u00a0<strong>UCBUM<\/strong>.<\/p>\n<h3>Nel quartiere di Buterere, una delle aree pi\u00f9 povere e abbandonate della citt\u00e0<\/h3>\n<p>UCBUM svolge attivit\u00e0 nel quartiere di Buterere, situato nella zona nord di Bujumbura, non distante dall\u2019aeroporto, una delle aree pi\u00f9 povere, insicure e abbandonate della citt\u00e0. La popolazione del quartiere, composta da minoranze etniche e sfollati sia interni sia dalla Repubblica Democratica del Congo, \u00e8 senza occupazione e cerca di guadagnarsi da vivere rovistando nella discarica locale. La spazzatura forma vere e proprie colline, e la popolazione cerca di recuperare qualsiasi cosa possa essere riciclata, oltre a residui di carbone. La quantit\u00e0 di rifiuti aumenta quotidianamente, con molti camion che scaricano immondizia in vari punti del quartiere, trasformandolo in una enorme discarica a cielo aperto.<\/p>\n<h3>I tre orfanotrofi<\/h3>\n<p>Il progetto si rivolge in particolare a tre orfanotrofi:<\/p>\n<ul>\n<li>Il centro Ruhuka Kibondo, gestito direttamente da UCBUM, che coinvolge 60 beneficiari diretti.<\/li>\n<li>Il centro Burundi bwa Uno Musi, gestito direttamente da UCBUM, che coinvolge 150 beneficiari diretti.<\/li>\n<li>Il centro Girimbabazi Tujane, nell\u2019ambito di una iniziativa supportata da UCBUM per la minoranza Twa (pigmei), che coinvolge 200 beneficiari diretti.<\/li>\n<\/ul>\n<p>I due orfanotrofi gestiti da UCBUM offrono accoglienza giornaliera ai minori del quartiere di Buterere, svolgendo attivit\u00e0 nutrizionali, educative, psicologiche, sociali, ricreative e di prima assistenza sanitaria. Offrono anche accoglienza temporanea, inclusa quella notturna, per minori in difficolt\u00e0 per malattia o abbandono.<\/p>\n<h3>I bambini aiutati<\/h3>\n<p>Il sostegno educativo di\u00a0<strong>210 minori<\/strong>\u00a0seguiti da UCBUM si \u00e8 concretizzato con l\u2019acquisto di materiale scolastico, vestiario e scarpe per i bambini delle scuole primaria e dell\u2019infanzia. Per la scuola della minoranza Twa, il sostegno \u00e8 stato garantito a\u00a0<strong>200 minori<\/strong>\u00a0con l\u2019acquisto di materiale scolastico.<br \/>\nAi minori beneficiari \u00e8 garantita una supervisione attraverso attivit\u00e0 ludico-ricreative e socio-educative, che comprendono la creazione di gruppi di ascolto e l\u2019approfondimento di temi utili al loro sviluppo cognitivo, sociale e comportamentale. Tra le attivit\u00e0 pi\u00f9 apprezzate dai ragazzi tra i 7 e i 17 anni, vi \u00e8 stata quella di elettronica, culminata nella costruzione di un semaforo.<br \/>\nGli agenti sociali si occupano anche del follow-up scolastico attraverso visite alle scuole per monitorare il comportamento dei minori, oltre che di sostegno psicosociale e visite a domicilio nei casi in cui \u00e8 necessario un trattamento. I gruppi di ascolto e discussione hanno aiutato i minori a riflettere sui propri comportamenti e a non considerare esempi da seguire quelli scorretti, come rubare o litigare.<br \/>\nTutti i minori dei tre centri hanno beneficiato dell\u2019acquisto di alimenti e del sostegno sanitario, inclusi medicinali e visite mediche. Infine, i minori accolti nei due centri gestiti da UCBUM hanno beneficiato dell\u2019acquisto di tre letti e tre materassi nuovi per l\u2019alloggio temporaneo e dell\u2019allestimento delle rispettive biblioteche, molto frequentate, con scaffali, sedie e libri.<\/p>\n<h3>Africa. Emergenza Abbandono<\/h3>\n<p>Ai.Bi. ha lanciato, nell\u2019Africa Sub-Sahariana, una campagna regionale di contrasto all\u2019abbandono che coinvolge, oltre al Burundi, altri 3 paesi, nei quali l\u2019emergenza abbandono \u00e8 drammatica: la Repubblica Democratica del Congo, Ghana e Repubblica del Congo (Congo Brazaville).<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*224082-start*\/\n#btnsx-224082{margin-top:10px;margin-bottom:10px;margin-left:0px;margin-right:0px;padding-top:17px;padding-bottom:17px;padding-left:12px;padding-right:12px;}\n#btnsx-224082 .btnsx-text-primary{text-transform:capitalize;font-size:18px;line-height:18px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-224082:hover .btnsx-text-primary{color:#fe0000;}\n#btnsx-224082{background-color:#fe0000!important;}\n#btnsx-224082:hover{background-color:#ffffff!important;}\n#btnsx-224082{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-224082:hover{border-top-width:1px;border-bottom-width:1px;border-left-width:1px;border-right-width:1px;border-style:solid;border-color:#fe0000;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-224082{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-224082:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*224082-end*\/\n<\/style><div id=\"btnsx-224082-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-224082-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/emergenza-burundi\/?act=cplt&amp;origine=button-in-article\" id=\"btnsx-224082\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">DONA ORA Emergenza Burundi<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline<\/p>\n","protected":false},"author":133,"featured_media":224219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1091,1104,1097],"class_list":["post-224215","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-burundi","tag-emergenza-abbandono","tag-spem"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi<\/title>\n<meta name=\"description\" content=\"Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura\" \/>\n<meta property=\"og:description\" content=\"Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T06:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/Burundi-Emergenza-Abbandno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura\",\"datePublished\":\"2024-08-02T06:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/Burundi-Emergenza-Abbandno.jpg\",\"keywords\":[\"Burundi\",\"Emergenza abbandono\",\"Kenya - SPEM\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/\",\"name\":\"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/Burundi-Emergenza-Abbandno.jpg\",\"datePublished\":\"2024-08-02T06:00:45+00:00\",\"description\":\"Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/Burundi-Emergenza-Abbandno.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/Burundi-Emergenza-Abbandno.jpg\",\"width\":1350,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/burundi-educazione-sostegno-bambini-orfanotrofi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi","description":"Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/","og_locale":"it_IT","og_type":"article","og_title":"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura","og_description":"Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline","og_url":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-08-02T06:00:45+00:00","og_image":[{"width":1350,"height":709,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/Burundi-Emergenza-Abbandno.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura","datePublished":"2024-08-02T06:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/"},"wordCount":580,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/Burundi-Emergenza-Abbandno.jpg","keywords":["Burundi","Emergenza abbandono","Kenya - SPEM"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/","url":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/","name":"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/Burundi-Emergenza-Abbandno.jpg","datePublished":"2024-08-02T06:00:45+00:00","description":"Sono i bambini ospitati in tre centri seguiti da Ai.Bi. e dal suo partner locale UCBUM, situati nel quartiere Buterere, dove la popolazione, bambini compresi, cerca di procurarsi da vivere rovistando nelle discariche della spazzatura che formano vere e proprie colline","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/Burundi-Emergenza-Abbandno.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/Burundi-Emergenza-Abbandno.jpg","width":1350,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/burundi-educazione-sostegno-bambini-orfanotrofi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Burundi. Educazione e sostegno per 410 bambini degli orfanotrofi di Bujumbura"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:00:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/224215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=224215"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/224215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/224219"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=224215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=224215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=224215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}