﻿


{"id":224485,"date":"2024-08-26T08:00:23","date_gmt":"2024-08-26T06:00:23","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=224485"},"modified":"2024-08-30T08:25:37","modified_gmt":"2024-08-30T06:25:37","slug":"perdono-abbandono-scelta-dono-amore","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/","title":{"rendered":"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore"},"content":{"rendered":"<h2>Il 31\u00b0 Incontro nazionale di Ai.Bi. Amici dei Bambini ETS e l\u2019Associazione La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema perdono all\u2019interno delle relazioni familiari, con una riflessione del prof. Leonardo Trione e un laboratorio esperienziale per le famiglie<\/h2>\n<p><!--more--><\/p>\n<p>Ufficialmente <a href=\"https:\/\/www.aibi.it\/ita\/chiamato-nome-figlio-chiama-incontro-nazionale-aibi-lps\/\">iniziato sabato 24 agosto<\/a>, con la presentazione del programma e la festa di benvenuto, e proseguito con l\u2019Assemblea plenaria e la santa messa di domenica 25 celebrata da <strong>S.E. Mons. Roberto Campiotti<\/strong>, il 31\u00b0 <strong>Incontro <\/strong>nazionale di Ai.Bi. e dell\u2019Associazione La Pietra Scartata \u201c<strong>Chiamato per nome, un figlio ci chiama\u201d<\/strong> entra nel cuore della riflessione proposta per questa edizione con la giornata di luned\u00ec 26 agosto.<br \/>\nIl programma \u00e8 incentrato sul tema: \u201c<strong>Il Perdono: scelta e dono d\u2019amore<\/strong>\u201d, titolo dell\u2019incontro proposto durante la mattinata e tenuto da <strong>Leonardo Trione<\/strong>, laureato in psicologia clinica e scienze religiose, psicologo clinico, docente, counsellor e mediatore familiare, sposato e padre di 5 figli. Proprio con la moglie Mariella, Trione ha fondato la Comunit\u00e0 <strong>Arca dell\u2019Alleanza<\/strong> e da circa 20 anni \u00e8 impegnato nell\u2019ascolto delle coppie in crisi, nella promozione di corsi di formazione per fidanzati e sposi e nella diffusione della cultura dell\u2019affido e dell\u2019adozione.<\/p>\n<h3>L\u2019esperienza del perdono all\u2019interno dei rapporti familiari<\/h3>\n<p>La riflessione proposta dal prof. Trione <strong>traccia i confini dell\u2019esperienza del perdono all\u2019interno delle mura domestiche<\/strong>, dove diventa una vera e propria <strong>scuola di formazione alla vita sociale<\/strong>.<br \/>\nPartendo dal presupposto che nessun rapporto familiare pu\u00f2 essere perfetto e, dunque, il conflitto \u00e8 inevitabile, proprio il contesto della famiglia diventa il primo luogo di <strong>confronto quotidiano con l\u2019altro diverso da noi<\/strong>. Il luogo, dunque, dove pi\u00f9 che in ogni altro possiamo coltivare la <strong>forza rigenerante del perdono<\/strong>.<br \/>\nIl prof. Trione spiega come \u00e8 proprio l\u2019esperienza del perdono a permettere di costruire e rinsaldare i rapporti familiari, dove <strong>per-donare pu\u00f2 essere una risposta concreta per vivere in armonia con se stessi e con gli altri<\/strong> componenti della nostra famiglia, sviluppando sempre pi\u00f9 la nostra capacit\u00e0 di amare.<\/p>\n<h3>Laboratorio esperienziale sul perdono<\/h3>\n<p>Questa visione del perdono \u201cincarnata\u201d all\u2019interno della vita di una famiglia verr\u00e0 poi ulteriormente analizzata e discussa all\u2019interno del <strong>laboratorio esperienziale<\/strong> che, coordinato sempre dal prof. Trione, avr\u00e0 luogo nel pomeriggio di luned\u00ec 26 agosto.<br \/>\nPartendo, come detto, dalla consapevolezza di come il perdono sia parte integrante di una storia d\u2019amore che si costruisce in ogni sistema familiare, il laboratorio si rivolge a genitori che vivono l&#8217;esperienza dell&#8217;affido o dell\u2019adozione con l\u2019obiettivo di <strong>aiutarli a vivere una vera e propria esperienza di perdono a livello coniugale e familiare<\/strong>.<br \/>\nLa finalit\u00e0 del laboratorio, che utilizza strumenti che prendono spunto dalla Parola di Dio e dalla psicologia (in particolare dalla Terapia Breve Strategica), \u00e8 quella di <strong>facilitare un processo di consapevolezza<\/strong> sulle ferite della vita; <strong>bloccare le tentate soluzioni disfunzionali<\/strong> che spesso alimentano rancori e sentimenti; <strong>sviluppare un percorso che facilita l\u2019esperienza del perdono<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 31&deg; Incontro nazionale di Ai.Bi. Amici dei Bambini ETS e l&rsquo;Associazione La Pietra Scartata prosegue con l&rsquo;incontro incentrato sul tema perdono all&rsquo;interno delle relazioni familiari, con una riflessione del prof. Leonardo Trione e un laboratorio esperienziale per le famiglie<\/p>\n","protected":false},"author":102,"featured_media":224486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[753,444],"class_list":["post-224485","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-aibi","tag-perdono"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore<\/title>\n<meta name=\"description\" content=\"Il 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema del perdono nell&#039;abbandono\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore\" \/>\n<meta property=\"og:description\" content=\"Il 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema del perdono nell&#039;abbandono\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-26T06:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T06:25:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-terra-perdono-nell-abbandono.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore\",\"datePublished\":\"2024-08-26T06:00:23+00:00\",\"dateModified\":\"2024-08-30T06:25:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/\"},\"wordCount\":495,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-terra-perdono-nell-abbandono.jpg\",\"keywords\":[\"aibi\",\"perdono\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/\",\"name\":\"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-terra-perdono-nell-abbandono.jpg\",\"datePublished\":\"2024-08-26T06:00:23+00:00\",\"dateModified\":\"2024-08-30T06:25:37+00:00\",\"description\":\"Il 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema del perdono nell'abbandono\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-terra-perdono-nell-abbandono.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-terra-perdono-nell-abbandono.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perdono-abbandono-scelta-dono-amore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore","description":"Il 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema del perdono nell'abbandono","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/","og_locale":"it_IT","og_type":"article","og_title":"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore","og_description":"Il 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema del perdono nell'abbandono","og_url":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-08-26T06:00:23+00:00","article_modified_time":"2024-08-30T06:25:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-terra-perdono-nell-abbandono.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore","datePublished":"2024-08-26T06:00:23+00:00","dateModified":"2024-08-30T06:25:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/"},"wordCount":495,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-terra-perdono-nell-abbandono.jpg","keywords":["aibi","perdono"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/","url":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/","name":"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-terra-perdono-nell-abbandono.jpg","datePublished":"2024-08-26T06:00:23+00:00","dateModified":"2024-08-30T06:25:37+00:00","description":"Il 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata prosegue con l\u2019incontro incentrato sul tema del perdono nell'abbandono","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-terra-perdono-nell-abbandono.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-terra-perdono-nell-abbandono.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Il Perdono nell\u2019abbandono: scelta e dono d\u2019amore"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:39:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/224485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=224485"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/224485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/224486"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=224485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=224485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=224485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}