﻿


{"id":224526,"date":"2024-08-27T08:00:51","date_gmt":"2024-08-27T06:00:51","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=224526"},"modified":"2024-08-30T08:26:32","modified_gmt":"2024-08-30T06:26:32","slug":"riscoperta-essere-sempre-stato-figlio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/","title":{"rendered":"La riscoperta di \u201cessere sempre stato figlio\u201d"},"content":{"rendered":"<h2>La riflessione condotta all\u2019interno del 31\u00b0 Incontro nazionale di Ai.Bi. e La Pietra Scartata giunge a un punto decisivo con il seminario di marted\u00ec 27 agosto: l\u2019abbandono viene riletto alla luce del grande progetto di Dio per ciascun uomo, che svela come l\u2019abbandono non sia che una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione, con la quale non si rinasce figlio n\u00e9 lo si ridiventa, perch\u00e9 lo si \u00e8 sempre stati!<\/h2>\n<p><!--more--><\/p>\n<p>Entra sempre pi\u00f9 nel vivo il 31\u00b0 <strong>Incontro <\/strong>nazionale di Ai.Bi. Amici dei Bambini ETS e l\u2019Associazione di fedeli \u201cPietra Scartata \u201c<strong>Chiamato per nome, un figlio ci chiama\u201d<\/strong>, in corso nella bella cittadina di <strong>Casino di Terra<\/strong> (PI); dal 24 al 29 agosto.<br \/>\nDopo aver visto i <a href=\"https:\/\/www.aibi.it\/ita\/chiamato-nome-figlio-chiama-incontro-nazionale-aibi-lps\/\">temi generali<\/a> e gli argomenti di fondo, e dopo l\u2019interessante riflessione e il laboratorio esperienziale <a href=\"https:\/\/www.aibi.it\/ita\/perdono-abbandono-scelta-dono-amore\/\">dedicati al perdono<\/a> svolti nella giornata di luned\u00ec, il programma dell\u2019incontro prosegue nella giornata di marted\u00ec 27 agosto con un importante seminario il cui titolo \u00e8 stato utilizzato per dare il nome a tutto l\u2019evento: \u201c<strong>Chiamato per nome, un figlio ci chiama<\/strong>\u201d.<\/p>\n<h3>Dalla promessa al compimento<\/h3>\n<p>Il seminario \u00e8 introdotto dal prof. <strong>Gianmario Fogliazza<\/strong>, con una relazione incentrata sulla \u201c<strong>sfida dell\u2019identit\u00e0 nell\u2019accoglienza famigliare tra promessa, abbandono, accoglienza, fallimenti e compimento<\/strong>\u201d.<br \/>\nSulla scia delle riflessioni gi\u00e0 svolte intorno ai temi della <strong>ricerca delle origini<\/strong> e del <strong>perdono<\/strong>, il percorso ci suggerisce una terza e ulteriore prospettiva per accostare nuovamente e meglio decifrare le incognite e le <strong>domande introdotte o insinuate da crisi relazionali, esistenziali o fallimenti autentici o presunti<\/strong>. Le tensioni vissute e le fragilit\u00e0 riscontrate nelle relazioni genitoriali e filiali, vengono osservate nel contesto di una pi\u00f9 complessiva questione che sempre pi\u00f9 appare rilevante anche nel quadro dei rapporti familiari e nelle trame delle relazioni interpersonali vissute con l\u2019ambizione di essere autentiche: <strong>l\u2019identit\u00e0 e il suo riconoscimento<\/strong>.<\/p>\n<h3>Sono sempre stato figlio!<\/h3>\n<p>Il programma prosegue con l\u2019intervento del Presidente Di Ai.Bi. <strong>Marco Griffini<\/strong>: \u201cSono sempre stato un figlio\u201d. Qui, la riflessione sull\u2019abbandono compie un ulteriore e decisivo passo in avanti, dimostrando come \u201cl\u2019essere figlio\u201d sia una <strong>condizione originaria di ciascun uomo e donna<\/strong> che viene al mondo. Una condizione inserita da Dio nel piano perfetto della creazione. Come, dunque, poter mettere insieme questa perfezione con l\u2019apparente \u201cnegazione\u201d vissuta da tutti i bambini abbandonati? La risposta la forniscono i figli stessi attraverso la <strong>straordinaria esperienza del perdono<\/strong>. Chi si ferma al \u201cprimo grido\u201d di Ges\u00f9 sulla Croce rimane come incatenato al passato. Chi, invece, come Ges\u00f9, \u201csi <strong>riconosce figlio nonostante il fallimento<\/strong> <strong>dell\u2019abbandono<\/strong>, scopre, vivendolo, di essere sempre stato un figlio\u201d!<br \/>\nScrive Griffini nel suo intervento<strong>: \u201c<\/strong>Nel figlio adottato, come in Ges\u00f9 Bambino Abbandonato e Risorto, la ferita dell\u2019abbandono ancora sanguina, ma ora \u00e8 <strong>illuminata da una nuova luce<\/strong>. L\u2019adozione da parte dei genitori rivela i contorni, forse non sempre ben definiti, del progetto di salvezza in corso e il perdono da parte del figlio &#8211; il vero protagonista &#8211; lo porta a compimento.<br \/>\n<strong>L\u2019adozione non ti fa rinascere figlio, ma ti svela una fondamentale verit\u00e0:<\/strong> <strong>tu sei sempre stato figlio, pensato e voluto da Dio; <\/strong>l\u2019abbandono ha annebbiato o sembra avere <strong>sospeso quella relazione<\/strong>, forse l\u2019unica del vero amore, la relazione filiale.<br \/>\n<strong>L<\/strong><strong>\u2019<\/strong><strong>adozione la <\/strong>&#8220;<strong>riannoda<\/strong>&#8220;, in maniera indissolubile, rivelando la verit\u00e0: <strong>tu sei sempre stato figlio\u201d<\/strong>.<br \/>\nA seguire, chiudono il seminario gli interventi del prof. <strong>Trione<\/strong> \u201cAccogliere, accompagnare e custodire un\u2019identit\u00e0 filiale\u201d e quello di S.E. <strong>Mons. Emidio Cipollone<\/strong>, \u201cEster e i capovolgimenti della storia: da un\u2019identit\u00e0 nascosta, poi svelata, la via per la salvezza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La riflessione condotta all&rsquo;interno del 31&deg; Incontro nazionale di Ai.Bi. e La Pietra Scartata giunge a un punto decisivo con il seminario di marted&igrave; 27 agosto: l&rsquo;abbandono viene riletto alla luce del grande progetto di Dio per ciascun uomo, che svela come l&rsquo;abbandono non sia che una &ldquo;sospensione&rdquo; della relazione [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":224528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[499,753,502],"class_list":["post-224526","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-abbandono","tag-aibi","tag-la-pietra-scartata"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La riscoperta di \u201cessere sempre stato figlio\u201d<\/title>\n<meta name=\"description\" content=\"L\u2019incontro nazionale di Ai.Bi. e LPS rilegge l\u2019abbandono alla luce del progetto di Dio: una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La riscoperta di \u201cessere sempre stato figlio\u201d\" \/>\n<meta property=\"og:description\" content=\"L\u2019incontro nazionale di Ai.Bi. e LPS rilegge l\u2019abbandono alla luce del progetto di Dio: una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T06:00:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T06:26:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-di-terra-abbandono-seconda-giornata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"La riscoperta di \u201cessere sempre stato figlio\u201d\",\"datePublished\":\"2024-08-27T06:00:51+00:00\",\"dateModified\":\"2024-08-30T06:26:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/\"},\"wordCount\":604,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-di-terra-abbandono-seconda-giornata.jpg\",\"keywords\":[\"abbandono\",\"aibi\",\"La Pietra Scartata\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/\",\"name\":\"La riscoperta di \u201cessere sempre stato figlio\u201d\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-di-terra-abbandono-seconda-giornata.jpg\",\"datePublished\":\"2024-08-27T06:00:51+00:00\",\"dateModified\":\"2024-08-30T06:26:32+00:00\",\"description\":\"L\u2019incontro nazionale di Ai.Bi. e LPS rilegge l\u2019abbandono alla luce del progetto di Dio: una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-di-terra-abbandono-seconda-giornata.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/08\\\/casino-di-terra-abbandono-seconda-giornata.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riscoperta-essere-sempre-stato-figlio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La riscoperta di \u201cessere sempre stato figlio\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La riscoperta di \u201cessere sempre stato figlio\u201d","description":"L\u2019incontro nazionale di Ai.Bi. e LPS rilegge l\u2019abbandono alla luce del progetto di Dio: una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/","og_locale":"it_IT","og_type":"article","og_title":"La riscoperta di \u201cessere sempre stato figlio\u201d","og_description":"L\u2019incontro nazionale di Ai.Bi. e LPS rilegge l\u2019abbandono alla luce del progetto di Dio: una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione","og_url":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-08-27T06:00:51+00:00","article_modified_time":"2024-08-30T06:26:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-di-terra-abbandono-seconda-giornata.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"La riscoperta di \u201cessere sempre stato figlio\u201d","datePublished":"2024-08-27T06:00:51+00:00","dateModified":"2024-08-30T06:26:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/"},"wordCount":604,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-di-terra-abbandono-seconda-giornata.jpg","keywords":["abbandono","aibi","La Pietra Scartata"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/","url":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/","name":"La riscoperta di \u201cessere sempre stato figlio\u201d","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-di-terra-abbandono-seconda-giornata.jpg","datePublished":"2024-08-27T06:00:51+00:00","dateModified":"2024-08-30T06:26:32+00:00","description":"L\u2019incontro nazionale di Ai.Bi. e LPS rilegge l\u2019abbandono alla luce del progetto di Dio: una \u201csospensione\u201d della relazione filiale, riallacciata per sempre dall\u2019adozione","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-di-terra-abbandono-seconda-giornata.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/08\/casino-di-terra-abbandono-seconda-giornata.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/riscoperta-essere-sempre-stato-figlio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"La riscoperta di \u201cessere sempre stato figlio\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:14:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/224526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=224526"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/224526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/224528"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=224526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=224526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=224526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}