﻿


{"id":225022,"date":"2024-09-18T07:40:06","date_gmt":"2024-09-18T05:40:06","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=225022"},"modified":"2024-10-03T10:06:18","modified_gmt":"2024-10-03T08:06:18","slug":"bolivia-bambini-nino-jesus-cassa-tesoro-passato","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/","title":{"rendered":"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato"},"content":{"rendered":"<h2>Donare ai bambini la loro storia, affinch\u00e9 rimangano anche nella nostra. La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto, grazie al progetto &#8220;Sostieni a distanza i bambini di un orfanotrofio&#8221;<\/h2>\n<p><!--more--><\/p>\n<p>Dopo un lungo periodo d\u2019attesa, finalmente arriva per i bambini dell&#8217;orfanotrofio <strong>Ni\u00f1o Jes\u00fas<\/strong> il momento tanto desiderato: lasciare il centro per iniziare una nuova vita con i loro <strong>genitori adottivi<\/strong>. Tuttavia, la loro storia non comincia con l&#8217;adozione; grazie al progetto <strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong> hanno potuto vivere esperienze importanti, momenti che Amici dei Bambini cerca di preservare nella <em><strong>Cassa del tesoro<\/strong><\/em>.<\/p>\n<h3>La Cassa del tesoro<\/h3>\n<p>Questa cassa speciale contiene un libro chiamato <strong><em>Tejiendo mi historia<\/em><\/strong>, in cui vengono annotati gli episodi pi\u00f9 significativi della vita del bambino. Le educatrici scrivono cosa lo fa sorridere, cosa lo rende triste e cosa ama fare, insieme a dediche affettuose che lasciano i compagni e le persone che lo hanno accolto al suo arrivo. Nella cassa c\u2019\u00e8 anche un album fotografico, che raccoglie i momenti pi\u00f9 belli della sua permanenza al centro.<br \/>\nI vestiti e i giocattoli passano da un bambino all\u2019altro, ma la <em><strong>Cassa del tesoro<\/strong><\/em> \u00e8 qualcosa di unico, personale, un oggetto che appartiene solo al bambino. Durante il tempo passato nel centro, la cassa si riempie non solo di ricordi, ma anche di informazioni utili per i genitori adottivi: come ad esempio se il bambino preferisce dormire con una certa musica o se gli piace essere coccolato in un certo modo.<\/p>\n<h3>Conservare una traccia del loro passato<\/h3>\n<p>L\u2019obiettivo di questo progetto \u00e8 fare in modo che i bambini non perdano mai traccia della loro storia.<br \/>\nQualcuno una volta ha detto: \u201ctogliamo ai bambini la loro storia, poi noi li cancelliamo dalla nostra\u201d. Questo \u00e8 esattamente ci\u00f2 che <strong>Ai.Bi.<\/strong> vuole evitare.<\/p>\n<h3>L\u2019attesa di Estrella, Matias Alejandro e Jhunior<\/h3>\n<p>Negli orfanotrofi in Bolivia,\u00a0<strong>Estrella<\/strong>, <strong>Matias Alejandro <\/strong>e<strong> Jhunior <\/strong>stanno ancora aspettando qualcuno che\u00a0<strong>possa accompagnarle nel loro cammino di speranza e di emancipazione\u00a0<\/strong>attraverso un\u2019<strong>Adozione a Distanza.<\/strong><br \/>\nLeggi la storia di <strong><a href=\"https:\/\/www.aibi.it\/ita\/bolivia-estrella\/\">Estrella<\/a><\/strong>, quella di <strong><a href=\"https:\/\/www.aibi.it\/ita\/bolivia-matias-alejandro-aiuto\/\">Matias Alejandro<\/a><\/strong> e quella di\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/bolivia-jhunior-aiuto\/\">Jhunior<\/a><\/strong>.<\/p>\n<h3>Come aiutare i bambini abbandonati degli orfanotrofi in Bolivia?<\/h3>\n<p><strong>Puoi\u00a0<\/strong>contribuire alle attivit\u00e0 promosse da\u00a0Ai.Bi. con una donazione,\u00a0<strong>cliccando\u00a0<a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">qui<\/a><\/strong>.<br \/>\nSe vuoi\u00a0<strong>dare continuit\u00e0 al tuo aiuto, stando vicino\u00a0<\/strong>ogni giorno ai bambini degli orfanotrofi e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto \u201cAdotta a distanza i bambini di un orfanotrofio\u201d.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Bolivia\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Infine se vuoi creare con <strong>Estrella<\/strong>, <strong>Matias Alejandro <\/strong>o con<strong> Jhunior <\/strong>un rapporto unico ed esclusivo per accompagnarli attivamente nella loro crescita, puoi adottare a distanza uno di loro. Riceverai il suo dossier, potrai scrivergli, ricevere le sue foto e mandargli le tue, chiedere e ricevere aggiornamenti periodici, pensare a regali aggiuntivi per momenti particolari. E, perch\u00e9 no, andare anche a trovarlo.<br \/>\nPer richiedere informazioni sull\u2019Adozione a Distanza\u00a0<a href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a>.<br \/>\nE ricorda: come ogni donazione, anche\u00a0<strong>le Adozioni a Distanza\u00a0di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donare ai bambini la loro storia, affinch&eacute; rimangano anche nella nostra. La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto, grazie al progetto &ldquo;Sostieni a distanza i bambini di un orfanotrofio&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":225024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[646],"class_list":["post-225022","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-nino-jesus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro<\/title>\n<meta name=\"description\" content=\"La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato\" \/>\n<meta property=\"og:description\" content=\"La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-18T05:40:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T08:06:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Bolivia-Cassa-del-Tesoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato\",\"datePublished\":\"2024-09-18T05:40:06+00:00\",\"dateModified\":\"2024-10-03T08:06:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/\"},\"wordCount\":544,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Bolivia-Cassa-del-Tesoro.jpg\",\"keywords\":[\"Nino Jesus\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/\",\"name\":\"I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Bolivia-Cassa-del-Tesoro.jpg\",\"datePublished\":\"2024-09-18T05:40:06+00:00\",\"dateModified\":\"2024-10-03T08:06:18+00:00\",\"description\":\"La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Bolivia-Cassa-del-Tesoro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Bolivia-Cassa-del-Tesoro.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro","description":"La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato","og_description":"La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-09-18T05:40:06+00:00","article_modified_time":"2024-10-03T08:06:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Bolivia-Cassa-del-Tesoro.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato","datePublished":"2024-09-18T05:40:06+00:00","dateModified":"2024-10-03T08:06:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/"},"wordCount":544,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Bolivia-Cassa-del-Tesoro.jpg","keywords":["Nino Jesus"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/","name":"I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Bolivia-Cassa-del-Tesoro.jpg","datePublished":"2024-09-18T05:40:06+00:00","dateModified":"2024-10-03T08:06:18+00:00","description":"La Cassa del Tesoro racchiude i momenti importanti che i minori, una volta adottati, non dimentichino i tanti momenti importanti che hanno vissuto","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Bolivia-Cassa-del-Tesoro.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Bolivia-Cassa-del-Tesoro.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-bambini-nino-jesus-cassa-tesoro-passato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. I Bambini del Ni\u00f1o Jes\u00fas e la loro Cassa del Tesoro: un legame con il passato"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:59:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/225022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=225022"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/225022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/225024"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=225022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=225022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=225022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}