﻿{"id":22512,"date":"2011-05-16T15:07:55","date_gmt":"2011-05-16T14:07:55","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=22512"},"modified":"2011-05-16T15:13:47","modified_gmt":"2011-05-16T14:13:47","slug":"adozioni-internazionali-crescita-record-nel-lazio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/","title":{"rendered":"Adozioni internazionali: crescita record nel Lazio"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-22513\" style=\"margin: 10px;\" title=\"adozioni_lazio\" src=\"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg\" alt=\"adozioni internazionali lazio\" width=\"100\" height=\"100\" \/><\/a>Nel 2010, <strong>433 minori stranieri hanno trovato una famiglia che li ha accolti<\/strong> in Regione, 75 in pi\u00f9 del 2009.<br \/>\nIn media pi\u00f9 di uno ogni giorno, dato che fa conquistare al<strong> Lazio il secondo posto<\/strong> in classifica nazionale, <strong>preceduto solo dalla Lombardia con 794 adozioni<\/strong>.<\/p>\n<p>A certificarlo \u00e8 il <strong>Rapporto 2010 della Commissione per le Adozioni Internazionali<\/strong> che registra invece il primato nel Lazio di coppie che hanno deciso di adottare un bambino: lo scorso anno in 335 hanno avviato l\u2019iter autorizzativo.<br \/>\nAnche nel 2010, inoltre, <strong>la Colombia si conferma il primo paese di provenienza<\/strong> dei minori stranieri adottati (53), seguita dal <strong>Brasile<\/strong> (52), <strong>Ucraina<\/strong> (39), <strong>Vietnam<\/strong> (38) e dalla <strong>Federazione Russa<\/strong> (36).<br \/>\n<strong>Unica nota negativa<\/strong>, il crollo verticale dei decreti autorizzativi da parte del tribunale dei minori di Roma. Dopo l\u2019introduzione nell\u2019Aprile 2009 di un colloquio obbligatorio per la coppia che vuole adottare un bambino e complice anche le lungaggini burocratiche, questi ultimi sono passati dai 542 del 2008 ai 164 del 2010.<br \/>\nIntanto per\u00f2 <strong>il protocollo sottoscritto ad Aprile da Regione e Tribunale dei Minori<\/strong>, punta a <strong>semplificare le procedur<\/strong>e e ridurre i tempi di attesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel 2010, 433 minori stranieri hanno trovato una famiglia che li ha accolti in regione,\u00a075 in\u00a0pi\u00f9 del 2009.\u00a0In media pi\u00f9 di uno ogni giorno, dato che fa conquistare al <strong>Lazio il secondo posto in classifica nazionale<\/strong>, preceduto solo dalla Lombardia con 794 adozioni. <a href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/\"><strong>LEGGI TUTTO&#8230;<\/strong><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-22512","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni internazionali nel Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali: crescita record nel Lazio\" \/>\n<meta property=\"og:description\" content=\"Nel 2010, 433 minori stranieri hanno trovato una famiglia che li ha accolti in regione,\u00a075 in\u00a0pi\u00f9 del 2009.\u00a0In media pi\u00f9 di uno ogni giorno, dato che fa conquistare al Lazio il secondo posto in classifica nazionale, preceduto solo dalla Lombardia con 794 adozioni. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-16T14:07:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-05-16T14:13:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni internazionali: crescita record nel Lazio\",\"datePublished\":\"2011-05-16T14:07:55+00:00\",\"dateModified\":\"2011-05-16T14:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozioni_lazio.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/\",\"name\":\"Adozioni internazionali nel Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozioni_lazio.jpg\",\"datePublished\":\"2011-05-16T14:07:55+00:00\",\"dateModified\":\"2011-05-16T14:13:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozioni_lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozioni_lazio.jpg\",\"width\":100,\"height\":100,\"caption\":\"adozioni internazionali lazio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-crescita-record-nel-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali: crescita record nel Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni internazionali nel Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali: crescita record nel Lazio","og_description":"Nel 2010, 433 minori stranieri hanno trovato una famiglia che li ha accolti in regione,\u00a075 in\u00a0pi\u00f9 del 2009.\u00a0In media pi\u00f9 di uno ogni giorno, dato che fa conquistare al Lazio il secondo posto in classifica nazionale, preceduto solo dalla Lombardia con 794 adozioni. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-05-16T14:07:55+00:00","article_modified_time":"2011-05-16T14:13:47+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni internazionali: crescita record nel Lazio","datePublished":"2011-05-16T14:07:55+00:00","dateModified":"2011-05-16T14:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/"},"wordCount":179,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/","name":"Adozioni internazionali nel Lazio","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg","datePublished":"2011-05-16T14:07:55+00:00","dateModified":"2011-05-16T14:13:47+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozioni_lazio.jpg","width":100,"height":100,"caption":"adozioni internazionali lazio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-crescita-record-nel-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali: crescita record nel Lazio"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:10:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/22512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=22512"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/22512\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=22512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=22512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=22512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}