﻿


{"id":225213,"date":"2024-09-24T11:00:31","date_gmt":"2024-09-24T09:00:31","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=225213"},"modified":"2024-09-24T17:36:57","modified_gmt":"2024-09-24T15:36:57","slug":"assegno-unico-2024-maggiorazioni-ottobre","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/","title":{"rendered":"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre"},"content":{"rendered":"<h2>Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli<\/h2>\n<p><!--more--><\/p>\n<p>A partire da ottobre 2024, l&#8217;Assegno Unico familiare vedr\u00e0 un significativo incremento <span>per tutte le famiglie che ne hanno fatto richiesta, magari in seguito a una modifica del proprio stato di famiglia<\/span>. Gli aumenti potranno raggiungere fino a 100 euro per le famiglie che rispettano specifici requisiti, con l\u2019obiettivo di garantire un maggiore sostegno economico, soprattutto per quelle in situazioni di difficolt\u00e0, come nuclei con figli piccoli, disabili o gestiti da un solo genitore vedovo.<\/p>\n<h3>Le maggiorazioni dell\u2019Assegno Unico<\/h3>\n<p>L\u2019assegno base, calcolato in base all\u2019ISEE del nucleo familiare, <span>infatti, pu\u00f2 essere incrementato<\/span> da diverse maggiorazioni, a seconda della situazione specifica. Tra le principali si segnalano:<\/p>\n<ul>\n<li>Un aumento del 50% per ogni figlio con et\u00e0 inferiore a un anno.<\/li>\n<li>Maggiorazioni del 50% per ciascun figlio tra 1 e 3 anni, se il nucleo ha almeno tre figli e un ISEE pari o inferiore a 40mila euro.<\/li>\n<li>Un ulteriore incremento del 50% per famiglie con almeno quattro figli.<\/li>\n<li>Per i figli disabili, la maggiorazione sar\u00e0 proporzionata al grado di disabilit\u00e0.<\/li>\n<li>Le madri con meno di 21 anni riceveranno 20 euro aggiuntivi per ogni figlio.<\/li>\n<li>I genitori vedovi potranno beneficiare di un incremento dell\u2019assegno fino a cinque anni dall&#8217;evento luttuoso.<\/li>\n<\/ul>\n<h3>Una platea di beneficiari pi\u00f9 ampia<\/h3>\n<p><span>In questo modo si estender\u00e0 ancora di pi\u00f9 la platea dei beneficiari che, secondo le ultime comunicazioni dell&#8217;INPS, aggiornate a luglio 2024, conta<\/span> <strong><span>6.219.848 nuclei familiari<\/span><\/strong>, per un totale di<strong> 9.854.566 figli.<\/strong><\/p>\n<p><span>Nell&#8217;ampliamento delle categorie<\/span> <span>dei beneficiari, spicca l&#8217;inclusione di nuove categorie<\/span> di lavoratori e famiglie che finora erano escluse, come i genitori vedovi e il personale scolastico. In particolare:<\/p>\n<ul>\n<li>I genitori vedovi riceveranno un incremento di 32,40 euro mensili per ogni figlio, a condizione che il coniuge fosse deceduto entro cinque anni dalla richiesta e fosse impiegato al momento della morte.<\/li>\n<li>Il personale scolastico, tra cui docenti, personale amministrativo e ATA, assunto con l\u2019avvio del nuovo anno scolastico, avr\u00e0 diritto alla maggiorazione.<\/li>\n<\/ul>\n<h3>Come ottenere le maggiorazioni<\/h3>\n<p>Per accedere a questi nuovi aumenti, le famiglie devono presentare domanda tramite il sito dell\u2019INPS, utilizzando il servizio online apposito. In alternativa, si pu\u00f2 chiedere assistenza presso CAF o patronati. \u00c8 essenziale avere un ISEE aggiornato, poich\u00e9 l&#8217;importo dell&#8217;assegno dipende dalla situazione economica: minore \u00e8 l\u2019ISEE, maggiore sar\u00e0 il sostegno. Tuttavia, anche senza presentare l\u2019ISEE, si avr\u00e0 diritto a una quota minima di 57 euro per figlio.<\/p>\n<h3>Le date di pagamento di ottobre<\/h3>\n<p>Per chi gi\u00e0 riceve l\u2019assegno senza variazioni, l\u2019accredito avverr\u00e0 tra il 16 e il 18 ottobre 2024. Chi ha presentato nuove domande o richiesto modifiche vedr\u00e0 il pagamento tra il 26 e il 31 ottobre. Questo aggiornamento dell\u2019Assegno Unico si pone come un supporto fondamentale per molte famiglie, aumentando l\u2019equit\u00e0 e offrendo un aiuto economico a chi ne ha pi\u00f9 bisogno.<\/p>\n<p><strong>[Fonte: QuiFinanza]<\/strong><\/p>\n<p><strong>L\u2019Osservatorio statistico sull\u2019Assegno Unico<\/strong><\/p>\n<p>L&#8217;Osservatorio INPS ha pubblicato i dati relativi agli anni 2022 e 2023, confermando l\u2019importanza dell\u2019Assegno Unico. Nel solo 2024 sono stati erogati 11,5 miliardi di euro, che si aggiungono ai 18,2 miliardi del 2023 e ai 13,2 miliardi del 2022.<\/p>\n<p><span><span>\u00a0L&#8217;importo medio per figlio, comprensivo delle maggiorazioni, \u00e8 di 171 euro, variando da 57 euro per chi non presenta l&#8217;ISEE a 224 euro per chi rientra nella classe di ISEE minima (17.090,61 euro).<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli<\/p>\n","protected":false},"author":133,"featured_media":225214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[750],"class_list":["post-225213","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-assegno-unico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Assegno Unico 2024. Maggiorazioni in arrivo a ottobre<\/title>\n<meta name=\"description\" content=\"Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre\" \/>\n<meta property=\"og:description\" content=\"Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T09:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-24T15:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Assegno-unico-ottobre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre\",\"datePublished\":\"2024-09-24T09:00:31+00:00\",\"dateModified\":\"2024-09-24T15:36:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Assegno-unico-ottobre.jpg\",\"keywords\":[\"assegno unico\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/\",\"name\":\"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Assegno-unico-ottobre.jpg\",\"datePublished\":\"2024-09-24T09:00:31+00:00\",\"dateModified\":\"2024-09-24T15:36:57+00:00\",\"description\":\"Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Assegno-unico-ottobre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/09\\\/Assegno-unico-ottobre.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/assegno-unico-2024-maggiorazioni-ottobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre","description":"Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/","og_locale":"it_IT","og_type":"article","og_title":"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre","og_description":"Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli","og_url":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-09-24T09:00:31+00:00","article_modified_time":"2024-09-24T15:36:57+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Assegno-unico-ottobre.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre","datePublished":"2024-09-24T09:00:31+00:00","dateModified":"2024-09-24T15:36:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/"},"wordCount":560,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Assegno-unico-ottobre.jpg","keywords":["assegno unico"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/","url":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/","name":"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Assegno-unico-ottobre.jpg","datePublished":"2024-09-24T09:00:31+00:00","dateModified":"2024-09-24T15:36:57+00:00","description":"Aumenti fino a 100 euro per famiglie con figli a carico che abbiano fatto una nuova richiesta e nuovi sostegni per vedovi e lavoratori scolastici. Scopri i dettagli","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Assegno-unico-ottobre.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/09\/Assegno-unico-ottobre.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/assegno-unico-2024-maggiorazioni-ottobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Assegno Unico 2024. Maggiorazioni in arrivo a ottobre"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:58:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/225213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=225213"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/225213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/225214"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=225213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=225213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=225213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}