﻿


{"id":225425,"date":"2024-10-03T07:30:48","date_gmt":"2024-10-03T05:30:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=225425"},"modified":"2024-10-03T10:29:54","modified_gmt":"2024-10-03T08:29:54","slug":"bolivia-madre-muore-padre-abbandona-sei-figli","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/","title":{"rendered":"Bolivia. La madre muore e il padre abbandona i sei figli"},"content":{"rendered":"<h2>Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto &#8220;Sostieni a distanza i bambini di un orfanotrofio&#8221;, pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto<\/h2>\n<p><!--more--><\/p>\n<p>\u201cMio Dio, mio Dio, perch\u00e9 mi hai abbandonato?\u201d<br \/>\nQuesto grido risuona nelle nostre orecchie, ricordandoci il motivo per cui siamo qui, impegnati ogni giorno nelle adozioni e nella tutela dei minori abbandonati in diverse parti del mondo.<br \/>\nLo staff di <strong>Ai.Bi.<\/strong> in <strong>Bolivia<\/strong> racconta la realt\u00e0 dolorosa di quando un padre, spinto dalla disperazione, decide di affidare i propri figli a un orfanotrofio, nella speranza di garantire loro un futuro migliore.<\/p>\n<h3>Un limbo di attesa e speranza<\/h3>\n<p>L\u2019albergo transitorio <strong>Bicentenario<\/strong> \u00e8 un luogo di profonda tristezza, dove <strong>si incontrano bambini con un passato drammatico e un futuro incerto<\/strong>. \u00c8 una sorta di terra di mezzo: da un lato, storie di crudelt\u00e0 che non dovrebbero mai toccare l\u2019infanzia; dall\u2019altro, l\u2019incognita del domani, con la speranza che i servizi sociali possano restituire a questi bambini un futuro dignitoso. In questo limbo vengono accolti minori abbandonati, con l\u2019obiettivo di valutare il tipo di sostegno di cui hanno bisogno, sperando di farli tornare figli al pi\u00f9 presto.<\/p>\n<h3>Una storia tra tante<\/h3>\n<p>Una rappresentante di <em>Amici dei Bambini<\/em> racconta: \u201cQualche giorno fa sono arrivati sei fratelli, orfani di madre e abbandonati dal padre. La sorella maggiore si prendeva cura di loro, ma non sappiamo per quanto tempo fosse riuscita a farlo. Le loro condizioni erano allarmanti: una delle sorelle soffre di diabete e il suo stato di salute era molto compromesso. \u00c8 stata subito ricoverata nell\u2019Ospedale del Bambino, ma il sistema sanitario non poteva provvedere all\u2019insulina di cui aveva urgente bisogno. Fortunatamente, siamo riusciti a fornirla grazie al nostro intervento. Gli altri fratelli, invece, vivevano in condizioni igieniche disastrose e alcuni di loro necessitavano di cure mediche, che abbiamo potuto garantire, il tutto grazie ai sostenitori del progetto <strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong>.<\/p>\n<h3>Non tutte le storie hanno un lieto fine<\/h3>\n<p>Questa \u00e8 solo una delle tante vicende che attraversano questa fragile linea tra il Bene e il Male. Talvolta, dopo un periodo di attesa che varia da caso a caso, un minore viene dichiarato adottabile e pu\u00f2 entrare in una famiglia affidataria, o meglio, trovare una mamma e un pap\u00e0 definitivi.<br \/>\nAltri bambini, per\u00f2, non possono essere avviati all\u2019adozione per motivi legati alla loro famiglia d\u2019origine: anche se non pu\u00f2 occuparsi di loro, il legame di parentela non pu\u00f2 essere spezzato. In questi casi, il bambino inizia un lungo percorso di istituzionalizzazione fino alla maggiore et\u00e0, sperando che un giorno possa trovare la propria strada.<\/p>\n<h3>L\u2019impegno di Amici dei Bambini e il bisogno di sostegno<\/h3>\n<p>Lo staff di Ai.Bi. si prende cura di questi minori vittime di abbandono\u00a0, che spesso non hanno nessun altro a cui rivolgersi. L\u2019associazione si fa carico delle spese e garantisce un sostegno educativo, psicologico e sanitario, nei limiti concessi dalle autorit\u00e0 locali. Nonostante l&#8217;impegno incessante, ci si trova spesso di fronte a difficolt\u00e0 insormontabili: da soli non si pu\u00f2 fare abbastanza. \u00c8 qui che entra in gioco l\u2019importanza di un donatore, di un sostenitore che decida di accompagnare uno di questi bambini lungo il difficile cammino verso la maggiore et\u00e0. Grazie a questo sostegno, i piccoli possono sentire la vicinanza e l\u2019affetto di qualcuno che, anche se non pu\u00f2 sostituire una famiglia vera, offre loro una carezza, un sostegno costante.<\/p>\n<h3>L\u2019attesa di Estrella, Matias Alejandro e Jhunior<\/h3>\n<p>Negli orfanotrofi in Bolivia,\u00a0<strong>Estrella<\/strong>, <strong>Matias Alejandro <\/strong>e<strong> Jhunior <\/strong>stanno ancora aspettando qualcuno che\u00a0<strong>possa accompagnarle nel loro cammino di speranza e di emancipazione\u00a0<\/strong>attraverso un\u2019<strong>Adozione a Distanza.<\/strong><br \/>\nLeggi la storia di <strong><a href=\"https:\/\/www.aibi.it\/ita\/bolivia-estrella\/\">Estrella<\/a><\/strong>, quella di <strong><a href=\"https:\/\/www.aibi.it\/ita\/bolivia-matias-alejandro-aiuto\/\">Matias Alejandro<\/a><\/strong> e quella di\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/bolivia-jhunior-aiuto\/\">Jhunior<\/a><\/strong>.<\/p>\n<h3>Come aiutare i bambini abbandonati degli orfanotrofi in Bolivia?<\/h3>\n<p><strong>Puoi\u00a0<\/strong>contribuire alle attivit\u00e0 promosse da\u00a0Ai.Bi. con una donazione,\u00a0<strong>cliccando\u00a0<a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">qui<\/a><\/strong>.<br \/>\nSe vuoi\u00a0<strong>dare continuit\u00e0 al tuo aiuto, stando vicino\u00a0<\/strong>ogni giorno ai bambini degli orfanotrofi e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto \u201cAdotta a distanza i bambini di un orfanotrofio\u201d.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Bolivia\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Infine se vuoi creare con <strong>Estrella<\/strong>, <strong>Matias Alejandro <\/strong>o con<strong> Jhunior <\/strong>un rapporto unico ed esclusivo per accompagnarli attivamente nella loro crescita, puoi adottare a distanza uno di loro. Riceverai il suo dossier, potrai scrivergli, ricevere le sue foto e mandargli le tue, chiedere e ricevere aggiornamenti periodici, pensare a regali aggiuntivi per momenti particolari. E, perch\u00e9 no, andare anche a trovarlo.<br \/>\nPer richiedere informazioni sull\u2019Adozione a Distanza\u00a0<a href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a>.<br \/>\nE ricorda: come ogni donazione, anche\u00a0<strong>le Adozioni a Distanza\u00a0di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto &ldquo;Sostieni a distanza i bambini di un orfanotrofio&rdquo;, pu&ograve; compiere un piccolo miracolo: tentare di&nbsp;restituire un futuro a chi ha perso tutto<\/p>\n","protected":false},"author":133,"featured_media":225426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[480],"class_list":["post-225425","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-bolivia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. La madre muore e il padre abbandona i sei figli<\/title>\n<meta name=\"description\" content=\"Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto &quot;Sostieni a distanza i bambini di un orfanotrofio&quot;, pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. La madre muore e il padre abbandona i sei figli\" \/>\n<meta property=\"og:description\" content=\"Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto &quot;Sostieni a distanza i bambini di un orfanotrofio&quot;, pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T05:30:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T08:29:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/10\/Bolivia-adozione-a-distanza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Bolivia. La madre muore e il padre abbandona i sei figli\",\"datePublished\":\"2024-10-03T05:30:48+00:00\",\"dateModified\":\"2024-10-03T08:29:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/\"},\"wordCount\":802,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/10\\\/Bolivia-adozione-a-distanza.jpg\",\"keywords\":[\"Bolivia\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/\",\"name\":\"Bolivia. La madre muore e il padre abbandona i sei figli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/10\\\/Bolivia-adozione-a-distanza.jpg\",\"datePublished\":\"2024-10-03T05:30:48+00:00\",\"dateModified\":\"2024-10-03T08:29:54+00:00\",\"description\":\"Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto \\\"Sostieni a distanza i bambini di un orfanotrofio\\\", pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/10\\\/Bolivia-adozione-a-distanza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/10\\\/Bolivia-adozione-a-distanza.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-madre-muore-padre-abbandona-sei-figli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. La madre muore e il padre abbandona i sei figli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. La madre muore e il padre abbandona i sei figli","description":"Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto \"Sostieni a distanza i bambini di un orfanotrofio\", pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. La madre muore e il padre abbandona i sei figli","og_description":"Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto \"Sostieni a distanza i bambini di un orfanotrofio\", pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-10-03T05:30:48+00:00","article_modified_time":"2024-10-03T08:29:54+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/10\/Bolivia-adozione-a-distanza.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Bolivia. La madre muore e il padre abbandona i sei figli","datePublished":"2024-10-03T05:30:48+00:00","dateModified":"2024-10-03T08:29:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/"},"wordCount":802,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/10\/Bolivia-adozione-a-distanza.jpg","keywords":["Bolivia"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/","name":"Bolivia. La madre muore e il padre abbandona i sei figli","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/10\/Bolivia-adozione-a-distanza.jpg","datePublished":"2024-10-03T05:30:48+00:00","dateModified":"2024-10-03T08:29:54+00:00","description":"Nella desolante tristezza di una famiglia spezzata, Ai.Bi., grazie al progetto \"Sostieni a distanza i bambini di un orfanotrofio\", pu\u00f2 compiere un piccolo miracolo: tentare di\u00a0restituire un futuro a chi ha perso tutto","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/10\/Bolivia-adozione-a-distanza.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/10\/Bolivia-adozione-a-distanza.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-madre-muore-padre-abbandona-sei-figli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. La madre muore e il padre abbandona i sei figli"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/225425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=225425"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/225425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/225426"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=225425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=225425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=225425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}