﻿


{"id":227025,"date":"2024-12-21T07:50:54","date_gmt":"2024-12-21T06:50:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=227025"},"modified":"2024-12-17T17:58:01","modified_gmt":"2024-12-17T16:58:01","slug":"marocco-orfanatrofio-smail","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/","title":{"rendered":"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail"},"content":{"rendered":"<h2>Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA<!--more--><\/h2>\n<p>Il 24 ottobre \u00e8 stato un giorno importante per Smail, una bambina di dieci anni che ha trovato una nuova casa e un nuovo inizio in orfanotrofio.<br \/>\nSmail e suo fratello, che frequenta il quarto anno di scuola, hanno trovato rifugio in questa struttura accogliente.<br \/>\nLa perdita del padre avvenuta anni fa ha lasciato un grande vuoto nella vita di Smail e della sua famiglia. La madre, impegnata duramente come donna delle pulizie, lavora senza sosta per garantire un futuro ai suoi figli. Nonostante le difficolt\u00e0 economiche e emotive, Smail si considera fortunata per aver trovato un posto sicuro e pieno di calore presso l\u2019orfanotrofio APA.<\/p>\n<h3>Dentro il centro APA<\/h3>\n<p>Quando \u00e8 arrivata nella struttura, Smail era comprensibilmente spaventata e insicura. Tuttavia, grazie alla gentilezza e al supporto del personale, quei sentimenti si sono presto trasformati in serenit\u00e0. Per Smail, l\u2019orfanotrofio non \u00e8 solo un luogo dove vivere: \u00e8 diventata una vera e propria seconda famiglia. Gli operatori si prendono cura di ogni aspetto della sua vita quotidiana, offrendo supporto sia nello studio che nei momenti di svago. Il loro rapporto \u00e8 fondato sul rispetto reciproco e sull\u2019incoraggiamento costante, aiutandola a costruire una maggiore fiducia in s\u00e9 stessa.<\/p>\n<h3>Costruire nuovi rapporti<\/h3>\n<p>Un altro aspetto fondamentale della sua esperienza \u00e8 il legame con gli altri bambini. Nel centro, Smail ha trovato una comunit\u00e0 solidale, simile a una grande famiglia, in cui ognuno sostiene l\u2019altro, specialmente nei momenti difficili. Condividono momenti di gioco, studio e complicit\u00e0, creando ricordi preziosi che alleviano il peso delle sfide quotidiane.<\/p>\n<h3>Imparare a rispondere<\/h3>\n<p>Anche a scuola Smail ha incontrato delle difficolt\u00e0 iniziali. Le domande dei compagni sulla sua vita e sulle ragioni che l\u2019hanno portata in orfanotrofio la rendevano nervosa. Tuttavia, con il tempo, ha imparato a rispondere con sicurezza, capendo che la curiosit\u00e0 dei suoi compagni non nascondeva cattiveria, ma solo interesse. I rapporti con i suoi coetanei sono migliorati gradualmente e\u00a0oggi\u00a0Smail si diverte a giocare con loro al parco e a condividere momenti di studio e gioco.<br \/>\nLa sua insegnante, particolarmente attenta alla sua situazione, le offre un supporto prezioso, aiutandola a superare le difficolt\u00e0 che a volte le impediscono di concentrarsi. La presenza degli amici e dei compagni di classe rappresenta un importante punto di forza per Smail, che riesce cos\u00ec a sentirsi meno sola e pi\u00f9 motivata nello studio.<\/p>\n<h3><strong>L\u2019inizio di qualcosa di migliore<\/strong><\/h3>\n<p>L\u2019obiettivo di Smail \u00e8 chiaro: vuole diventare\u00a0<strong>una persona affidabile e dimostrare al mondo che le difficolt\u00e0 non segnano la fine<\/strong>, ma possono essere\u00a0<strong>l\u2019inizio di qualcosa di migliore<\/strong>. Il suo desiderio pi\u00f9 grande \u00e8 quello di aiutare sua madre e suo fratello, offrendo loro una vita migliore. Grazie al calore e al sostegno che riceve al centro e a scuola, Smail si sente determinata a trasformare questo sogno in realt\u00e0. La sua storia \u00e8 un esempio di resilienza e speranza, un promemoria di come l\u2019amore e il supporto possano fare la differenza nella vita di un bambino.<\/p>\n<h3>Un&#8217;Adozione a Distanza per i bambini degli orfanotrofi in Marocco<\/h3>\n<p>Anche tu puoi aiutare tanti minori abbandonati decidendo di aderire al progetto di Ai.Bi. con una donazione cliccando\u00a0<strong><a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">qui<\/a><\/strong>.<br \/>\nSe vuoi fare di pi\u00f9 e stare vicino ogni giorno ai bambini in orfanotrofio in Marocco e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto \u201cAdotta a distanza i bambini di un orfanotrofio\u201d.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Marocco\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Per richiedere informazioni sull\u2019Adozione a Distanza\u00a0<a href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a>.<br \/>\nE ricorda: come ogni donazione, anche le<strong>\u00a0Adozioni a Distanza di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto &ldquo;Adotta a Distanza i minori di un orfanotrofio&rdquo;, una seconda famiglia e la forza di inseguire i suoi sogni, all&rsquo;interno del centro APA<\/p>\n","protected":false},"author":133,"featured_media":227028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[838],"class_list":["post-227025","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-apa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marocco.\u00a0La storia di Smail<\/title>\n<meta name=\"description\" content=\"Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail\" \/>\n<meta property=\"og:description\" content=\"Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-21T06:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2024\/12\/Marocco-APA-Smail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail\",\"datePublished\":\"2024-12-21T06:50:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/\"},\"wordCount\":655,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/12\\\/Marocco-APA-Smail.jpg\",\"keywords\":[\"APA\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/\",\"name\":\"Marocco.\u00a0La storia di Smail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/12\\\/Marocco-APA-Smail.jpg\",\"datePublished\":\"2024-12-21T06:50:54+00:00\",\"description\":\"Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/12\\\/Marocco-APA-Smail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/12\\\/Marocco-APA-Smail.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-orfanatrofio-smail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marocco.\u00a0La storia di Smail","description":"Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/","og_locale":"it_IT","og_type":"article","og_title":"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail","og_description":"Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA","og_url":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2024-12-21T06:50:54+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2024\/12\/Marocco-APA-Smail.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail","datePublished":"2024-12-21T06:50:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/"},"wordCount":655,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/12\/Marocco-APA-Smail.jpg","keywords":["APA"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/","url":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/","name":"Marocco.\u00a0La storia di Smail","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/12\/Marocco-APA-Smail.jpg","datePublished":"2024-12-21T06:50:54+00:00","description":"Dopo aver affrontato la perdita e le sfide con coraggio, la piccola Smail ha scoperto, grazie al progetto \u201cAdotta a Distanza i minori di un orfanotrofio\u201d, una seconda famiglia e la forza di inseguire i suoi sogni, all\u2019interno del centro APA","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/12\/Marocco-APA-Smail.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/12\/Marocco-APA-Smail.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/marocco-orfanatrofio-smail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Marocco.\u00a0Iniziare a 10 anni una nuova vita\u00a0in orfanatrofio: la storia di Smail"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=227025"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/227028"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=227025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=227025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=227025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}