﻿


{"id":227499,"date":"2025-01-18T07:50:21","date_gmt":"2025-01-18T06:50:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=227499"},"modified":"2025-01-15T15:23:06","modified_gmt":"2025-01-15T14:23:06","slug":"aibiweek-settimana-eventi-scoprili-tutti","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/","title":{"rendered":"AibiWeek. Una settimana ricca di eventi: scoprili tutti"},"content":{"rendered":"<h2>Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia<\/h2>\n<p><!--more--><\/p>\n<h3>Marted\u00ec 21 gennaio<\/h3>\n<p><strong>Ai.Bi. sede di Mestre<\/strong><br \/>\n<strong>L\u2019incontro con l\u2019Adozione Internazionale (primo incontro informativo)<br \/>\nOn Line<br \/>\nOre 17<\/strong><br \/>\nAmici dei Bambini organizza incontri informativi di gruppo gratuiti, per le coppie che desiderano approfondire la conoscenza dell\u2019adozione internazionale, dell\u2019associazione e delle procedure di adozione. Gli incontri hanno una durata di 4 ore, sono condotti da un operatore di Amici dei Bambini e prevedono la testimonianza di una famiglia adottiva. La partecipazione all\u2019incontro di entrambi i coniugi \u00e8 obbligatoria per le coppie che intendono conferire mandato ad Ai.Bi. Sono aperti alle coppie che hanno concluso il percorso con i Servizi o gi\u00e0 in possesso del decreto di idoneit\u00e0.<br \/>\nPer informazioni e iscrizioni:\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/#incontri-informativi-adozione\"><strong>QUI<\/strong><\/a>.<\/p>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Informativo sull\u2019affido familiare \u2013 residenti in Lombardia<br \/>\nOre: 21<br \/>\n<\/strong>Quando una famiglia attraversa un momento di difficolt\u00e0 e non riesce a prendersi momentaneamente cura dei figli, i minori possono essere accolti per un periodo di tempo determinato in un\u2019altra famiglia, la famiglia accogliente. Chi pu\u00f2 fare affido? Che et\u00e0 bisogna avere? Quanto pu\u00f2 durare un affido? E che tipologie di affido esistono? Come funziona tutto il procedimento?<br \/>\nSe sei un single, una coppia o una famiglia con figli e sei interessata\/o a conoscere e approfondire il tema dell\u2019affido familiare, partecipa al nostro incontro informativo.<br \/>\nIncontro riservato ai soli residenti in Lombardia<br \/>\nL\u2019incontro informativo \u00e8 condotto da una famiglia affidataria di Ai.Bi. \u2013 Amici dei Bambini. Avrai modo di conoscere l\u2019accoglienza familiare temporanea grazie alla testimonianza diretta di chi vive quest\u2019esperienza.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-sullaffido-familiare-residenti-in-lombardia-2\/\"><strong>qui<\/strong><\/a>.<\/p>\n<h3>Mercoled\u00ec 22 gennaio<\/h3>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Primi passi nel mondo dell\u2019Adozione Internazionale<br \/>\nOre: 17<br \/>\n<\/strong>Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-primi-passi-nel-mondo-delladozione-internazionale-2\/\"><strong>qui<\/strong><\/a>.<\/p>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Informativo su come aprire una casa famiglia per minori<br \/>\nOre: 18.30<br \/>\n<\/strong>Il webinar informativo \u00e8 rivolto a chi vuole capire se approfondire la possibilit\u00e0 di aprire una propria casa famiglia per minori, acquisendo le prime informazioni di base.<br \/>\nNel webinar verranno approfondite le specificit\u00e0 che l\u2019inizio di un progetto familiare di questo genere comportano, verr\u00e0, in particolare, sottolineata la differenza con l\u2019istituto dell\u2019affido familiare. Tutto ci\u00f2 al fine di dare stimolo e maggiore consapevolezza all\u2019eventuale discernimento di coloro i quali partecipano al webinar.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-su-come-aprire-una-casa-famiglia-per-minori\/\"><strong>qui<\/strong><\/a>.<\/p>\n<h3>Sabato\u00a025 gennaio<\/h3>\n<p><strong>Aladin \u2013 Il Musical<br \/>\nTeatro Petrarca &#8211; Arezzo<br \/>\nOre: 17<br \/>\n<\/strong>Con Max Laudadio nel ruolo del genio, questa produzione speciale, ideata da Stefano D\u2019Orazio, si avvale delle musiche senza tempo di Roby Facchinetti, Dodi Battaglia e Red Canzian dei Pooh. Sotto la regia di Luca Cattaneo, la classica storia di Aladino si rinnova con l\u2019aggiunta di un \u201cquarto desiderio\u201d, che sorprende e dona una profondit\u00e0 inaspettata alla narrazione.<br \/>\nMaggiori informazioni,\u00a0<a href=\"https:\/\/www.compagniadellora.it\/aladin-il-musical-di-stefano-dorazio\/\"><strong>qui<\/strong><\/a>.<\/p>\n<p><strong>La Musica della Memoria<br \/>\n<\/strong><strong>Sala Athenaeum, Via Madonna degli Angeli 29, Barletta<br \/>\n<\/strong><strong>Ore: 18<br \/>\n<\/strong>Concerto benefico per Ai.Bi. Amici dei Bambini, con brani illustrati e suonati da Francesco Lomuscio.<br \/>\nUn concerto speciale, che unisce musica e solidariet\u00e0; arte e ricordi; storia da non dimenticare e futuro da costruire.<br \/>\nUn viaggio emozionante attraverso la memoria e le note, con l\u2019esecuzione di una serie di brani che sono stati scritti all\u2019interno dei campi di concentramento e di sterminio.<br \/>\nPartecipando, oltre a godere del concerto, sosterrai le bambine e i bambini vittime di abbandono e i progetti di Ai.Bi. Amici dei Bambini in Puglia, a contrasto della povert\u00e0 educativa e in aiuto delle famiglie in difficolt\u00e0.<br \/>\nMaggiori informazioni,\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/evento\/musica-memoria\/\"><strong>qui<\/strong><\/a>.<\/p>\n<p><strong>Aladin \u2013 Il Musical<br \/>\nTeatro Petrarca &#8211; Arezzo<br \/>\nOre: 21<br \/>\n<\/strong>Con Max Laudadio nel ruolo del genio, questa produzione speciale, ideata da Stefano D\u2019Orazio, si avvale delle musiche senza tempo di Roby Facchinetti, Dodi Battaglia e Red Canzian dei Pooh. Sotto la regia di Luca Cattaneo, la classica storia di Aladino si rinnova con l\u2019aggiunta di un \u201cquarto desiderio\u201d, che sorprende e dona una profondit\u00e0 inaspettata alla narrazione.<br \/>\nMaggiori informazioni,\u00a0<a href=\"https:\/\/www.compagniadellora.it\/aladin-il-musical-di-stefano-dorazio\/\"><strong>qui<\/strong><\/a>.<\/p>\n<h3>Domenica 26 gennaio<\/h3>\n<p><strong>Aladin \u2013 Il Musical<br \/>\nTeatro Europa \u2013 Aprilia<br \/>\nOre: 17<br \/>\n<\/strong>Con Max Laudadio nel ruolo del genio, questa produzione speciale, ideata da Stefano D\u2019Orazio, si avvale delle musiche senza tempo di Roby Facchinetti, Dodi Battaglia e Red Canzian dei Pooh. Sotto la regia di Luca Cattaneo, la classica storia di Aladino si rinnova con l\u2019aggiunta di un \u201cquarto desiderio\u201d, che sorprende e dona una profondit\u00e0 inaspettata alla narrazione.<br \/>\nMaggiori informazioni,\u00a0<a href=\"https:\/\/www.compagniadellora.it\/aladin-il-musical-di-stefano-dorazio\/\"><strong>qui<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia<\/p>\n","protected":false},"author":133,"featured_media":227500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[781],"class_list":["post-227499","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-aibiweek"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AibiWeek. Una settimana ricca di eventi: scoprili tutti<\/title>\n<meta name=\"description\" content=\"Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AibiWeek. Una settimana ricca di eventi: scoprili tutti\" \/>\n<meta property=\"og:description\" content=\"Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-18T06:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/AibiWeek-18-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"AibiWeek. Una settimana ricca di eventi: scoprili tutti\",\"datePublished\":\"2025-01-18T06:50:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/\"},\"wordCount\":798,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/AibiWeek-18-01.jpg\",\"keywords\":[\"AIBIweek\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/\",\"name\":\"AibiWeek. Una settimana ricca di eventi: scoprili tutti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/AibiWeek-18-01.jpg\",\"datePublished\":\"2025-01-18T06:50:21+00:00\",\"description\":\"Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/AibiWeek-18-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/AibiWeek-18-01.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-settimana-eventi-scoprili-tutti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AibiWeek. Una settimana ricca di eventi: scoprili tutti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AibiWeek. Una settimana ricca di eventi: scoprili tutti","description":"Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/","og_locale":"it_IT","og_type":"article","og_title":"AibiWeek. Una settimana ricca di eventi: scoprili tutti","og_description":"Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia","og_url":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-01-18T06:50:21+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/AibiWeek-18-01.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"AibiWeek. Una settimana ricca di eventi: scoprili tutti","datePublished":"2025-01-18T06:50:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/"},"wordCount":798,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/AibiWeek-18-01.jpg","keywords":["AIBIweek"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/","url":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/","name":"AibiWeek. Una settimana ricca di eventi: scoprili tutti","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/AibiWeek-18-01.jpg","datePublished":"2025-01-18T06:50:21+00:00","description":"Dal 20 al 26 gennaio, vi aspettano corsi online su Adozione Internazionale, Affido Familiare, il webinar informativo su come aprire una casa famiglia per minori oltre al concerto Musica della Memoria a Barletta e il musical di Aladin nei teatri di Arezzo e Aprilia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/AibiWeek-18-01.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/AibiWeek-18-01.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-settimana-eventi-scoprili-tutti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"AibiWeek. Una settimana ricca di eventi: scoprili tutti"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:33:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=227499"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/227500"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=227499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=227499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=227499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}