﻿{"id":227529,"date":"2025-01-16T07:40:48","date_gmt":"2025-01-16T06:40:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=227529"},"modified":"2025-01-16T14:11:41","modified_gmt":"2025-01-16T13:11:41","slug":"appelli-affido-familiare-joseph-paolo","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/","title":{"rendered":"Due appelli urgenti per affido familiare: Joseph e Paolo"},"content":{"rendered":"<h2>Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0<\/h2>\n<p><!--more--><\/p>\n<p>Essere una famiglia affidataria \u00e8 un gesto di straordinaria umanit\u00e0. Il Servizio Affidi dell\u2019ambito di Cinisello Balsamo ha recentemente lanciato un appello per due bambini con esperienze difficili e dolorose: Joseph e Paolo cercano una famiglia che possa donare loro l\u2019amore e la stabilit\u00e0 che meritano.<\/p>\n<h3>Joseph: un cuore che aspetta calore<\/h3>\n<p>Joseph ha 12 anni, \u00e8 un ragazzino che appare pi\u00f9 piccolo della sua et\u00e0, con un viso dolce e infantile. Giunto in Italia a 5 anni insieme alla giovane mamma e al fratello maggiore, ha vissuto per anni in condizioni di estrema precariet\u00e0, in una baracca senza riscaldamento n\u00e9 acqua corrente. La mancanza di cure e le difficili condizioni igieniche hanno segnato i suoi primi anni di vita.<br \/>\nDa alcuni anni Joseph vive in comunit\u00e0, dove ha imparato a prendersi cura di s\u00e9 grazie al supporto delle figure educative. Nonostante i progressi, ha ancora bisogno di un punto di riferimento adulto che lo guidi con pazienza e affetto. Frequenta la prima media con entusiasmo, ma necessita di affiancamento e rassicurazioni nello studio, a causa della discontinuit\u00e0 scolastica vissuta in passato.<br \/>\nLa mamma, una donna giovane ma in grande difficolt\u00e0, non pu\u00f2 occuparsi di lui e immagina per il figlio un affido a lungo termine. Joseph cerca una coppia con o senza figli, residente a Milano o nelle province di Como, che possa offrirgli l\u2019amore e la stabilit\u00e0 che non ha mai conosciuto.<\/p>\n<h3>Paolo: il desiderio di appartenenza<\/h3>\n<p>Paolo ha 9 anni, \u00e8 un bambino pieno di energia e con una grande voglia di trovare una famiglia. Dopo essere stato abbandonato dalla mamma da piccolo, \u00e8 stato cresciuto dal pap\u00e0, che per\u00f2 ha presto riconosciuto le proprie difficolt\u00e0 e chiesto aiuto ai servizi sociali.<br \/>\nA soli 6 anni, <strong>Paolo \u00e8 stato accompagnato in comunit\u00e0 dal padre, che gli aveva promesso di tornare a prenderlo<\/strong>. <strong>Da allora sono passati due anni e quella promessa<\/strong> non \u00e8 mai stata mantenuta. <strong>Il dolore dell\u2019abbandono<\/strong> si \u00e8 manifestato con rabbia e irrequietezza, ma oggi Paolo \u00e8 pronto a lasciarsi alle spalle il passato e affidarsi a nuovi adulti.<br \/>\nIl Servizio Affidi cerca per lui una famiglia residente a Milano o provincia, in grado di offrirgli attenzioni esclusive e quell\u2019amore che non ha mai ricevuto.<\/p>\n<h3>Un gesto che pu\u00f2 cambiare una vita<\/h3>\n<p>Accogliere Joseph o Paolo significa dare loro la possibilit\u00e0 di un futuro sereno, ricco di amore e stabilit\u00e0. Se siete interessati a questa importante opportunit\u00e0, contattate il Servizio Affidi dell\u2019Ambito di Cinisello Balsamo al numero <strong>3386694557 o 3516302121<\/strong> oppure scrivete a <strong><a href=\"mailto:servizio.affidi@insiemeperilsociale.it\">servizio.affidi@insiemeperilsociale.it<\/a><\/strong>.<\/p>\n<h3>Maggiori informazioni<\/h3>\n<p>Quando una famiglia attraversa un momento di difficolt\u00e0 e non riesce a prendersi momentaneamente cura dei figli, i minori possono essere accolti per un periodo di tempo determinato in un\u2019altra famiglia, la famiglia accogliente.<br \/>\nAi.Bi. organizza diverse attivit\u00e0 di formazione per\u00a0famiglie, coppie o single pronte ad aprire la loro casa, e la loro vita, a un\u2019esperienza di affido familiare. Tutte le informazioni si trovano sulla\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/attivita\/affido\/\"><strong>pagina dedicata\u00a0<\/strong><\/a>del sito dell\u2019Associazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit&agrave;<\/p>\n","protected":false},"author":133,"featured_media":227530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[848],"class_list":["post-227529","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-appelli-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Due appelli urgenti per affido familiare: Joseph e Paolo<\/title>\n<meta name=\"description\" content=\"Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Due appelli urgenti per affido familiare: Joseph e Paolo\" \/>\n<meta property=\"og:description\" content=\"Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T06:40:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T13:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/appelli-affido-Joseph-Paolo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Due appelli urgenti per affido familiare: Joseph e Paolo\",\"datePublished\":\"2025-01-16T06:40:48+00:00\",\"dateModified\":\"2025-01-16T13:11:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/\"},\"wordCount\":534,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/appelli-affido-Joseph-Paolo.jpg\",\"keywords\":[\"appelli affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/\",\"name\":\"Due appelli urgenti per affido familiare: Joseph e Paolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/appelli-affido-Joseph-Paolo.jpg\",\"datePublished\":\"2025-01-16T06:40:48+00:00\",\"dateModified\":\"2025-01-16T13:11:41+00:00\",\"description\":\"Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/appelli-affido-Joseph-Paolo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/appelli-affido-Joseph-Paolo.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/appelli-affido-familiare-joseph-paolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Due appelli urgenti per affido familiare: Joseph e Paolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Due appelli urgenti per affido familiare: Joseph e Paolo","description":"Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/","og_locale":"it_IT","og_type":"article","og_title":"Due appelli urgenti per affido familiare: Joseph e Paolo","og_description":"Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-01-16T06:40:48+00:00","article_modified_time":"2025-01-16T13:11:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/appelli-affido-Joseph-Paolo.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Due appelli urgenti per affido familiare: Joseph e Paolo","datePublished":"2025-01-16T06:40:48+00:00","dateModified":"2025-01-16T13:11:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/"},"wordCount":534,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/appelli-affido-Joseph-Paolo.jpg","keywords":["appelli affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/","url":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/","name":"Due appelli urgenti per affido familiare: Joseph e Paolo","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/appelli-affido-Joseph-Paolo.jpg","datePublished":"2025-01-16T06:40:48+00:00","dateModified":"2025-01-16T13:11:41+00:00","description":"Joseph e Paolo, rispettivamente di 12 e 9 anni, hanno vissuto esperienze dolorose. Il Servizio Affidi di Cinisello Balsamo, ora, sta cercando due famiglie affidatarie per offrire a ciascuno dei due bambini amore e stabilit\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/appelli-affido-Joseph-Paolo.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/appelli-affido-Joseph-Paolo.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/appelli-affido-familiare-joseph-paolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Due appelli urgenti per affido familiare: Joseph e Paolo"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:18:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=227529"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/227530"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=227529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=227529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=227529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}