﻿


{"id":227608,"date":"2025-01-20T07:50:36","date_gmt":"2025-01-20T06:50:36","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=227608"},"modified":"2025-01-20T17:33:19","modified_gmt":"2025-01-20T16:33:19","slug":"congo-progetto-igiene-salute-orfanotrofi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/","title":{"rendered":"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido"},"content":{"rendered":"<h2>Forniture mediche, kit igienici e formazione dei responsabili dei centri FED e SODAS. Grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, la salute \u00e8 sempre al centro dell\u2019attenzione<\/h2>\n<p><!--more--><\/p>\n<p>Il progetto <strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong> continua a portare speranza e miglioramenti concreti nella vita dei bambini accolti negli <strong>orfanotrofi FED e SODAS<\/strong> nella <strong>Repubblica Democratica del Congo<\/strong>. Grazie alle costanti donazioni, \u00e8 stata garantita la fornitura di medicinali essenziali e di kit igienici, con un\u2019attenzione particolare alla prevenzione e all\u2019autonomia gestionale degli istituti, specie in un periodo in cui le epidemie sono purtroppo\u00a0<span id=\"OBJ_PREFIX_DWT3393_com_zimbra_url\" class=\"Object\" role=\"link\"><span id=\"OBJ_PREFIX_DWT3418_com_zimbra_url\" class=\"Object\" role=\"link\"><a href=\"https:\/\/www.aibi.it\/ita\/congo-allarme-sanitario\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">una realt\u00e0 con cui dover fare i conti<\/a><\/span><\/span>\u00a0nel Paese.<br \/>\nLe piccole farmacie dei centri sono state rifornite di antibiotici, pomate, antimalarici, vitamine, dentifrici e spazzolini. Inoltre, per le ragazze, sono stati distribuiti kit igienici femminili completi di biancheria intima, una necessit\u00e0 spesso trascurata ma fondamentale per la dignit\u00e0 e il benessere delle giovani ospiti.<\/p>\n<h3>Nuove attivit\u00e0 per migliorare l\u2019igiene<\/h3>\n<p>Per contrastare la diffusione degli insetti, sono stati acquistati polverizzatori e prodotti specifici da irrorare. Le operazioni di sanificazione generale saranno affiancate da interventi regolari, grazie alla formazione offerta dal medico del progetto. Questi incontri formativi garantiranno ai responsabili di FED e SODAS le competenze necessarie per <strong>utilizzare i prodotti in modo sicuro ed efficace<\/strong>.<\/p>\n<h3>Il lavoro sanitario e due casi seguiti con attenzione<\/h3>\n<p>Il medico del progetto continua a monitorare regolarmente la salute dei bambini, con azioni preventive che hanno ridotto al minimo i casi gravi. Tuttavia, due episodi recenti hanno richiesto un\u2019attenzione particolare:<\/p>\n<ul>\n<li><strong>Un bambino di 4 anni<\/strong> del centro FED ha contratto la malaria. Dopo un ricovero ospedaliero di alcuni giorni, <strong>\u00e8 stato dimesso in buone condizioni<\/strong>. Per supportare il suo recupero e migliorare la nutrizione di tutti i bambini sotto i cinque anni del centro, \u00e8 stata fornita una scorta di MASOSO, una miscela nutriente a base di mais, soia e sorgo.<\/li>\n<li><strong>Una ragazza di 14 anni<\/strong> del centro SODAS ha ricevuto cure per un\u2019amenorrea prolungata. Dopo una terapia antibiotica e un consulto specialistico, i <strong>progressi sono incoraggianti<\/strong>. Tuttavia, la situazione potrebbe essere legata a un blocco psicologico. Per questo, \u00e8 stata <strong>avviata una collaborazione con l\u2019equipe degli psicologi<\/strong>, affinch\u00e9 la ragazza riceva un supporto completo e adeguato al suo sviluppo personale.<\/li>\n<\/ul>\n<h3>Il valore del progetto<\/h3>\n<p>Grazie a questo progetto, <strong>si sta costruendo un sistema sanitario e igienico pi\u00f9 solido<\/strong>, capace di rispondere non solo alle emergenze ma anche alle necessit\u00e0 quotidiane dei bambini. Un esempio concreto di come solidariet\u00e0 e professionalit\u00e0 possano cambiare la vita di chi ha pi\u00f9 bisogno.<\/p>\n<h3>L\u2019attesa di Nathan, Anita, Kevin e Viviane<\/h3>\n<p>Negli orfanotrofi in Repubblica Democratica del Congo, <strong>Nathan<\/strong>,\u00a0<strong>Anita<\/strong>,\u00a0<strong>Kevin<\/strong> e\u00a0<strong>Viviane<\/strong>\u00a0stanno ancora aspettando qualcuno che\u00a0<strong>possa accompagnarle nel loro cammino di speranza e di emancipazione\u00a0<\/strong>attraverso un\u2019<strong>Adozione a Distanza.<\/strong><br \/>\nLeggi la storia di <strong><a href=\"https:\/\/www.aibi.it\/ita\/congo-nathan-orfano\/\">Nathan<\/a><\/strong>, di <strong><a href=\"https:\/\/www.aibi.it\/ita\/congo-anita-speranza\/\">Anita<\/a><\/strong>,\u00a0di <strong><a href=\"https:\/\/www.aibi.it\/ita\/congo-poverta-guerra-fame-futuro-kevin\/\">Kevin<\/a><\/strong> e quella di\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/congo-guerra-abbandonata-viviane-speranza\/\">Viviane<\/a><\/strong>.<\/p>\n<h3>L\u2019Adozione a Distanza in Repubblica Democratica del Congo<\/h3>\n<p>Anche tu puoi sostenere le attivit\u00e0 di Ai.Bi. in <strong>Repubblica Democratica del Congo<\/strong>\u00a0con una donazione cliccando\u00a0<a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\"><strong>qui<\/strong><\/a>.<br \/>\nSe vuoi fare di pi\u00f9 e stare vicino ogni giorno ai bambini degli orfanotrofi Fed e Sodas e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto \u201cAdotta a distanza i bambini di un orfanotrofio\u201d.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\" https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Congo\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Infine, se vuoi creare con Nathan, Anita, Kevin o con Viviane un rapporto unico ed esclusivo per accompagnarli attivamente nella loro crescita, puoi adottare a distanza uno di loro. Riceverai il suo dossier, potrai scrivergli, ricevere le sue foto e mandargli le tue, chiedere e ricevere aggiornamenti periodici, pensare a regali aggiuntivi per momenti particolari. E, perch\u00e9 no, andare anche a trovarli.<br \/>\nPer richiedere informazioni sull\u2019Adozione a Distanza <a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">clicca qui<\/a>.<br \/>\nE ricorda: come ogni donazione, anche le Adozioni a Distanza di Ai.Bi. godono delle seguenti <a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\">agevolazioni fiscali<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forniture mediche, kit igienici e formazione dei responsabili dei centri FED e SODAS. Grazie al progetto &ldquo;Sostieni a distanza i bambini di un orfanotrofio&rdquo;, la salute &egrave; sempre al centro dell&rsquo;attenzione<\/p>\n","protected":false},"author":133,"featured_media":227609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[645,671],"class_list":["post-227608","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-fed","tag-sodas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo. Igiene e salute negli orfanotrofi<\/title>\n<meta name=\"description\" content=\"Forniture mediche, kit igienici e formazione per i centri FED e SODAS del Congo, grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido\" \/>\n<meta property=\"og:description\" content=\"Forniture mediche, kit igienici e formazione per i centri FED e SODAS del Congo, grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-20T06:50:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T16:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/RDC-igiene-salute.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido\",\"datePublished\":\"2025-01-20T06:50:36+00:00\",\"dateModified\":\"2025-01-20T16:33:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/\"},\"wordCount\":664,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/RDC-igiene-salute.jpg\",\"keywords\":[\"Fed\",\"Sodas\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/\",\"name\":\"Congo. Igiene e salute negli orfanotrofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/RDC-igiene-salute.jpg\",\"datePublished\":\"2025-01-20T06:50:36+00:00\",\"dateModified\":\"2025-01-20T16:33:19+00:00\",\"description\":\"Forniture mediche, kit igienici e formazione per i centri FED e SODAS del Congo, grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/RDC-igiene-salute.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/RDC-igiene-salute.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-progetto-igiene-salute-orfanotrofi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo. Igiene e salute negli orfanotrofi","description":"Forniture mediche, kit igienici e formazione per i centri FED e SODAS del Congo, grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/","og_locale":"it_IT","og_type":"article","og_title":"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido","og_description":"Forniture mediche, kit igienici e formazione per i centri FED e SODAS del Congo, grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d","og_url":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-01-20T06:50:36+00:00","article_modified_time":"2025-01-20T16:33:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/RDC-igiene-salute.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido","datePublished":"2025-01-20T06:50:36+00:00","dateModified":"2025-01-20T16:33:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/"},"wordCount":664,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/RDC-igiene-salute.jpg","keywords":["Fed","Sodas"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/","url":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/","name":"Congo. Igiene e salute negli orfanotrofi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/RDC-igiene-salute.jpg","datePublished":"2025-01-20T06:50:36+00:00","dateModified":"2025-01-20T16:33:19+00:00","description":"Forniture mediche, kit igienici e formazione per i centri FED e SODAS del Congo, grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/RDC-igiene-salute.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/RDC-igiene-salute.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/congo-progetto-igiene-salute-orfanotrofi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Repubblica Democratica del Congo. Un progetto che fa la differenza per un sistema sanitario e igienico pi\u00f9 solido"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:11:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=227608"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/227609"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=227608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=227608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=227608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}