﻿


{"id":227702,"date":"2025-01-23T07:30:33","date_gmt":"2025-01-23T06:30:33","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=227702"},"modified":"2025-02-06T14:43:31","modified_gmt":"2025-02-06T13:43:31","slug":"kenya-adozione-a-distanza-tornare-casa-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/","title":{"rendered":"Kenya. I successi dell&#8217;Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0"},"content":{"rendered":"<h2>Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia<\/h2>\n<p><!--more--><\/p>\n<p>La scorsa settimana si \u00e8 tenuta una riunione di coordinamento presso l\u2019ORFANOTROFIO<strong> Shelter Children\u2019s Home<\/strong>, con la partecipazione della psicologa responsabile dei percorsi di reintegro familiare dei bambini, un&#8217;iniziativa resa possibile grazie al sostegno del progetto <strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong>.<\/p>\n<h3>Un quadro incoraggiante<\/h3>\n<p>Durante l\u2019incontro, sono stati valutati i risultati del reinserimento dei minori accolti nelle loro famiglie lo scorso anno. \u00c8 emerso un <strong>quadro incoraggiante<\/strong>: i bambini stanno vivendo serenamente nelle loro nuove realt\u00e0 familiari, molti hanno concluso con successo l\u2019anno scolastico e hanno superato le difficolt\u00e0 iniziali grazie al costante supporto fornito dallo staff di <strong>Ai.Bi.<\/strong> e dello <strong>Shelter<\/strong>. I genitori hanno espresso profonda gratitudine per il sostegno ricevuto, sottolineando quanto l\u2019accompagnamento sia stato determinante per trasformare l\u2019integrazione familiare in un\u2019esperienza positiva.<\/p>\n<h3>L\u2019ultimo incontro<\/h3>\n<p>Nella stessa giornata, si \u00e8 svolta l\u2019ultima sessione di gruppo con 17 bambini e ragazzi che presto lasceranno il centro per tornare definitivamente alle loro famiglie. Durante l\u2019incontro, i minori hanno condiviso le loro emozioni, raccontando la gioia di rientrare a casa, ma anche le apprensioni per le sfide future. La psicologa li ha aiutati a elaborare questi sentimenti, fornendo loro strumenti pratici per affrontare il cambiamento.<br \/>\nL\u2019esperienza dimostra quanto sia fondamentale il supporto continuo offerto dai <strong>progetti di adozione a distanza<\/strong>, che rendono possibile non solo il reinserimento, ma anche un percorso di crescita e stabilit\u00e0 per i bambini e le loro famiglie.<\/p>\n<h3>L\u2019attesa di Wycliffe e Elias<\/h3>\n<p>Negli orfanotrofi del Kenya altri bambini stanno aspettando qualcuno che li aiuti nel loro percorso, bambini come <strong><a href=\"https:\/\/www.aibi.it\/ita\/kenya-grido-aiuto-wycliffe\/\">Wycliffe<\/a><\/strong> ed <strong><a href=\"https:\/\/www.aibi.it\/ita\/kenya-elias-genitori-orfanotrofio-futuro\/\">Elias<\/a><\/strong>.<\/p>\n<h3>Come aiutare i bambini abbandonati degli orfanotrofi in Kenya?<\/h3>\n<p><strong>Puoi <\/strong>contribuire alle attivit\u00e0 promosse da Ai.Bi. con una donazione, <strong>cliccando <a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">qui<\/a><\/strong>.<br \/>\nSe vuoi <strong>dare continuit\u00e0 al tuo aiuto, stando vicino <\/strong>ogni giorno ai bambini degli orfanotrofi sostenuti da Ai.Bi. e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto <strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong>.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*214772-start*\/\n#btnsx-214772{margin-top:0px;margin-bottom:15px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-214772 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-214772:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-214772{background-color:#ee7e0d!important;}\n#btnsx-214772:hover{background-color:#ed650b!important;}\n#btnsx-214772{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-214772:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-214772{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-214772:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*214772-end*\/\n<\/style><div id=\"btnsx-214772-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-214772-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-214772\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">ADOTTA A DISTANZA ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Infine se vuoi creare con <strong>Wycliffe<\/strong> o con <strong>Elias<\/strong> un rapporto unico ed esclusivo per accompagnarli attivamente nella loro crescita, puoi adottare a distanza uno di loro. Riceverai il suo dossier, potrai scrivergli, ricevere le sue foto e mandargli le tue, chiedere e ricevere aggiornamenti periodici, pensare a regali aggiuntivi per momenti particolari. E, perch\u00e9 no, andare anche a trovarlo.<br \/>\nPer richiedere informazioni sull\u2019Adozione a Distanza <a href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a>.<br \/>\nE ricorda: come ogni donazione, anche le<strong> Adozioni a Distanza di Ai.Bi. <\/strong>godono delle seguenti <a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accompagnamento psicologico e supporto: cos&igrave; il progetto &ldquo;Sostieni a distanza i bambini di un orfanotrofio&rdquo;, ha permesso a tanti bambini dell&rsquo;orfanotrofio Shelter Children&rsquo;s Home di ritrovare la propria famiglia<\/p>\n","protected":false},"author":133,"featured_media":227703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[640],"class_list":["post-227702","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-shelter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya. Tornare a casa\u00a0 dalla propria famiglia\u00a0<\/title>\n<meta name=\"description\" content=\"Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. I successi dell&#039;Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0\" \/>\n<meta property=\"og:description\" content=\"Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T06:30:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T13:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/Kenya-tornare-a-casa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Kenya. I successi dell&#8217;Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0\",\"datePublished\":\"2025-01-23T06:30:33+00:00\",\"dateModified\":\"2025-02-06T13:43:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/\"},\"wordCount\":464,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/Kenya-tornare-a-casa.jpg\",\"keywords\":[\"Shelter\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/\",\"name\":\"Kenya. Tornare a casa\u00a0 dalla propria famiglia\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/Kenya-tornare-a-casa.jpg\",\"datePublished\":\"2025-01-23T06:30:33+00:00\",\"dateModified\":\"2025-02-06T13:43:31+00:00\",\"description\":\"Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/Kenya-tornare-a-casa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/01\\\/Kenya-tornare-a-casa.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-adozione-a-distanza-tornare-casa-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. I successi dell&#8217;Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya. Tornare a casa\u00a0 dalla propria famiglia\u00a0","description":"Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. I successi dell'Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0","og_description":"Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia","og_url":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-01-23T06:30:33+00:00","article_modified_time":"2025-02-06T13:43:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/Kenya-tornare-a-casa.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Kenya. I successi dell&#8217;Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0","datePublished":"2025-01-23T06:30:33+00:00","dateModified":"2025-02-06T13:43:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/"},"wordCount":464,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/Kenya-tornare-a-casa.jpg","keywords":["Shelter"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/","name":"Kenya. Tornare a casa\u00a0 dalla propria famiglia\u00a0","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/Kenya-tornare-a-casa.jpg","datePublished":"2025-01-23T06:30:33+00:00","dateModified":"2025-02-06T13:43:31+00:00","description":"Accompagnamento psicologico e supporto: cos\u00ec il progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d, ha permesso a tanti bambini dell\u2019orfanotrofio Shelter Children\u2019s Home di ritrovare la propria famiglia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/Kenya-tornare-a-casa.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/01\/Kenya-tornare-a-casa.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-adozione-a-distanza-tornare-casa-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. I successi dell&#8217;Adozione a Distanza: tornare a casa\u00a0 dalla propria famiglia\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:44:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=227702"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/227702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/227703"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=227702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=227702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=227702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}