﻿{"id":22790,"date":"2011-05-25T14:18:07","date_gmt":"2011-05-25T13:18:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=22790"},"modified":"2011-05-25T14:48:00","modified_gmt":"2011-05-25T13:48:00","slug":"riconoscimento-kafala-perche-il-governo-non-decide","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/","title":{"rendered":"Riconoscimento Kafala: perche&#8217; il Governo non decide?"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/kafala_bimbi1003.jpg\"><\/a><a href=\"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-22802\" style=\"margin: 5px;\" title=\"orphan2\" src=\"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Il Governo italiano continua a mantenere un inquietante silenzio sul disegno di legge per la ratifica della Convenzione de L\u2019Aja del 1996 che aprirebbe la strada al riconoscimento della kafala: la proposta governativa avrebbe dovuto essere pronta all\u2019inizio del 2011 e non si sa invece che fine abbia fatto.<\/p>\n<p>E rimane finora senza risposta anche l\u2019ultima delle lodevoli iniziative dei parlamentari, quella dell\u2019<strong>On. Sandra Zampa, deputato del gruppo parlamentare del Partito Democratico,<\/strong> \u00a0che, mantenendo alto il suo impegno per i diritti dei minori, ha presentato una <strong>nuova interrogazione parlamentare il 4 maggio scorso<\/strong> e ha chiesto ancora una volta al Ministro degli Esteri e al Ministro della Giustizia quali siano le ragioni del <strong>ritardo<\/strong>.<\/p>\n<p>Pubblichiamo il testo dell\u2019interrogazione a risposta in Commissione 5\/04712,<strong> <\/strong>dall\u2019onorevole Zampa che ha evidenziato gli impegni dell\u2019Italia nei confronti dell\u2019Unione Europea visto che la Convenzione \u00e8 stata definita di <strong>\u201crilevanza comunitaria\u201d<\/strong> dal Consiglio dell\u2019Unione Europea gi\u00e0 nel giugno 2008<strong>.<\/strong><\/p>\n<p>\u201c<strong>premesso che<\/strong>:<\/p>\n<p><em>&#8211; Il Governo non ha ancora presentato il disegno di legge di ratifica della Convenzione dell&#8217;Aja del 1996 in materia di responsabilit\u00e0 genitoriale e di misure di protezione dei minori, <\/em><em>la Convenzione<\/em><\/p>\n<div><em>si applica a tutte le situazioni in cui emergono elementi di \u00abinternazionalit\u00e0\u00bb attraverso obiettivi specifici quali: determinare quale stato \u00e8 competente ad adottare misure volte alla protezione della persona o dei beni del minore; attribuire alle autorit\u00e0 del Paese in cui il minore si trova fisicamente la competenza per l&#8217;adozione di tutti i provvedimenti d&#8217;urgenza; determinare la legge applicabile dalle autorit\u00e0 competenti; determinare la legge applicabile alla \u00abresponsabilit\u00e0 genitoriale\u00bb; garantire il riconoscimento e l&#8217;esecuzione delle misure di protezione del minore in tutti gli Stati contraenti; stabilire una cooperazione fra gli Stati coinvolti nell&#8217;emanazione e nel riconoscimento dei provvedimenti sui minori;<br \/>\n&#8211; nel Trattato di Lisbona l&#8217;Unione europea ha inserito i diritti dei minori tra gli obiettivi comuni;<br \/>\n&#8211; l&#8217;Italia ha l&#8217;obbligo di ottemperare alle disposizioni dell&#8217;Unione in quanto Stato membro;<br \/>\n\u00e8 stato istituito un tavolo interministeriale, che ha iniziato i lavori nel novembre del 2008 su proposta del Ministero della giustizia, al quale partecipano rappresentanti dei Ministeri interessati, il tavolo ha elaborato una bozza di disegno di legge di ratifica nei confronti della quale sono state sollevate delle riserve da parte del Ministero dell&#8217;interno relativamente al riconoscimento, previsto dalla Convenzione, della kafala, istituto di diritto islamico;<br \/>\n&#8211; il Ministero dell&#8217;interno in conformit\u00e0 con l&#8217;orientamento della Corte di Cassazione, ritiene tale istituto conforme ai principi del nostro ordinamento solo nel caso in cui l&#8217;autorit\u00e0 giudiziaria locale emetta il provvedimento per l&#8217;affidamento, la cosiddetta kafala giudiziale, sulla quale il Ministero dell&#8217;interno ha sciolto la riserva;<br \/>\n&#8211; lo scioglimento della riserva da parte del Ministero dell&#8217;interno avrebbe dovuto permettere la riconvocazione del tavolo da parte del Ministero della giustizia per completare il lavoro finalizzato alla stesura del disegno di legge di ratifica della Convenzione -:<\/em><\/div>\n<div><strong>Per sapere<\/strong><em><br \/>\n\u201c<strong>quali siano i motivi che ostacolano la presentazione del disegno di legge, considerando che l&#8217;Unione europea ha gi\u00e0 sollecitato la ratifica della citata Convenzione dell&#8217;Aja del 1996<\/strong>. (5-04712)\u201d.<\/em><strong>\u00a0<\/strong><\/div>\n<p>\u00a0Aspettiamo con ansia una risposta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblichiamo il testo dell\u2019interrogazione a risposta in Commissione 5\/04712,<strong> <\/strong>dall\u2019onorevole Zampa che ha evidenziato gli impegni dell\u2019Italia nei confronti dell\u2019Unione Europea visto che la Convenzione \u00e8 stata definita di <strong>\u201crilevanza comunitaria\u201d<\/strong> dal Consiglio dell\u2019Unione Europea gi\u00e0 nel giugno 2008<strong>. <a href=\"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-22790","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Riconoscimento Kafala: perche&#039; il Governo non decide? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riconoscimento Kafala: perche&#039; il Governo non decide?\" \/>\n<meta property=\"og:description\" content=\"Pubblichiamo il testo dell\u2019interrogazione a risposta in Commissione 5\/04712, dall\u2019onorevole Zampa che ha evidenziato gli impegni dell\u2019Italia nei confronti dell\u2019Unione Europea visto che la Convenzione \u00e8 stata definita di \u201crilevanza comunitaria\u201d dal Consiglio dell\u2019Unione Europea gi\u00e0 nel giugno 2008. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-25T13:18:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-05-25T13:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Riconoscimento Kafala: perche&#8217; il Governo non decide?\",\"datePublished\":\"2011-05-25T13:18:07+00:00\",\"dateModified\":\"2011-05-25T13:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/orphan2.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/\",\"name\":\"Riconoscimento Kafala: perche' il Governo non decide? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/orphan2.jpg\",\"datePublished\":\"2011-05-25T13:18:07+00:00\",\"dateModified\":\"2011-05-25T13:48:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/orphan2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/orphan2.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/riconoscimento-kafala-perche-il-governo-non-decide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Riconoscimento Kafala: perche&#8217; il Governo non decide?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Riconoscimento Kafala: perche' il Governo non decide? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/","og_locale":"it_IT","og_type":"article","og_title":"Riconoscimento Kafala: perche' il Governo non decide?","og_description":"Pubblichiamo il testo dell\u2019interrogazione a risposta in Commissione 5\/04712, dall\u2019onorevole Zampa che ha evidenziato gli impegni dell\u2019Italia nei confronti dell\u2019Unione Europea visto che la Convenzione \u00e8 stata definita di \u201crilevanza comunitaria\u201d dal Consiglio dell\u2019Unione Europea gi\u00e0 nel giugno 2008. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-05-25T13:18:07+00:00","article_modified_time":"2011-05-25T13:48:00+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Riconoscimento Kafala: perche&#8217; il Governo non decide?","datePublished":"2011-05-25T13:18:07+00:00","dateModified":"2011-05-25T13:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/"},"wordCount":527,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/","url":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/","name":"Riconoscimento Kafala: perche' il Governo non decide? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg","datePublished":"2011-05-25T13:18:07+00:00","dateModified":"2011-05-25T13:48:00+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/orphan2.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/riconoscimento-kafala-perche-il-governo-non-decide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Riconoscimento Kafala: perche&#8217; il Governo non decide?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:37:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/22790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=22790"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/22790\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=22790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=22790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=22790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}