﻿


{"id":228626,"date":"2025-03-07T07:30:19","date_gmt":"2025-03-07T06:30:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=228626"},"modified":"2025-10-22T17:41:39","modified_gmt":"2025-10-22T15:41:39","slug":"bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/","title":{"rendered":"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]\n<h2>Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria<\/h2>\n<p><!--more--><\/p>\n<p>Salvador ha sei anni e non ha mai conosciuto l&#8217;affetto e la protezione di una famiglia. Suo padre \u00e8 morto, sua madre \u00e8 alle prese con problemi di dipendenza e i suoi nonni hanno rifiutato di prendersi cura di lui.<br \/>\nIn un contesto cos\u00ec difficile, la Defensor\u00eda dell\u2019Infanzia e dell\u2019Adolescenza ha individuato per lui una possibile soluzione: il programma di famiglie sostitutive. Salvador ricever\u00e0 visite da famiglie interessate a offrirgli un ambiente domestico temporaneo. Dopo un mese di incontri, il bambino potr\u00e0 trascorrere alcuni giorni presso una delle famiglie candidate, con la possibilit\u00e0 di trasferirsi stabilmente se il percorso si dimostrer\u00e0 positivo.<br \/>\nIl giudice incaricato ha autorizzato che questa custodia abbia fini adottivi: una volta completata l&#8217;estinzione dell&#8217;autorit\u00e0 materna, Salvador potr\u00e0 essere adottato definitivamente.<br \/>\n<strong>L&#8217;orfanotrofio Jos\u00e9 Soria\u00a0<\/strong>ha avviato\u00a0<strong>l\u2019iniziativa\u00a0<\/strong>con Salvador, aderendo al programma di deistituzionalizzazione gi\u00e0 attivo negli altri orfanotrofi sostenuti da Ai.Bi. in Bolivia.<\/p>\n<h3>Che cosa prevede il programma<\/h3>\n<p>Il programma di deistituzionalizzazione prevede che gli operatori di Ai.Bi., in collaborazione con le autorit\u00e0, si occupino di rintracciare la famiglia biologica del minore abbandonato,\u00a0 in caso di impossibilit\u00e0 del rientro in famiglia o di non rintracciamento , dopo vari tentativi di ricerca della famiglia, preparare la documentazione necessaria per la destituzione della potest\u00e0 genitoriale e raccogliere i certificati di nascita e d&#8217;identit\u00e0 del bambino. Inoltre, formano e accompagnano le famiglie\u00a0\u00a0candidate all\u2019adozione\u00a0\u00a0durante il delicato periodo di affiatamento con il bambino.<br \/>\nTutto questo \u00e8 possibile anche grazie al sostegno del progetto \u201c<a href=\"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/bolivia-dal-nido-alla-nascita-lidentita-i-diritti-e-le-opportunita\/\">Dal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0<\/a>\u201c,\u00a0finanziato dalla CAI con Ai.Bi. capofila, che permette a tanti bambini come Salvador di sperare in un futuro migliore.[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&rdquo;&rdquo;] Grazie anche al sostegno del progetto progetto finanziato dalla CAI &ldquo;Dal Nido: alla Nascita, l&rsquo;Identit&agrave;, i Diritti, e le Opportunit&agrave;&ldquo;, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit&agrave; adottive nell&rsquo;orfanotrofio Jos&eacute; Soria<\/p>\n","protected":false},"author":133,"featured_media":228627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[647],"class_list":["post-228626","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-jose-soria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia.\u00a0Il programma di deistituzionalizzazione<\/title>\n<meta name=\"description\" content=\"Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini\" \/>\n<meta property=\"og:description\" content=\"Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T06:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T15:41:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/03\/Bolivia-orfanotrofio-programma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini\",\"datePublished\":\"2025-03-07T06:30:19+00:00\",\"dateModified\":\"2025-10-22T15:41:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/\"},\"wordCount\":354,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/03\\\/Bolivia-orfanotrofio-programma.jpg\",\"keywords\":[\"Jos\u00e8 Soria\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/\",\"name\":\"Bolivia.\u00a0Il programma di deistituzionalizzazione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/03\\\/Bolivia-orfanotrofio-programma.jpg\",\"datePublished\":\"2025-03-07T06:30:19+00:00\",\"dateModified\":\"2025-10-22T15:41:39+00:00\",\"description\":\"Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/03\\\/Bolivia-orfanotrofio-programma.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/03\\\/Bolivia-orfanotrofio-programma.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia.\u00a0Il programma di deistituzionalizzazione","description":"Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini","og_description":"Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-03-07T06:30:19+00:00","article_modified_time":"2025-10-22T15:41:39+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/03\/Bolivia-orfanotrofio-programma.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini","datePublished":"2025-03-07T06:30:19+00:00","dateModified":"2025-10-22T15:41:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/"},"wordCount":354,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/03\/Bolivia-orfanotrofio-programma.jpg","keywords":["Jos\u00e8 Soria"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/","name":"Bolivia.\u00a0Il programma di deistituzionalizzazione","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/03\/Bolivia-orfanotrofio-programma.jpg","datePublished":"2025-03-07T06:30:19+00:00","dateModified":"2025-10-22T15:41:39+00:00","description":"Grazie anche al sostegno del progetto progetto finanziato dalla CAI \u201cDal Nido: alla Nascita, l\u2019Identit\u00e0, i Diritti, e le Opportunit\u00e0\u201c, il piccolo Salvador, un bambino di sei anni, avvia il percorso di affido con finalit\u00e0 adottive nell\u2019orfanotrofio Jos\u00e9 Soria","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/03\/Bolivia-orfanotrofio-programma.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/03\/Bolivia-orfanotrofio-programma.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-orfanotrofio-famiglia-programma-deistituzionalizzazione-amici-dei-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Bolivia.\u00a0Dall\u2019orfanotrofio a una famiglia: il programma di deistituzionalizzazione promosso da Amici dei Bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:12:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/228626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=228626"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/228626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/228627"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=228626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=228626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=228626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}