﻿


{"id":229207,"date":"2025-04-01T13:20:36","date_gmt":"2025-04-01T11:20:36","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=229207"},"modified":"2025-04-01T13:20:36","modified_gmt":"2025-04-01T11:20:36","slug":"natalita-minimi-impatto-adozione-internazionale-gratuita","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/","title":{"rendered":"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l&#8217;adozione internazionale se diventasse gratuita?"},"content":{"rendered":"<h2>L\u2019Istat certifica che calano sempre pi\u00f9 le famiglie con figli e, invece, aumentano i single. Il possibile ruolo dell\u2019adozione internazionale: con soli 15 milioni di euro mille nuovi \u201cfigli\u201d e cittadini italiani<\/h2>\n<p><!--more--><\/p>\n<p>L\u2019ISTAT ha reso noto il report relativo agli <strong>indicatori demografici dell\u2019anno 2024<\/strong>: non si arresta il calo demografico; il tasso di fecondit\u00e0 scende ai minimi storici e il saldo tra nascite e decessi continua a essere fortemente negativo.<br \/>\nCerto, che il quadro fosse preoccupante era noto a tutti, ma vedere le cifre cristallizzate e ufficializzate dall\u2019Istituto Nazionale di Statistica rende evidente <strong>tutta la drammaticit\u00e0 della situazione<\/strong>.<\/p>\n<h3>Tasso di fertilit\u00e0 ai minimi storici<\/h3>\n<p>Prima di tutto si evidenzia l\u2019ennesimo calo di nuovi nati, che si attestano a <strong>370mila<\/strong> per un <strong>calo del 2,6%<\/strong> rispetto al 2023. Il risultato \u00e8 un\u2019ulteriore diminuzione della popolazione italiana scesa al di sotto dei 59 milioni. Per la precisione: <strong>58milioni 934mila<\/strong>. A completare il quadro allarmante c\u2019\u00e8 la discesa del <strong>tasso di fertilit\u00e0 a 1,18 figli per donna<\/strong>, che non solo \u00e8 meno dell\u20191,20 del 2023, ma anche del precedente minimo storico di 1,19 del 1995.<br \/>\nContinua anche l\u2019evidente cambiamento nella composizione delle famiglie: calano sempre di pi\u00f9 le coppie con figli, arrivate a rappresentare il 29,2% del totale, e crescono in maniera inversamente proporzionale le <strong>famiglie formate da una sola persona, arrivate a essere il 36,2%<\/strong> (erano il 25,5% solo 20 anni fa). Stabili, invece, le coppie senza figli.<\/p>\n<h3>Rendere gratuita l\u2019adozione internazionale<\/h3>\n<p>Anche quest\u2019ultimo aspetto non fa che accentuare l\u2019evidente problema italiano della denatalit\u00e0 e della mancanza di segnali per una inversione di tendenza. Anche le politiche finora messe in atto non stanno evidentemente dando i risultati sperati. Ma se per quanto riguarda le nascite si pu\u00f2 dire che almeno qualche tentativo venga fatto, se guardiamo all\u2019adozione internazionale \u00e8 inevitabile constatare <strong>l\u2019assenza di misure di sostegno.<br \/>\n<\/strong>Eppure, in un quadro cos\u00ec cupo, il suo contributo potrebbe rivelarsi molto importante, sia nei numeri sia come segnale di speranza.<br \/>\nDichiara <strong>Marco Griffini<\/strong>, presidente di Ai.Bi. Amici dei Bambini ETS: \u201cSe ci fosse un\u2019attenzione particolare da parte della politica (come c\u2019\u00e8 stata, per esempio, per la fecondazione assistita, resa gratuita in tutte le regioni), le <strong>adozioni internazionali in Italia potrebbero essere migliaia<\/strong>, e non solo le poche centinaia di oggi. A maggior ragione ora, con <a href=\"https:\/\/www.aibi.it\/ita\/adozione-single-webinar-gratuito-capire\/\">l\u2019apertura anche verso i single<\/a>. Serve un aiuto concreto che vada innanzitutto verso la gratuit\u00e0 dell\u2019adozione. Per avere una idea dei possibili numeri: basterebbero <strong>poco pi\u00f9 di 15 milioni di euro<\/strong> per accompagnare l\u2019adozione di circa <strong>700 famiglie per almeno mille minori<\/strong> provenienti dall\u2019estero, che diventerebbero immediatamente figli e cittadini italiani. Ma serve anche un sostegno alle istituzioni preposte all\u2019infanzia abbandonata nei Paesi di origine dei minori, in special modo per le pratiche connesse alla dichiarazione di adottabilit\u00e0, visto che nel mondo ci sono <strong>milioni di bambini abbandonati costretti a marcire negli orfanotrofi fino alla maggiore et\u00e0<\/strong>, mentre i minori dichiarati adottabili sono una parte infinitamente minore di essi.<br \/>\nInsomma, come non ci stanchiamo di ripetere da anni, le soluzioni per rilanciare l\u2019Adozione Internazionale, e con essa contribuire alla natalit\u00e0, ci sono, bisogna solo avere la volont\u00e0 politica di intraprenderle\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Istat certifica che calano sempre pi&ugrave; le famiglie con figli e, invece, aumentano i single. Il possibile ruolo dell&rsquo;adozione internazionale: con soli 15 milioni di euro mille nuovi &ldquo;figli&rdquo; e cittadini italiani<\/p>\n","protected":false},"author":102,"featured_media":213021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,299,798],"class_list":["post-229207","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-denatalita","tag-single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Natalit\u00e0 ai minimi. Che impatto avrebbe un&#039;adozione internazionale gratuita?<\/title>\n<meta name=\"description\" content=\"L\u2019Istat certifica il calo della natalit\u00e0 e delle famiglie con figli. Aumentano i single. Il possibile ruolo che avrebbe un\u2019adozione internazionale gratuita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l&#039;adozione internazionale se diventasse gratuita?\" \/>\n<meta property=\"og:description\" content=\"L\u2019Istat certifica il calo della natalit\u00e0 e delle famiglie con figli. Aumentano i single. Il possibile ruolo che avrebbe un\u2019adozione internazionale gratuita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T11:20:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/2023-nascite-denatalita-primo-trimestre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l&#8217;adozione internazionale se diventasse gratuita?\",\"datePublished\":\"2025-04-01T11:20:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/\"},\"wordCount\":536,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/2023-nascite-denatalita-primo-trimestre.jpg\",\"keywords\":[\"Adozione Internazionale\",\"denatalit\u00e0\",\"single\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/\",\"name\":\"Natalit\u00e0 ai minimi. Che impatto avrebbe un'adozione internazionale gratuita?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/2023-nascite-denatalita-primo-trimestre.jpg\",\"datePublished\":\"2025-04-01T11:20:36+00:00\",\"description\":\"L\u2019Istat certifica il calo della natalit\u00e0 e delle famiglie con figli. Aumentano i single. Il possibile ruolo che avrebbe un\u2019adozione internazionale gratuita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/2023-nascite-denatalita-primo-trimestre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/2023-nascite-denatalita-primo-trimestre.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/natalita-minimi-impatto-adozione-internazionale-gratuita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l&#8217;adozione internazionale se diventasse gratuita?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Natalit\u00e0 ai minimi. Che impatto avrebbe un'adozione internazionale gratuita?","description":"L\u2019Istat certifica il calo della natalit\u00e0 e delle famiglie con figli. Aumentano i single. Il possibile ruolo che avrebbe un\u2019adozione internazionale gratuita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/","og_locale":"it_IT","og_type":"article","og_title":"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l'adozione internazionale se diventasse gratuita?","og_description":"L\u2019Istat certifica il calo della natalit\u00e0 e delle famiglie con figli. Aumentano i single. Il possibile ruolo che avrebbe un\u2019adozione internazionale gratuita","og_url":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-04-01T11:20:36+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/2023-nascite-denatalita-primo-trimestre.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l&#8217;adozione internazionale se diventasse gratuita?","datePublished":"2025-04-01T11:20:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/"},"wordCount":536,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/2023-nascite-denatalita-primo-trimestre.jpg","keywords":["Adozione Internazionale","denatalit\u00e0","single"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/","url":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/","name":"Natalit\u00e0 ai minimi. Che impatto avrebbe un'adozione internazionale gratuita?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/2023-nascite-denatalita-primo-trimestre.jpg","datePublished":"2025-04-01T11:20:36+00:00","description":"L\u2019Istat certifica il calo della natalit\u00e0 e delle famiglie con figli. Aumentano i single. Il possibile ruolo che avrebbe un\u2019adozione internazionale gratuita","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/2023-nascite-denatalita-primo-trimestre.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/2023-nascite-denatalita-primo-trimestre.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/natalita-minimi-impatto-adozione-internazionale-gratuita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Natalit\u00e0 ai minimi storici. Quale impatto avrebbe l&#8217;adozione internazionale se diventasse gratuita?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:10:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=229207"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/213021"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=229207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=229207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=229207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}