﻿


{"id":229225,"date":"2025-04-02T07:30:13","date_gmt":"2025-04-02T05:30:13","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=229225"},"modified":"2025-04-02T10:45:51","modified_gmt":"2025-04-02T08:45:51","slug":"kenya-abusi-violenza-wycliffe-sorridere","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/","title":{"rendered":"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere"},"content":{"rendered":"<h2>Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d<\/h2>\n<p><!--more--><\/p>\n<p>La madre del piccolo\u00a0<strong>Wycliffe<\/strong>, gravemente dipendente dall\u2019alcool, conduceva una vita instabile, trascinando i figli con s\u00e9 in un vortice di\u00a0<strong>trascuratezza e abuso<\/strong>.<br \/>\nSpesso, i bambini si ritrovavano nei bar notturni mentre la madre, completamente ubriaca, ignorava le loro necessit\u00e0. In alcune occasioni, la donna per farli addormentare arrivava a somministrare ai piccoli\u00a0<strong>alcolici, esponendoli a gravi rischi<\/strong>.<br \/>\nLa situazione era ancora pi\u00f9 drammatica per la\u00a0<strong>sorella di Wycliffe, vittima di abusi da parte degli uomini che frequentavano la madre<\/strong>. In questo clima di totale abbandono, il futuro di Wycliffe sembrava senza speranza.<\/p>\n<h3>L\u2019accoglienza dell\u2019orfanotrofio Shelter Children&#8217;s Home<\/h3>\n<p>Fortunatamente, la\u00a0<strong>segnalazione di una vicina di casa e l\u2019intervento delle autorit\u00e0<\/strong>\u00a0hanno permesso di allontanare Wycliffe e i suoi fratelli da questa situazione pericolosa.<br \/>\nI bambini sono stati accolti presso l\u2019<strong>orfanotrofio Shelter Children&#8217;s Home<\/strong>, che ha offerto loro la protezione, il calore e la sicurezza di cui avevano un disperato bisogno.<\/p>\n<h3>Un percorso di rinascita<\/h3>\n<p>Qui, Wycliffe ha potuto iniziare un\u00a0<strong>percorso di rinascita<\/strong>. Ha avuto accesso all&#8217;istruzione, alla cura e a una quotidianit\u00e0 pi\u00f9 serena, lontano dalle sofferenze del passato.<br \/>\nGrazie al progetto\u00a0<strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong>, il bambino ha potuto proseguire il suo percorso scolastico e\u00a0oggi, che ha\u00a0<strong>dieci anni<\/strong>, frequenta la quinta elementare.<br \/>\nIl diritto all&#8217;istruzione, un tempo irraggiungibile, \u00e8 diventato una realt\u00e0. Il supporto ricevuto gli ha permesso di avere materiali scolastici, cure mediche e tutto ci\u00f2 che \u00e8 necessario per\u00a0<strong>crescere con dignit\u00e0<\/strong>.<br \/>\nNonostante le difficolt\u00e0 economiche, la sorella maggiore di Wycliffe continua a essere una presenza fondamentale nella sua vita. Sebbene non abbia ancora un lavoro stabile, si prende cura di lui ogni volta che pu\u00f2, con la speranza di riuscire un giorno a garantire ai suoi fratelli un futuro migliore.<br \/>\nOggi, Wycliffe \u00e8 un bambino\u00a0<strong>socievole e affettuoso, che ama stare in compagnia dei suoi amici<\/strong>. Il sostegno ricevuto ha avuto un impatto positivo non solo sul suo rendimento scolastico, ma anche sul suo sviluppo emotivo e psicologico. Grazie all&#8217;affetto e alla sicurezza che ha trovato nella sua nuova casa,\u00a0<strong>sta costruendo le basi per un futuro migliore<\/strong>, un sogno che, fino a poco tempo fa, sembrava impossibile da realizzare.<\/p>\n<h3>Come aiutare i bambini abbandonati degli orfanotrofi in Kenya?<\/h3>\n<p><strong>Puoi\u00a0<\/strong>contribuire alle attivit\u00e0 promosse da Ai.Bi. con una donazione,\u00a0<strong>cliccando\u00a0<a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\">qui<\/a><\/strong>.<br \/>\nSe vuoi\u00a0<strong>dare continuit\u00e0 al tuo aiuto, stando vicino\u00a0<\/strong>ogni giorno ai bambini degli orfanotrofi sostenuti da Ai.Bi. e ricevere periodiche notizie e informazioni su di loro, puoi aderire al progetto\u00a0<strong>Sostieni a distanza i bambini di un orfanotrofio<\/strong>.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*214772-start*\/\n#btnsx-214772{margin-top:0px;margin-bottom:15px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-214772 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-214772:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-214772{background-color:#ee7e0d!important;}\n#btnsx-214772:hover{background-color:#ed650b!important;}\n#btnsx-214772{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-214772:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-214772{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-214772:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*214772-end*\/\n<\/style><div id=\"btnsx-214772-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-214772-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-214772\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">ADOTTA A DISTANZA ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Per richiedere informazioni sull\u2019Adozione a Distanza\u00a0<a href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a>.<br \/>\nE ricorda: come ogni donazione, anche le<strong>\u00a0Adozioni a Distanza di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cresciuto in un ambiente segnato dalla&nbsp;povert&agrave; e dalla negligenza, Wycliffe ha avuto un&rsquo;infanzia caratterizzata da&nbsp;privazioni e abusi. Ora, a dieci anni,&nbsp;Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto &ldquo;Sostieni a distanza i bambini di un orfanotrofio&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":229226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[640],"class_list":["post-229225","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-shelter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya. Wycliffe ha imparato a sorridere<\/title>\n<meta name=\"description\" content=\"Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere\" \/>\n<meta property=\"og:description\" content=\"Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-02T05:30:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T08:45:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Kenya-Wycliffe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere\",\"datePublished\":\"2025-04-02T05:30:13+00:00\",\"dateModified\":\"2025-04-02T08:45:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Kenya-Wycliffe.jpg\",\"keywords\":[\"Shelter\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/\",\"name\":\"Kenya. Wycliffe ha imparato a sorridere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Kenya-Wycliffe.jpg\",\"datePublished\":\"2025-04-02T05:30:13+00:00\",\"dateModified\":\"2025-04-02T08:45:51+00:00\",\"description\":\"Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Kenya-Wycliffe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Kenya-Wycliffe.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abusi-violenza-wycliffe-sorridere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya. Wycliffe ha imparato a sorridere","description":"Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere","og_description":"Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d","og_url":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-04-02T05:30:13+00:00","article_modified_time":"2025-04-02T08:45:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Kenya-Wycliffe.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere","datePublished":"2025-04-02T05:30:13+00:00","dateModified":"2025-04-02T08:45:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/"},"wordCount":518,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Kenya-Wycliffe.jpg","keywords":["Shelter"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/","url":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/","name":"Kenya. Wycliffe ha imparato a sorridere","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Kenya-Wycliffe.jpg","datePublished":"2025-04-02T05:30:13+00:00","dateModified":"2025-04-02T08:45:51+00:00","description":"Cresciuto in un ambiente segnato dalla\u00a0povert\u00e0 e dalla negligenza, Wycliffe ha avuto un\u2019infanzia caratterizzata da\u00a0privazioni e abusi. Ora, a dieci anni,\u00a0Wycliffe ha trovato protezione, amicizia e speranza grazie al progetto \u201cSostieni a distanza i bambini di un orfanotrofio\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Kenya-Wycliffe.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Kenya-Wycliffe.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-abusi-violenza-wycliffe-sorridere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. Strappato da un vortice di abusi e violenza, ora Wycliffe ha imparato a sorridere"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:38:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=229225"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/229226"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=229225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=229225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=229225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}