﻿


{"id":229551,"date":"2025-04-17T07:30:35","date_gmt":"2025-04-17T05:30:35","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=229551"},"modified":"2025-04-17T13:53:41","modified_gmt":"2025-04-17T11:53:41","slug":"fame-di-mamma-gioco-attenzione-autostima-ritrovata","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/","title":{"rendered":"Fame di Mamma. Il gioco, l&#8217;attenzione e l&#8217;autostima ritrovata&#8230; Per cambiare il corso di due vite!"},"content":{"rendered":"<h2>La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l&#8217;ascolto e l&#8217;attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0<\/h2>\n<p><!--more--><\/p>\n<p>Qualche tempo fa, <strong>Antoine de Saint Exupery<\/strong> (l&#8217;autore del libro <strong>Il piccolo principe<\/strong>)scrisse: \u201cTutti siamo stati bambini, ma pochi da adulti se ne ricordano.\u201d<br \/>\nNel frenetico vivere, sperimentiamo spesso quanto queste parole siano vere. I momenti per ritrovare quella spensieratezza tipica dell\u2019infanzia \u2013 quando la fantasia ci permetteva di trasformare i cuscini del divano nei vagoni di un treno o una pentola capovolta in una batteria rock \u2013 sono sempre pi\u00f9 rari. E ancor pi\u00f9 rari sono i momenti in cui\u00a0<strong>riusciamo a riconoscere e valorizzare la creativit\u00e0 dei pi\u00f9 piccoli<\/strong>, che siano figli, alunni, nipoti o semplicemente bambini del nostro quartiere.<\/p>\n<h3>Attivit\u00e0 ludico-ricreative<\/h3>\n<p>Consapevoli\u00a0<strong>dell\u2019importanza che la creativit\u00e0 ha nello sviluppo dell\u2019autostima<\/strong>, nelle comunit\u00e0 familiri sostenute dai progetti\u00a0<strong>Fame di Mamma<\/strong>\u00a0dedichiamo ampio spazio ad attivit\u00e0 ludico-ricreative e affianchiamo le mamme nel riconoscere quanto sia fondamentale coltivare l\u2019immaginazione dei loro bambini. Crediamo fermamente che rafforzare l\u2019autostima fin da piccoli sia un passo essenziale verso una crescita serena e consapevole.<br \/>\nPotremmo raccontarvi di come abbiamo allestito i nostri saloni con spazi ampi per il gioco, tavolini adatti anche ai pi\u00f9 piccini e materiali vari a disposizione. Ma preferiamo soffermarci su quello che riteniamo lo strumento pi\u00f9 prezioso per stimolare la creativit\u00e0:\u00a0<strong>la partecipazione attenta e rispettosa degli adulti<\/strong>\u00a0\u2013 genitori o educatori che siano.<\/p>\n<h3>La storia di Marco e di sua mamma Giada<\/h3>\n<p>\u00c8 il caso di Marco, un bambino che da pochissimo ha compiuto tre anni. Marco \u00e8 arrivato in comunit\u00e0 con la sua mamma, Giada, circa un anno fa. All\u2019inizio era silenzioso, non riusciva a giocare con gli altri e spesso\u00a0<strong>piangeva per attirare l\u2019attenzione della madre<\/strong>. Giada, segnata da una storia personale di gravi trascuratezze e difficolt\u00e0 familiari, faticava a riconoscere i segnali del figlio, interpretandoli come semplici \u201ccapricci\u201d, alimentando cos\u00ec la frustrazione del piccolo.<br \/>\nCon il tempo, grazie alla pazienza delle educatrici, si \u00e8 instaurata una relazione di fiducia con Giada, che ha cominciato a guardare ai propri limiti non pi\u00f9 con giudizio ma\u00a0<strong>con apertura e desiderio di miglioramento<\/strong>. Ci ha raccontato di come da bambina le fosse stato negato lo spazio per giocare: era dovuta crescere in fretta, occupandosi dei fratelli pi\u00f9 piccoli mentre i genitori lottavano con problemi di alcolismo. Eppure, ricordava quanto amasse disegnare e cantare.<br \/>\nPartendo da queste passioni dimenticate,\u00a0<strong>Giada ha riscoperto la gioia del gioco condiviso<\/strong>. Inizialmente un po\u2019 imbarazzata, ha imparato a sedersi con Marco e colorare insieme. Dapprima disegni prestampati, poi fogli bianchi da riempire solo con la fantasia. Ha rispolverato un piccolo\u00a0<strong>Canta Tu\u00a0<\/strong>per bambini, e ha iniziato a fare musica con il figlio. Giorno dopo giorno, quel momento creativo \u00e8 diventato anche\u00a0<strong>uno spazio di relazione<\/strong>.<\/p>\n<h3>Ascoltare il cuore<\/h3>\n<p>Un giorno, mentre erano in salone per cantare, Marco ha sorpreso tutti con la sua fantasia. Ha staccato il microfono dal supporto, se l\u2019\u00e8 messo al collo e ha detto: \u201cMamma, guarda, sono una dottoressa\u2026 anzi, un dottore!\u201d. Giada ha colto al volo il gioco e gli ha chiesto se voleva ascoltarle il battito del cuore. Cos\u00ec, in un attimo, la lezione di canto si \u00e8 trasformata in una sessione medica giocosa: Marco ha auscultato il cuore della mamma, degli altri bambini e dell\u2019educatrice. Alla fine, con soddisfazione, ha detto: \u201c<strong>Stiamo tutti bene\u2026 adesso andiamo a cantare!<\/strong>\u201d. Tutti abbiamo sorriso, e gli abbiamo confermato che, grazie alle sue cure, avremmo cantato ancora meglio.<br \/>\nGiada, emozionata, ha confidato all\u2019educatrice quanto fosse felice di vedere i progressi di Marco, non solo nel gioco ma anche nel linguaggio e nelle relazioni con gli altri bambini. Un po\u2019 commossa, ha riflettuto su come sarebbe stata diversa la sua infanzia se qualcuno avesse saputo riconoscere i suoi bisogni. Ma con forza e determinazione\u00a0<strong>ha dichiarato il suo impegno a garantire a Marco tutto ci\u00f2 che lei non ha avuto<\/strong>: ascolto, attenzione, libert\u00e0 di esprimersi e crescere felice.<br \/>\nQuesta determinazione di Giada \u00e8 anche la nostra. Come operatori, vogliamo continuare a\u00a0<strong>garantire alle famiglie che accogliamo tempo, ascolto e opportunit\u00e0 per scoprire i propri talenti<\/strong>\u00a0nascosti, rafforzare la propria autostima e sentirsi degni di amore e di un futuro migliore.<\/p>\n<h3>Sostieni il progetto \u201cFame\u00a0di\u00a0Mamma\u201d<\/h3>\n<p>Grazie ai sostenitori a distanza del progetto \u201cFame\u00a0di\u00a0Mamma\u201d, Ai.Bi. pu\u00f2 aiutare nelle sue comunit\u00e0 molti minori bisognosi\u00a0di\u00a0aiuto.<br \/>\nDiventa anche tu un sostenitore: puoi farlo con una donazione, cliccando\u00a0<a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;caus=3784\"><strong>QUI<\/strong><\/a>, o con un contributo\u00a0di\u00a0<strong>10 euro al mese,<\/strong>\u00a0aderendo al progetto\u00a0di\u00a0<strong>Adozione a Distanza \u201cFame\u00a0di\u00a0Mamma\u201d<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La storia di Giada e Marco ci insegna che non &egrave; mai troppo tardi per riscoprire la propria creativit&agrave;, e che attraverso il gioco condiviso, l&rsquo;ascolto e l&rsquo;attenzione si pu&ograve; guarire il passato e costruire legami nuovi, forti e pieni di possibilit&agrave;<\/p>\n","protected":false},"author":133,"featured_media":229552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[608],"class_list":["post-229551","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-fame-di-mamma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fame di Mamma. Il gioco, l&#039;attenzione e l&#039;autostima ritrovata...<\/title>\n<meta name=\"description\" content=\"La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l&#039;ascolto e l&#039;attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fame di Mamma. Il gioco, l&#039;attenzione e l&#039;autostima ritrovata... Per cambiare il corso di due vite!\" \/>\n<meta property=\"og:description\" content=\"La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l&#039;ascolto e l&#039;attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-17T05:30:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-17T11:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Fame-di-Mamma-gioco-creativita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Fame di Mamma. Il gioco, l&#8217;attenzione e l&#8217;autostima ritrovata&#8230; Per cambiare il corso di due vite!\",\"datePublished\":\"2025-04-17T05:30:35+00:00\",\"dateModified\":\"2025-04-17T11:53:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/\"},\"wordCount\":800,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Fame-di-Mamma-gioco-creativita.jpg\",\"keywords\":[\"Fame di mamma\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/\",\"name\":\"Fame di Mamma. Il gioco, l'attenzione e l'autostima ritrovata...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Fame-di-Mamma-gioco-creativita.jpg\",\"datePublished\":\"2025-04-17T05:30:35+00:00\",\"dateModified\":\"2025-04-17T11:53:41+00:00\",\"description\":\"La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l'ascolto e l'attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Fame-di-Mamma-gioco-creativita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Fame-di-Mamma-gioco-creativita.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fame di Mamma. Il gioco, l&#8217;attenzione e l&#8217;autostima ritrovata&#8230; Per cambiare il corso di due vite!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fame di Mamma. Il gioco, l'attenzione e l'autostima ritrovata...","description":"La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l'ascolto e l'attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/","og_locale":"it_IT","og_type":"article","og_title":"Fame di Mamma. Il gioco, l'attenzione e l'autostima ritrovata... Per cambiare il corso di due vite!","og_description":"La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l'ascolto e l'attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-04-17T05:30:35+00:00","article_modified_time":"2025-04-17T11:53:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Fame-di-Mamma-gioco-creativita.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Fame di Mamma. Il gioco, l&#8217;attenzione e l&#8217;autostima ritrovata&#8230; Per cambiare il corso di due vite!","datePublished":"2025-04-17T05:30:35+00:00","dateModified":"2025-04-17T11:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/"},"wordCount":800,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Fame-di-Mamma-gioco-creativita.jpg","keywords":["Fame di mamma"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/","url":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/","name":"Fame di Mamma. Il gioco, l'attenzione e l'autostima ritrovata...","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Fame-di-Mamma-gioco-creativita.jpg","datePublished":"2025-04-17T05:30:35+00:00","dateModified":"2025-04-17T11:53:41+00:00","description":"La storia di Giada e Marco ci insegna che non \u00e8 mai troppo tardi per riscoprire la propria creativit\u00e0, e che attraverso il gioco condiviso, l'ascolto e l'attenzione si pu\u00f2 guarire il passato e costruire legami nuovi, forti e pieni di possibilit\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Fame-di-Mamma-gioco-creativita.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Fame-di-Mamma-gioco-creativita.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-gioco-attenzione-autostima-ritrovata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Fame di Mamma. Il gioco, l&#8217;attenzione e l&#8217;autostima ritrovata&#8230; Per cambiare il corso di due vite!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:05:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=229551"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/229552"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=229551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=229551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=229551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}