﻿


{"id":229927,"date":"2025-04-30T07:40:03","date_gmt":"2025-04-30T05:40:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=229927"},"modified":"2025-04-30T17:03:16","modified_gmt":"2025-04-30T15:03:16","slug":"adottare-consapevolmente-corso-preidoneita-alladozione-internazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/","title":{"rendered":"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single"},"content":{"rendered":"<h2>Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione<\/h2>\n<p><!--more--><\/p>\n<p>Il 13\u00a0maggio\u00a0alle ore 18:30 prender\u00e0 il via il nuovo\u00a0<strong>corso online di preidoneit\u00e0 all\u2019Adozione Internazionale<\/strong>, pensato per accompagnare aspiranti genitori adottivi \u2013 coppie coniugate o single \u2013 nel delicato e fondamentale cammino verso l\u2019incontro con il proprio futuro figlio.<\/p>\n<h3>Un camminino consapevole verso l\u2019idoneit\u00e0<\/h3>\n<p>Promosso da\u00a0<strong>Ai.Bi. Amici dei Bambini<\/strong>, attraverso la sua\u00a0<strong>Fondazione FARIS<\/strong>, il corso si rivolge a chi ha recentemente depositato, o \u00e8 in procinto di depositare, la\u00a0<strong>disponibilit\u00e0 all\u2019adozione internazionale<\/strong>\u00a0presso il Tribunale per i Minorenni. L\u2019obiettivo \u00e8 offrire uno spazio concreto di formazione e confronto, che metta al centro la realt\u00e0 dei bambini in attesa di famiglia.<br \/>\nIl programma si articola in cinque moduli che affrontano con profondit\u00e0 temi cruciali: il vissuto dei minori abbandonati, le cause dell\u2019abbandono, i meccanismi dell\u2019abbinamento e le caratteristiche richieste agli adottanti. Si parler\u00e0 anche delle diverse procedure adottive nei vari Paesi, con il contributo di operatori esperti e psicologhe specializzate. Un\u2019attenzione particolare sar\u00e0 riservata alla\u00a0<strong>preparazione emotiva dei genitori<\/strong>, culminando in un weekend intensivo durante il quale i partecipanti vivranno esercitazioni e attivit\u00e0 di gruppo volte a rafforzare la consapevolezza di s\u00e9 e del bambino reale che incontreranno.<br \/>\nIl corso, che si concluder\u00e0 il 25 maggio, prevede sei incontri distribuiti su due settimane e\u00a0<strong>rilascer\u00e0 un attestato di partecipazione<\/strong>. La docenza \u00e8 affidata a\u00a0<strong>Lorenza Persona<\/strong>, Desk Officer Adozioni Internazionali per Amici dei Bambini.<\/p>\n<h3>Informazioni<\/h3>\n<p><strong>NUOVO CORSO online di preidoneit\u00e0 all\u2019Adozione Internazionale<br \/>\n<\/strong>13\u00a0Maggio &#8211; 18:30<br \/>\nPer dettagli e iscrizioni, clicca <strong><a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/nuovo-corso-online-di-preidoneita-alladozione-internazionale\/\">qui<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ideato per chi intende avviare (o ha gi&agrave; avviato) il percorso per ottenere l&rsquo;idoneit&agrave; alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione<\/p>\n","protected":false},"author":133,"featured_media":229928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[718],"class_list":["post-229927","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Parte il corso di preidoneit\u00e0 all\u2019Adozione Internazionale<\/title>\n<meta name=\"description\" content=\"Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single\" \/>\n<meta property=\"og:description\" content=\"Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-30T05:40:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T15:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Corso-adozione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single\",\"datePublished\":\"2025-04-30T05:40:03+00:00\",\"dateModified\":\"2025-04-30T15:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/\"},\"wordCount\":298,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Corso-adozione.jpg\",\"keywords\":[\"Webinar\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/\",\"name\":\"Parte il corso di preidoneit\u00e0 all\u2019Adozione Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Corso-adozione.jpg\",\"datePublished\":\"2025-04-30T05:40:03+00:00\",\"dateModified\":\"2025-04-30T15:03:16+00:00\",\"description\":\"Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Corso-adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/04\\\/Corso-adozione.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Parte il corso di preidoneit\u00e0 all\u2019Adozione Internazionale","description":"Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single","og_description":"Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione","og_url":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-04-30T05:40:03+00:00","article_modified_time":"2025-04-30T15:03:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Corso-adozione.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single","datePublished":"2025-04-30T05:40:03+00:00","dateModified":"2025-04-30T15:03:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/"},"wordCount":298,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Corso-adozione.jpg","keywords":["Webinar"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/","url":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/","name":"Parte il corso di preidoneit\u00e0 all\u2019Adozione Internazionale","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Corso-adozione.jpg","datePublished":"2025-04-30T05:40:03+00:00","dateModified":"2025-04-30T15:03:16+00:00","description":"Ideato per chi intende avviare (o ha gi\u00e0 avviato) il percorso per ottenere l\u2019idoneit\u00e0 alla adozione internazionale, dal 13 maggio prende il via un nuovo corso strutturato su sei appuntamenti online, fra cui un intero weekend di formazione","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Corso-adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/04\/Corso-adozione.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adottare-consapevolmente-corso-preidoneita-alladozione-internazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adottare consapevolmente: parte un nuovo corso di preidoneit\u00e0 all\u2019Adozione Internazionale aperto anche ai single"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:40:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=229927"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/229927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/229928"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=229927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=229927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=229927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}