﻿{"id":230234,"date":"2025-05-15T11:30:50","date_gmt":"2025-05-15T09:30:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=230234"},"modified":"2025-05-17T16:57:24","modified_gmt":"2025-05-17T14:57:24","slug":"giornata-internazionale-famiglia-legami-sangue-genitori","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/","title":{"rendered":"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori"},"content":{"rendered":"<div>\n<h2>Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza<\/h2>\n<\/div>\n<p><!--more--><strong>Giorgia e Simone<\/strong>\u00a0si sono incontrati da giovani, tra le fila degli scout del Cuneese, dove hanno imparato il valore del servizio, dell\u2019ascolto e dell\u2019accoglienza.<br \/>\nUna volta diventati coppia, hanno scelto di trasformare questi valori in un progetto di vita:\u00a0<strong>diventare una famiglia affidataria, ancor prima di sposarsi<\/strong>. Una scelta controcorrente, mossa da una consapevolezza profonda: la genitorialit\u00e0 non \u00e8 solo biologica, ma soprattutto un dono che si fa.<\/p>\n<h3>Un affido che si trasforma in adozione<\/h3>\n<p>Nel 2017 si sposano, gi\u00e0 preparati e motivati all\u2019affido. Dopo essersi trasferiti a Varese per lavoro \u2013 lei ricercatrice, lui operatore sanitario \u2013 incontrano una rete di servizi sociali pronta ad accogliere il loro entusiasmo. La vita, per\u00f2, li sorprende: desideravano accogliere ragazzi pi\u00f9 grandi, ma la prima proposta riguarda un bambino di appena un anno e mezzo. Marco entra nelle loro vite con delicatezza e bisogno. Cinque anni dopo, quell\u2019<strong>affido si trasforma in adozione<\/strong>. Un atto d\u2019amore pieno, costruito giorno dopo giorno.<\/p>\n<h3>Diventare una famiglia ponte<\/h3>\n<p>Nel frattempo, diventano anche\u00a0<strong>famiglia ponte<\/strong>, accogliendo temporaneamente un neonato, poi accompagnato verso la sua famiglia adottiva. A\u00a0marzo\u00a0dello scorso anno, arriva Kevin, due anni e tre mesi. Un nuovo affido, con una sfida diversa: i genitori biologici sono ancora presenti e partecipano al percorso. Una relazione a quattro, fatta di rispetto, presenza e collaborazione. Marco,\u00a0oggi\u00a0pi\u00f9 grande, accoglie Kevin con entusiasmo e tenerezza: per\u00a0Natale\u00a0vuole che anche Babbo\u00a0Natale\u00a0sappia che in casa ora sono in due.<\/p>\n<h3>Aprirsi all\u2019affido<\/h3>\n<p>Oggi\u00a0Giorgia e Simone raccontano con sincerit\u00e0 cosa significhi aprirsi all\u2019affido: &#8221;\u00a0Cosa ci sentiamo di dire a un\u2019altra coppia che medita di aprirsi all\u2019affido? Che l\u2019accoglienza \u00e8 un servizio impegnativo che non \u00e8 obbligatoriamente nelle corde di tutte le persone. Per qualcuno potrebbe non essere semplice. Certo, nel momento in cui c\u2019\u00e8 la forza della coppia e la consapevolezza che lo sforzo viene fatto per il bene del bambino e di una famiglia fragile, alla fine le risorse interiori si trovano&#8221;.<br \/>\nL\u2019affido ha fatto crescere anche loro: &#8220;<strong>Aprirsi all\u2019affido<\/strong>\u00a0vuol dire costruire una famiglia pi\u00f9 ampia e con qualche responsabilit\u00e0 in pi\u00f9 rispetto a un nucleo familiare tradizionale. Ma \u00e8 una bella sfida, ne vale la pena&#8221;.<\/p>\n<p><strong>[Fonte: Avvenire]<\/strong><\/p>\n<h3><strong>Informazioni e richieste sull\u2019affido familiare<\/strong><\/h3>\n<p>Raccontare la storia di Giorgia e Simone \u00e8 un modo per celebrare la Giornata Internazionale della Famiglia, istituita dall&#8217;ONU nel 1993.\u00a0Lo \u00e8 perch\u00e9 la loro storia non solo \u00e8\u00a0straordinaria di per s\u00e9, ma lo \u00e8 a maggior ragione se si pensa a\u00a0<strong>quanta fatica si faccia,\u00a0oggi, a trovare coppie e single disponibili all&#8217;affido<\/strong>. Anche in questo campo, i bambini che avrebbero bisogno di una famiglia sono molti di pi\u00f9 delle famiglie pronte ad accoglierli, con la conseguenza che, magari per anni, questi minori rimangono in comunit\u00e0. Comunit\u00e0 che fanno di tutto per non far mancare niente ai bambini e per costruire attorno a loro un cammino che guardi al futuro, ma che mai, pur con tutt la buona volont\u00e0 del mondo, potranno sostituire l&#8217;affetto, la cura e l&#8217;accoglienza che solo una famiglia &#8220;vera&#8221; pu\u00f2 dare.<br \/>\nPer questo,\u00a0oggi\u00a0pi\u00f9 che mai, rinnoviamo l&#8217;appello a chiunque volesse approfondire la conoscenza dell\u2019<strong>affido familiare\u00a0<\/strong>e riflettere sulla propria disponibilit\u00e0 a\u00a0<strong>intraprendere questo percorso<\/strong>, di partecipare agli\u00a0<strong>incontri organizzati da Ai.Bi. Amici ei Bambini<\/strong>\u00a0Tutte le informazioni si trovano alla\u00a0<a href=\"http:\/\/www.aibi.it\/affido\"><strong>pagina dedicata<\/strong><\/a>\u00a0del sito dell\u2019Associazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull&rsquo;accoglienza<\/p>\n","protected":false},"author":133,"featured_media":230235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320],"class_list":["post-230234","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Non servono legami di sangue per essere genitori<\/title>\n<meta name=\"description\" content=\"Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori\" \/>\n<meta property=\"og:description\" content=\"Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T09:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T14:57:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/affido-adozione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori\",\"datePublished\":\"2025-05-15T09:30:50+00:00\",\"dateModified\":\"2025-05-17T14:57:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/\"},\"wordCount\":608,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/affido-adozione.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/\",\"name\":\"Non servono legami di sangue per essere genitori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/affido-adozione.jpg\",\"datePublished\":\"2025-05-15T09:30:50+00:00\",\"dateModified\":\"2025-05-17T14:57:24+00:00\",\"description\":\"Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/affido-adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/affido-adozione.jpg\",\"width\":900,\"height\":473},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-internazionale-famiglia-legami-sangue-genitori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Non servono legami di sangue per essere genitori","description":"Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori","og_description":"Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza","og_url":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-05-15T09:30:50+00:00","article_modified_time":"2025-05-17T14:57:24+00:00","og_image":[{"width":900,"height":473,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/affido-adozione.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori","datePublished":"2025-05-15T09:30:50+00:00","dateModified":"2025-05-17T14:57:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/"},"wordCount":608,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/affido-adozione.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/","url":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/","name":"Non servono legami di sangue per essere genitori","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/affido-adozione.jpg","datePublished":"2025-05-15T09:30:50+00:00","dateModified":"2025-05-17T14:57:24+00:00","description":"Un figlio adottato, uno in affido, un neonato ospitato per un mese: nel giorno che celebra la famiglia, la storia di una coppia che ha costruito la propria sul dono e sull\u2019accoglienza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/affido-adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/affido-adozione.jpg","width":900,"height":473},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/giornata-internazionale-famiglia-legami-sangue-genitori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Giornata Internazionale della Famiglia. Non servono legami di sangue per essere genitori"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:13:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/230234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=230234"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/230234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/230235"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=230234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=230234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=230234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}