﻿


{"id":230433,"date":"2025-05-24T17:00:21","date_gmt":"2025-05-24T15:00:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=230433"},"modified":"2025-05-23T09:11:42","modified_gmt":"2025-05-23T07:11:42","slug":"adozione-internazionale-jhon-tornare-figlio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/","title":{"rendered":"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio"},"content":{"rendered":"<h2>La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon, dalla Colombia, ai suoi genitori. Per ricongiungere una splendida famiglia che da oggi cammina insieme verso il futuro<\/h2>\n<p><!--more--><\/p>\n<p>La cicogna di Ai.Bi. \u00e8 una tipa precisa. Entusiasta e inarrestabile quando si tratta di partire per andare a prendere un nuovo \u201cfiglio\u201d, ma sempre molto professionale e attenta a tutti i dettagli. Aggiungete che sulle ali, ormai, ha <strong>pi\u00f9 di 40 anni<\/strong>\u2026 e capirete perch\u00e9, appena tornata dal viaggio dal Per\u00f9, <a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-scavalca-oceano-fabrizio\/\">insieme a Fabrizio<\/a>, ha dato un occhio a Google prima di rimettersi subito in viaggio per <strong>andare a prendere Jhon, in Colombia<\/strong>. Obiettivo della ricerca internet: dare un\u2019ultima controllata alla rotta, scoprendo, cos\u00ec, che se per arrivare a Lima, dall\u2019Italia, i km erano stati 10.600 (all\u2019incirca), per raggiungere <strong>Bogot\u00e0<\/strong> sono \u201csolo\u201d 9.100. Una passeggiata, insomma. O qualunque sia la parola per dire \u201cpasseggiata\u201d quando si usano le ali al posto delle gambe.<\/p>\n<h3>Un viaggio al ritmo del cuore<\/h3>\n<p>Che, poi, quando hai con te un bambino da portare ai suoi nuovi genitori, i km da percorrere sono l\u2019ultima cosa che interessa. Perch\u00e9 la cicogna di Amici dei Bambini, cos\u00ec come tutti i genitori che portano a termine un\u2019adozione e i loro figli che li attendono da sempre, non contano lo spazio in chilometri, ma piuttosto <strong>in sospiri e in battiti del cuore<\/strong>. Quei battiti che a volte sembrano quasi fermarsi, quando il telefono non squilla e una risposta tanto attesa non arriva, e che invece, ora, si susseguono sempre pi\u00f9 forte, uno dopo l\u2019altro, mentre la cicogna e il piccolo Jhon si avvicinano.<br \/>\nPerch\u00e9 quando il volo termina, con il pi\u00f9 bello degli abbracci, in quel momento i chilometri, le rotte, i sospiri e i battiti del cuore non diventano che un indistinto sottofondo, <strong>travolto dalla felicit\u00e0 di un incontro che \u00e8 per sempre<\/strong>. Che \u00e8 famiglia. Che \u00e8 vita!<br \/>\nBenvenuto, piccolo Jhon, e un abbraccio ai tuoi genitori, che potranno tornare, oggi, a misurare in metri e centimetri la distanza che li separa da te ogni volta che non sarete mano nella mano.<br \/>\nE per la cicogna di Ai.Bi\u2026 un piccolo aiuto! Dal Brasile ti stanno gi\u00e0 aspettando: sono pi\u00f9 o meno 9.900 chilometri. <strong>Puoi partire subito, senza controllare Google<\/strong>. Ci sono altri cuori da far battere sempre pi\u00f9 velocemente!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cicogna di Amici dei Bambini &egrave; tornata a sorvolare l&rsquo;oceano per portare il piccolo Jhon, dalla Colombia, ai suoi genitori. Per ricongiungere una splendida famiglia che da oggi cammina insieme verso il futuro<\/p>\n","protected":false},"author":102,"featured_media":230435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[],"class_list":["post-230433","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale. Jhon: 9mila km per tornare figlio<\/title>\n<meta name=\"description\" content=\"Adozione Internazionale. La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon dalla Colombia ai suoi genitori\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio\" \/>\n<meta property=\"og:description\" content=\"Adozione Internazionale. La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon dalla Colombia ai suoi genitori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-24T15:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio\",\"datePublished\":\"2025-05-24T15:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/\"},\"wordCount\":402,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg\",\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/\",\"name\":\"Adozione Internazionale. Jhon: 9mila km per tornare figlio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg\",\"datePublished\":\"2025-05-24T15:00:21+00:00\",\"description\":\"Adozione Internazionale. La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon dalla Colombia ai suoi genitori\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/05\\\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-jhon-tornare-figlio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale. Jhon: 9mila km per tornare figlio","description":"Adozione Internazionale. La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon dalla Colombia ai suoi genitori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio","og_description":"Adozione Internazionale. La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon dalla Colombia ai suoi genitori","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-05-24T15:00:21+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio","datePublished":"2025-05-24T15:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/"},"wordCount":402,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg","articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/","name":"Adozione Internazionale. Jhon: 9mila km per tornare figlio","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg","datePublished":"2025-05-24T15:00:21+00:00","description":"Adozione Internazionale. La cicogna di Amici dei Bambini \u00e8 tornata a sorvolare l\u2019oceano per portare il piccolo Jhon dalla Colombia ai suoi genitori","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/05\/Jhon-Colombia-24-mag-2025-NEWS-1200x630-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-jhon-tornare-figlio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale. Jhon: 9mila km e un battito di cuore per tornare a essere figlio"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:57:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/230433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=230433"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/230433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/230435"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=230433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=230433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=230433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}