﻿


{"id":230912,"date":"2025-06-14T07:50:37","date_gmt":"2025-06-14T05:50:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=230912"},"modified":"2025-06-12T08:41:48","modified_gmt":"2025-06-12T06:41:48","slug":"aibiweek-speciale-adozione-burundi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/","title":{"rendered":"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo &#8220;speciale&#8221; sull&#8217;Adozione in Burundi"},"content":{"rendered":"<h2>Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi<\/h2>\n<p><!--more--><\/p>\n<h3>Marted\u00ec 17 giugno<\/h3>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Primi passi nel mondo dell\u2019Adozione Internazionale<br \/>\nOre: 15<br \/>\n<\/strong>Il webinar risponde all\u2019esigenza di dare alle persone, coppie coniugate e single che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione.<br \/>\nObiettivi: dare ai partecipanti gli strumenti per presentare domanda di idoneit\u00e0 per diventare genitori adottivi sia a livello nazionale che a livello internazionale.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-primi-passi-nel-mondo-delladozione-internazionale-2\/\"><strong>qui<\/strong><\/a>.<\/p>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Dove tutto comincia: lo spazio dell\u2019incontro adottivo, tra attese, emozioni e prime connessioni<br \/>\nOre: 18.30<br \/>\n<\/strong>L\u2019incontro tra i bambini e i genitori adottivi rappresenta uno snodo centrale nel percorso dell\u2019adozione: non solo un evento, ma un tempo denso, carico di emozioni, aspettative, paure e desideri.<br \/>\n\u00c8 un passaggio simbolico e concreto in cui due storie si avvicinano, uno spazio in cui l\u2019altro si disvela e comincia il lavoro di costruzione delle relazioni. Il seminario vuole approfondire le caratteristiche del primo incontro, per accompagnare i futuri genitori in questa fase fondamentale, in grado di influenzare il processo di adattamento e di costruzione di un nuovo legame familiare.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-dove-tutto-comincia-lo-spazio-dellincontro-adottivo-tra-attese-emozioni-e-prime-connessioni\/\"><strong>qui<\/strong><\/a>.<\/p>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Informativo tecnico sull\u2019essere genitori affidatari<br \/>\nOre: 21<br \/>\n<\/strong>Il webinar \u00e8 rivolto a tutte le persone interessate all\u2019affidamento familiare (single, coppie, famiglie) che vorrebbero diventare una famiglia affidataria.<br \/>\nEssere genitore affidatario \u00e8 un\u2019avventura sicuramente affascinante ma che richiede un percorso di preparazione e tanto confronto con le altre famiglie affidatarie. Infatti, attraverso la formazione e lo scambio di esperienze, si pu\u00f2 fare una scelta pi\u00f9 consapevole per capire se e quando possiamo essere una risorsa per questi bambini e ragazzi.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-tecnico-sullessere-genitori-affidatari\/\"><strong>qui<\/strong><\/a>.<\/p>\n<h3>Mercoled\u00ec 18 giugno<\/h3>\n<p><strong>Adozione Internazionale in Burundi (primo incontro informativo)<br \/>\nOn Line<br \/>\nOre 17<\/strong><br \/>\nSolo per coppie gi\u00e0 in possesso del decreto di idoneit\u00e0.<br \/>\nAmici dei Bambini organizza incontri informativi di gruppo gratuiti, per le coppie che desiderano approfondire la conoscenza dell\u2019adozione internazionale, dell\u2019associazione e delle procedure di adozione. Gli incontri hanno una durata di 4 ore, sono condotti da un operatore di Amici dei Bambini e prevedono la testimonianza di una famiglia adottiva. La partecipazione all\u2019incontro di entrambi i coniugi \u00e8 obbligatoria per le coppie che intendono conferire mandato ad Ai.Bi. Sono aperti alle coppie che hanno concluso il percorso con i Servizi o gi\u00e0 in possesso del decreto di idoneit\u00e0.<br \/>\nIn questo incontro, in particolare, il focus sar\u00e0 sul Burundi, piccolo Paese dell\u2019Africa centrale dove l\u2019emergenza abbandono si fa sentire in particolar modo e il bisogno di coppie aperte e disponibili all\u2019adozione \u00e8 alto.<br \/>\nPer informazioni e iscrizioni:\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-su-come-aprire-una-casa-famiglia-per-minori\/\"><strong>QUI<\/strong><\/a>.<\/p>\n<h3>Gioved\u00ec 19 giugno<\/h3>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nWEBINAR Informativo su come aprire una casa famiglia per minori<br \/>\nOre: 18.30<br \/>\n<\/strong>Nel webinar verranno approfondite le specificit\u00e0 che l\u2019inizio di un progetto familiare di questo genere comportano, verr\u00e0, in particolare, sottolineata la differenza con l\u2019istituto dell\u2019affido familiare. Tutto ci\u00f2 al fine di dare stimolo e maggiore consapevolezza all\u2019eventuale discernimento di coloro i quali partecipano al webinar.<br \/>\nVerranno indicati anche gli eventuali \u201cprossimi passi\u201d per chi volesse approfondire il percorso informativo e formativo verso l\u2019apertura della casa famiglia.<br \/>\nPer maggiori informazioni, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-su-come-aprire-una-casa-famiglia-per-minori\/\"><strong>qui<\/strong><\/a>.<\/p>\n<h3>Sabato 21 giugno<strong><br \/>\n<\/strong><\/h3>\n<p><strong>Ai.Bi. sede di Mestre<\/strong><br \/>\n<strong>L\u2019incontro con l\u2019Adozione Internazionale (primo incontro informativo)<br \/>\nOn Line<br \/>\nOre 9.30<\/strong><br \/>\nSolo per coppie gi\u00e0 in possesso del decreto di idoneit\u00e0.<br \/>\nAmici dei Bambini organizza incontri informativi di gruppo gratuiti, per le coppie che desiderano approfondire la conoscenza dell\u2019adozione internazionale, dell\u2019associazione e delle procedure di adozione. Gli incontri hanno una durata di 4 ore, sono condotti da un operatore di Amici dei Bambini e prevedono la testimonianza di una famiglia adottiva. La partecipazione all\u2019incontro di entrambi i coniugi \u00e8 obbligatoria per le coppie che intendono conferire mandato ad Ai.Bi. Sono aperti alle coppie che hanno concluso il percorso con i Servizi o gi\u00e0 in possesso del decreto di idoneit\u00e0.<br \/>\nPer informazioni e iscrizioni:\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-su-come-aprire-una-casa-famiglia-per-minori\/\"><strong>QUI<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno&nbsp;per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi&ugrave;, un focus speciale sull&rsquo;adozione in Burundi<\/p>\n","protected":false},"author":133,"featured_media":230914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[781],"class_list":["post-230912","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-aibiweek"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AibiWeek. Lo &quot;speciale&quot; sull&#039;Adozione in Burundi<\/title>\n<meta name=\"description\" content=\"Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo &quot;speciale&quot; sull&#039;Adozione in Burundi\" \/>\n<meta property=\"og:description\" content=\"Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-14T05:50:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/AibiWeek-14-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo &#8220;speciale&#8221; sull&#8217;Adozione in Burundi\",\"datePublished\":\"2025-06-14T05:50:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/\"},\"wordCount\":712,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/AibiWeek-14-06.jpg\",\"keywords\":[\"AIBIweek\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/\",\"name\":\"AibiWeek. Lo \\\"speciale\\\" sull'Adozione in Burundi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/AibiWeek-14-06.jpg\",\"datePublished\":\"2025-06-14T05:50:37+00:00\",\"description\":\"Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/AibiWeek-14-06.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/AibiWeek-14-06.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aibiweek-speciale-adozione-burundi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo &#8220;speciale&#8221; sull&#8217;Adozione in Burundi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AibiWeek. Lo \"speciale\" sull'Adozione in Burundi","description":"Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/","og_locale":"it_IT","og_type":"article","og_title":"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo \"speciale\" sull'Adozione in Burundi","og_description":"Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi","og_url":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-06-14T05:50:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/AibiWeek-14-06.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo &#8220;speciale&#8221; sull&#8217;Adozione in Burundi","datePublished":"2025-06-14T05:50:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/"},"wordCount":712,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/AibiWeek-14-06.jpg","keywords":["AIBIweek"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/","url":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/","name":"AibiWeek. Lo \"speciale\" sull'Adozione in Burundi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/AibiWeek-14-06.jpg","datePublished":"2025-06-14T05:50:37+00:00","description":"Tutti gli appuntamenti di Amici dei Bambini dal 16 al 22 giugno\u00a0per scoprire come diventare genitori adottivi, affidatari o aprire una casa famiglia. in pi\u00f9, un focus speciale sull\u2019adozione in Burundi","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/AibiWeek-14-06.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/AibiWeek-14-06.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/aibiweek-speciale-adozione-burundi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"AibiWeek: fra i sei appuntamenti dedicati all\u2019accoglienza, spicca lo &#8220;speciale&#8221; sull&#8217;Adozione in Burundi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:35:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/230912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=230912"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/230912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/230914"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=230912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=230912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=230912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}