﻿


{"id":231413,"date":"2025-06-30T08:00:44","date_gmt":"2025-06-30T06:00:44","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231413"},"modified":"2025-06-27T16:38:25","modified_gmt":"2025-06-27T14:38:25","slug":"accogliere-bambino-abbandonato-difficolta-familiare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/","title":{"rendered":"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?"},"content":{"rendered":"<h2 class=\"ai-optimize-7\">Mercoled\u00ec 3 luglio alle ore 20:00 si terr\u00e0 il webinar gratuito &#8220;Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza&#8221;, per scoprire come aiutare concretamente i minori vittime di abbandono<\/h2>\n<p><!--more--><\/p>\n<p class=\"ai-optimize-9 ai-optimize-introduction\">Un\u2019occasione per conoscere pi\u00f9 da vicino il mondo dei minori vittime di abbandono in Italia e nel mondo.<br \/>\nDurante il\u00a0webinar gratuito\u00a0<strong>Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza<\/strong>, che si tiene il\u00a03\u00a0luglio\u00a0alle 20:00, si approfondiranno le diverse forme di accoglienza: affido, adozione nazionale e internazionale, ma anche il ruolo sempre pi\u00f9 importante dei\u00a0<strong>tutori volontari<\/strong>\u00a0per Minori Stranieri Non Accompagnati.<br \/>\nArgomenti che non trovano facilmente spazio nel &#8220;normale&#8221; dibattito collettivo, se non in occasioni di particolari eventi o emergenze. Eppure, si pu\u00f2 affermare senza timore che, nonostante non ci siano conteggi ufficiali da decenni,\u00a0nel mondo ci siano 200 milioni di bambini abbandonati. Mentre solo in Italia i minori fuori famiglia, compresi i MISNA, sono oltre 40mila.<br \/>\nPer questo, il webinar Faris si propone come un\u00a0momento di presa di consapevolezza e di orientamento aperto a tutti coloro che desiderano\u00a0<strong>avvicinarsi al tema dell\u2019accoglienza<\/strong>\u00a0e capire come diventare un punto di riferimento per un bambino o una bambina vittime di abbandono.<br \/>\nLa docenza sar\u00e0 a cura di Michela De Santi, Desk di Ai.Bi. Amici dei Bambini per l&#8217;adozione internazionale.<\/p>\n<h3 class=\"ai-optimize-11\">Informazioni<\/h3>\n<p class=\"ai-optimize-12\"><strong>Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza&#8221;<br \/>\n<\/strong>Mercoled\u00ec 3 luglio, ore 20:00<br \/>\nPer dettagli e iscrizione, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-bambini-da-accogliere-chi-e-come-aprirsi-allaccoglienza\/\"><strong>QUI<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled&igrave; 3 luglio alle ore 20:00 si terr&agrave; il webinar gratuito &ldquo;Bambini da accogliere, chi e come? Aprirsi all&rsquo;accoglienza&rdquo;, per scoprire come aiutare concretamente i minori vittime di abbandono<\/p>\n","protected":false},"author":133,"featured_media":231414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[],"class_list":["post-231413","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hai mai pensato di accogliere un bambino abbandonato?<\/title>\n<meta name=\"description\" content=\"Il 3 luglio alle 20si terr\u00e0 il webinar gratuito &quot;Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza&quot;, per scoprire come aiutare concretamente i minori bisognosi di accoglienza. Adozione nazionale e internazionale, affido familiare, minori stranieri non accompagnati i temi dell\u2019incontro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?\" \/>\n<meta property=\"og:description\" content=\"Il 3 luglio alle 20si terr\u00e0 il webinar gratuito &quot;Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza&quot;, per scoprire come aiutare concretamente i minori bisognosi di accoglienza. Adozione nazionale e internazionale, affido familiare, minori stranieri non accompagnati i temi dell\u2019incontro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-30T06:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/accoglienza-bambini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?\",\"datePublished\":\"2025-06-30T06:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/\"},\"wordCount\":245,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/accoglienza-bambini.jpg\",\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/\",\"name\":\"Hai mai pensato di accogliere un bambino abbandonato?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/accoglienza-bambini.jpg\",\"datePublished\":\"2025-06-30T06:00:44+00:00\",\"description\":\"Il 3 luglio alle 20si terr\u00e0 il webinar gratuito \\\"Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza\\\", per scoprire come aiutare concretamente i minori bisognosi di accoglienza. Adozione nazionale e internazionale, affido familiare, minori stranieri non accompagnati i temi dell\u2019incontro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/accoglienza-bambini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/06\\\/accoglienza-bambini.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accogliere-bambino-abbandonato-difficolta-familiare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hai mai pensato di accogliere un bambino abbandonato?","description":"Il 3 luglio alle 20si terr\u00e0 il webinar gratuito \"Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza\", per scoprire come aiutare concretamente i minori bisognosi di accoglienza. Adozione nazionale e internazionale, affido familiare, minori stranieri non accompagnati i temi dell\u2019incontro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/","og_locale":"it_IT","og_type":"article","og_title":"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?","og_description":"Il 3 luglio alle 20si terr\u00e0 il webinar gratuito \"Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza\", per scoprire come aiutare concretamente i minori bisognosi di accoglienza. Adozione nazionale e internazionale, affido familiare, minori stranieri non accompagnati i temi dell\u2019incontro.","og_url":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-06-30T06:00:44+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/accoglienza-bambini.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?","datePublished":"2025-06-30T06:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/"},"wordCount":245,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/accoglienza-bambini.jpg","articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/","url":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/","name":"Hai mai pensato di accogliere un bambino abbandonato?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/accoglienza-bambini.jpg","datePublished":"2025-06-30T06:00:44+00:00","description":"Il 3 luglio alle 20si terr\u00e0 il webinar gratuito \"Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza\", per scoprire come aiutare concretamente i minori bisognosi di accoglienza. Adozione nazionale e internazionale, affido familiare, minori stranieri non accompagnati i temi dell\u2019incontro.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/accoglienza-bambini.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/06\/accoglienza-bambini.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/accogliere-bambino-abbandonato-difficolta-familiare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Hai mai pensato di accogliere un bambino abbandonato o in difficolt\u00e0 familiare?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:41:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231413"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231414"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}