﻿{"id":231479,"date":"2025-07-06T08:00:37","date_gmt":"2025-07-06T06:00:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231479"},"modified":"2025-07-04T13:54:22","modified_gmt":"2025-07-04T11:54:22","slug":"affido-familiare-comuni-famiglie-affidatarie","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/","title":{"rendered":"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie"},"content":{"rendered":"<h2 class=\"ai-optimize-6 ai-optimize-introduction\">Misinto, Lazzate e Cogliate, tre comuni della Brianza (Lombardia) approvano un regolamento innovativo per sostenere l&#8217;affido familiare e garantire parit\u00e0 di accesso ai servizi: &#8220;Viene riconosciuto ai bambini in affido la piena dignit\u00e0 di residenti, garantendo loro parit\u00e0 di accesso a mense, servizi e altre agevolazioni&#8221;<\/h2>\n<p><!--more--><\/p>\n<p class=\"ai-optimize-9 ai-optimize-introduction\">Come\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/promozione-affido-familiare-buone-prassi\/\">ben documentato<\/a>\u00a0su AiBinews, la recente approvazione del regolamento sull&#8217;affido familiare nei\u00a0<strong>Comuni di Misinto, Lazzate e Cogliate<\/strong> (con la partnership di Ai.Bi. Amici dei Bambini che metter\u00e0 a disposizione l\u2019esperienza e la rete di famiglie) \u00e8 stata una novit\u00e0 assoluta che si propone di facilitare e sostenere questa straordinaria forma di accoglienza per bambine e bambini le cui famiglie stanno attraversando momenti di debolezza e difficolt\u00e0.<br \/>\n\u201cQuesta delibera &#8211; ha detto\u00a0<strong>Maria Galeazzi<\/strong>, responsabile del servizio affido di Amici dei Bambini &#8211; \u00e8 anche frutto di un grande lavoro e dell&#8217;esperienza di una famiglia affidataria e di una mamma da tempo impegnata con Ai.Bi. Amici dei Bambini,\u00a0<strong>Laura Ciapparelli<\/strong>\u00a0. In pi\u00f9, introduce un principio di per s\u00e9 non nuovo, perch\u00e9 previsto dalla legge, ma scarsamente applicato : ai minori in affido viene finalmente\u00a0<strong>riconosciuto l&#8217;accesso ai servizi essenziali<\/strong>, inclusa la scuola pubblica o paritaria, alle tariffe minime praticate per i residenti, anche quando non risiedono nel Comune della famiglia affidataria, fatto, quest\u2019ultimo, molto frequente\u201d.<br \/>\nPer comprendere meglio il valore di questa iniziativa, abbiamo incontrato anche\u00a0<strong>Stefania Balzaretti<\/strong>, responsabile del servizio affido dei tre Comuni protagonisti del progetto.<br \/>\n\u201c\u00c8 senz\u2019altro segno di una apertura significativa, purtroppo ancora adottata solo da pochi Comuni &#8220;illuminati&#8221; &#8211; ha detto &#8211; : si riconosce ai bambini in affido la piena dignit\u00e0 di residenti, garantendo loro parit\u00e0 di accesso a mense, servizi e altre agevolazioni. Questo non \u00e8 solo un atto burocratico, ma un forte\u00a0<strong>segnale in quanto la societ\u00e0 si fa carico, concretamente, del loro benessere<\/strong>; in pi\u00f9 \u00e8 un riconoscimento delle famiglia affidatarie, risorsa essenziale per i minori in difficolt\u00e0 familiare\u201d.<br \/>\nMa cosa significa in pratica questo regolamento per i bambini e i ragazzi coinvolti? Significa una maggiore inclusione, un accesso pi\u00f9 semplice a tutte le opportunit\u00e0 che il territorio offre e, soprattutto, una riduzione del peso economico per le famiglie affidatarie.<br \/>\nProsegue Balzaretti: \u201cLe famiglie non dovranno preoccuparsi di costi maggiorati per servizi fondamentali, potendo\u00a0<strong>concentrarsi interamente sull&#8217;accoglienza e sul supporto emotivo ai minori<\/strong>. Questa agevolazione \u00e8 un riconoscimento tangibile dell&#8217;impegno delle famiglie e della responsabilit\u00e0 sociale dei comuni\u201d.<\/p>\n<h3 class=\"ai-optimize-13\">Il programma Family Point<\/h3>\n<p class=\"ai-optimize-14\">Nonostante la sua rilevanza, \u201cl&#8217;affido familiare spesso soffre di una scarsa conoscenza e di una visibilit\u00e0 limitata sia tra le famiglie che tra le istituzioni &#8211; sottolinea Stefania &#8211; e ci sono ancora molti ostacoli da superare. Questo progetto in particolare si inserisce in un pi\u00f9 ampio programma denominato\u00a0<strong>Family Point<\/strong>, avviato nel 2023, che mira a prevenire il disagio e a offrire supporto generale alle famiglie\u201d.<br \/>\nUn esempio pratico di questo approccio sono gli ormai noti &#8220;sabati bianchi&#8221;, serate per ragazzi dai 13 ai 14 anni organizzate in collaborazione con associazioni di animatori ed educatori. \u201cL&#8217;obiettivo \u00e8 duplice &#8211; prosegue Balzaretti &#8211; : offrire ai giovani un luogo di incontro e divertimento e, allo stesso tempo, &#8220;liberare&#8221; i genitori per alcune ore,\u00a0<strong>dando spazio alla coppia e prevenendo cos\u00ec situazioni di disagio<\/strong>. Questo dimostra una visione integrata del benessere familiare, che riconosce la necessit\u00e0 di sostenere anche le famiglie &#8220;normali&#8221; che possono trovarsi in difficolt\u00e0\u201d.<\/p>\n<h3 class=\"ai-optimize-14\">La collaborazione con le scuole<\/h3>\n<p class=\"ai-optimize-15\">Non a caso \u00e8 un dato in crescita in molte comunit\u00e0: anche in quelle non a rischio, non mancano situazioni in cui alcune forme di affido possono venire incontro alle fragilit\u00e0 di bambine e bambini.<br \/>\n\u201cIl regolamento \u00e8 innovativo anche nel definire forme di\u00a0<strong>affido leggero e part-time<\/strong>, e nel promuovere il cosiddetto affido di prossimit\u00e0 &#8211; aggiunge Balzaretti &#8211; : un affido, come dice la parola, vicino a tutte le famiglie. Il supporto pu\u00f2 essere pomeridiano o limitati nel tempo, creando una vera e propria comunit\u00e0 di sostegno. Un forte focus infine \u00e8 posto sulla\u00a0<strong>collaborazione con le scuole<\/strong>\u00a0per stimolare, all&#8217;interno delle classi, una rete di supporto per famiglie isolate anche geograficamente rispetto ai centri principali\u201d.<br \/>\nUn fenomeno emergente, che il progetto sta studiando attentamente, \u00e8 infine quello del\u00a0<strong>ritiro sociale e dell&#8217;abbandono scolastico<\/strong>. \u201cAnche nelle nostre piccole realt\u00e0 abbiamo registrato alcuni casi \u00a0di abbandono scolastico, di ansia digitale e\u00a0<strong>hikikomori<\/strong>, spesso in famiglie considerate &#8220;normali&#8221; &#8211; dice &#8211; : la necessit\u00e0 di interventi preventivi e di supporto \u00e8 sempre pi\u00f9 pressante. L&#8217;et\u00e0 pi\u00f9 colpita \u00e8 quella delle scuole medie e dei primi anni delle superiori, con famiglie che si sentono spesso disarmate di fronte a situazioni imprevedibili\u201d.<br \/>\nDopo la fase di sperimentazione, si attendono i primi risultati entro la fine dell&#8217;anno.<\/p>\n<h3 class=\"ai-optimize-18\">Il futuro dell&#8217;iniziativa<\/h3>\n<p class=\"ai-optimize-19\">\u201cLa campagna di sensibilizzazione sta dando i suoi frutti &#8211; conclude Balzaretti &#8211; : tre famiglie si sono rese disponibili all&#8217;affido, una ha gi\u00e0 concluso il percorso e diverse altre hanno richiesto informazioni per offrire il loro aiuto come famiglie di rete. Con un bacino d&#8217;utenza complessivo di circa\u00a0<strong>22.500 abitanti<\/strong>\u00a0tra i tre comuni firmatari, l&#8217;idea \u00e8 di\u00a0<strong>ampliare in futuro l&#8217;iniziativa anche a comuni limitrofi come Ceriano Laghetto e Barlassina<\/strong>, che, pur essendo in parte distaccati dal loro ambito territoriale di riferimento, stanno iniziando a mostrare interesse.<br \/>\nE a settembre, per continuare il percorso di sensibilizzazione nelle comunit\u00e0 , sono previste iniziative come cineforum, dibattiti e una festa per riproporre l\u2019affido e i servizi sul territorio nella nuova sede comunale.<\/p>\n<h3 class=\"ai-optimize-21\">Informazioni e richieste sull\u2019affido familiare<\/h3>\n<p class=\"ai-optimize-22\">Chiunque volesse approfondire la conoscenza dell\u2019<strong>affido familiare\u00a0<\/strong>e riflettere sulla propria disponibilit\u00e0 a\u00a0<strong>intraprendere questo percorso<\/strong>, pu\u00f2 partecipare agli\u00a0<strong>incontri organizzati da Amici dei Bambini<\/strong><br \/>\nTutte le informazioni si trovano alla\u00a0<a href=\"http:\/\/www.aibi.it\/affido\"><strong>pagina dedicata<\/strong><\/a>\u00a0del sito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Misinto, Lazzate e Cogliate, tre comuni della Brianza (Lombardia) approvano un regolamento innovativo per sostenere l&rsquo;affido familiare e garantire parit&agrave; di accesso ai servizi: &ldquo;Viene riconosciuto ai bambini in affido la piena dignit&agrave; di residenti, garantendo loro parit&agrave; di accesso a mense, servizi e altre agevolazioni&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":231480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320],"class_list":["post-231479","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tre comuni virtuosi al fianco delle famiglie affidatarie<\/title>\n<meta name=\"description\" content=\"Misinto, Lazzate e Cogliate, tre comuni approvano un regolamento innovativo per sostenere l&#039;affido familiare e garantire parit\u00e0 di accesso ai servizi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie\" \/>\n<meta property=\"og:description\" content=\"Misinto, Lazzate e Cogliate, tre comuni approvano un regolamento innovativo per sostenere l&#039;affido familiare e garantire parit\u00e0 di accesso ai servizi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-06T06:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/affido-familiare-collaborazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie\",\"datePublished\":\"2025-07-06T06:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/\"},\"wordCount\":948,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/affido-familiare-collaborazione.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/\",\"name\":\"Tre comuni virtuosi al fianco delle famiglie affidatarie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/affido-familiare-collaborazione.jpg\",\"datePublished\":\"2025-07-06T06:00:37+00:00\",\"description\":\"Misinto, Lazzate e Cogliate, tre comuni approvano un regolamento innovativo per sostenere l'affido familiare e garantire parit\u00e0 di accesso ai servizi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/affido-familiare-collaborazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/affido-familiare-collaborazione.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-familiare-comuni-famiglie-affidatarie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tre comuni virtuosi al fianco delle famiglie affidatarie","description":"Misinto, Lazzate e Cogliate, tre comuni approvano un regolamento innovativo per sostenere l'affido familiare e garantire parit\u00e0 di accesso ai servizi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/","og_locale":"it_IT","og_type":"article","og_title":"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie","og_description":"Misinto, Lazzate e Cogliate, tre comuni approvano un regolamento innovativo per sostenere l'affido familiare e garantire parit\u00e0 di accesso ai servizi","og_url":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-07-06T06:00:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/affido-familiare-collaborazione.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie","datePublished":"2025-07-06T06:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/"},"wordCount":948,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/affido-familiare-collaborazione.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/","url":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/","name":"Tre comuni virtuosi al fianco delle famiglie affidatarie","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/affido-familiare-collaborazione.jpg","datePublished":"2025-07-06T06:00:37+00:00","description":"Misinto, Lazzate e Cogliate, tre comuni approvano un regolamento innovativo per sostenere l'affido familiare e garantire parit\u00e0 di accesso ai servizi","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/affido-familiare-collaborazione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/affido-familiare-collaborazione.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/affido-familiare-comuni-famiglie-affidatarie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Affido familiare. Tre comuni virtuosi al fianco delle famiglie affidatarie"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:13:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231479"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231480"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}