﻿


{"id":231537,"date":"2025-07-03T07:40:18","date_gmt":"2025-07-03T05:40:18","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231537"},"modified":"2025-07-08T15:10:55","modified_gmt":"2025-07-08T13:10:55","slug":"bomboniera-solidale-adozione-distanza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/","title":{"rendered":"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?"},"content":{"rendered":"<h2 class=\"ai-optimize-9 ai-optimize-introduction\">\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina<\/h2>\n<p><!--more--><\/p>\n<p class=\"ai-optimize-10 ai-optimize-introduction\">Fare un puzzle&#8230; il giorno del proprio matrimonio. Idea bizzarra, detta cos\u00ec. Ma che diventa un&#8217;idea originale e, soprattutto, solidale se il puzzle \u00e8 quello delle\u00a0<a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/bomboniera\/bomboniera-adozione-a-distanza\/\" target=\"_blank\" rel=\"noopener\"><strong>Bomboniere Adozione a Distanza<\/strong><\/a>\u00a0di\u00a0<strong>Ai.Bi. Amici dei Bambini.\u00a0<\/strong>Una bomboniera pensata per trasformare un&#8217;occasione gi\u00e0 speciale in un&#8217;occasione di amore ancora pi\u00f9 grande,\u00a0capace di oltrepassare i confini del proprio \u201cs\u00ec\u201d.<br \/>\nPerch\u00e9 con la\u00a0<strong>Bomboniera Adozione a Distanza<\/strong>\u00a0di\u00a0<strong>Ai.Bi.<\/strong>, l&#8217;amore degli sposi pu\u00f2 davvero cambiare il mondo, un bambino alla volta, visto che, scegliendola, si attiva a proprio nome un\u2019<strong>Adozione a Distanza<\/strong>, garantendo almeno un anno di sostegno ai bambini abbandonati negli orfanotrofi in\u00a0<strong>Africa<\/strong>,\u00a0<strong>Bolivia<\/strong>\u00a0o\u00a0<strong>Ucraina<\/strong>, dove la guerra e la povert\u00e0 hanno lasciato e continuano a lasciare ferite profonde.<br \/>\nL&#8217;esclusivo\u00a0<strong>\u201cPuzzle della Solidariet\u00e0\u201d<\/strong>,<strong>\u00a0<\/strong>ideatoda Amici dei Bambini, permette di donare a\u00a0ogni invitato una\u00a0<strong>bomboniera unica<\/strong>, contenente\u00a0<strong>una tessera numerata<\/strong>\u00a0di un puzzle solidale. Ogni tessera \u00e8 montata su un elegante cartoncino che riporta l\u2019immagine completa del puzzle, una frase augurale, la data delle nozze, il nome degli sposi e una breve descrizione del progetto sostenuto. Il tutto \u00e8 confezionato con cura in una\u00a0<strong>busta trasparente<\/strong>. (<em>Confetti non inclusi \u2013 dimensioni 21&#215;9 cm<\/em>).<br \/>\nOltre alle bomboniere, si riceve una\u00a0<strong>scheda descrittiva A4<\/strong>\u00a0che spiega agli ospiti il significato e il valore del gesto.<br \/>\nTre le opzioni possibili in base al numero di invitati:<\/p>\n<ul>\n<li class=\"ai-optimize-14\"><strong>48 tessere<\/strong>\u00a0= 1 anno di adozione (48 bomboniere)<\/li>\n<li class=\"ai-optimize-15\"><strong>96 tessere<\/strong>\u00a0= 2 anni di adozione (96 bomboniere)<\/li>\n<li class=\"ai-optimize-16\"><strong>192 tessere<\/strong>\u00a0= 3 anni di adozione (192 bomboniere)<\/li>\n<\/ul>\n<p class=\"ai-optimize-17\">Con questa scelta, ogni dettaglio del vostro matrimonio racconter\u00e0 una storia d\u2019amore che va oltre voi due: quella di un futuro donato a chi non ha nulla, grazie al vostro giorno pi\u00f9 bello.<\/p>\n<h3 class=\"ai-optimize-18\">Informazioni<\/h3>\n<p class=\"ai-optimize-19\">Per qualsiasi ulteriore informazione puoi contattarci al n. 02.98822359 oppure via mail all\u2019indirizzo\u00a0<a href=\"mailto:bomboniere@aibi.it\"><strong>bomboniere@aibi.it<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Egrave; una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d&rsquo;amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina<\/p>\n","protected":false},"author":133,"featured_media":231538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[520],"class_list":["post-231537","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bomboniere-solidali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?<\/title>\n<meta name=\"description\" content=\"\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?\" \/>\n<meta property=\"og:description\" content=\"\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-03T05:40:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T13:10:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/matrimonio-puzzle-della-solidarieta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?\",\"datePublished\":\"2025-07-03T05:40:18+00:00\",\"dateModified\":\"2025-07-08T13:10:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/\"},\"wordCount\":343,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/matrimonio-puzzle-della-solidarieta.jpg\",\"keywords\":[\"bomboniere solidali\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/\",\"name\":\"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/matrimonio-puzzle-della-solidarieta.jpg\",\"datePublished\":\"2025-07-03T05:40:18+00:00\",\"dateModified\":\"2025-07-08T13:10:55+00:00\",\"description\":\"\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/matrimonio-puzzle-della-solidarieta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/matrimonio-puzzle-della-solidarieta.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniera-solidale-adozione-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?","description":"\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?","og_description":"\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina","og_url":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-07-03T05:40:18+00:00","article_modified_time":"2025-07-08T13:10:55+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/matrimonio-puzzle-della-solidarieta.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?","datePublished":"2025-07-03T05:40:18+00:00","dateModified":"2025-07-08T13:10:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/"},"wordCount":343,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/matrimonio-puzzle-della-solidarieta.jpg","keywords":["bomboniere solidali"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/","url":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/","name":"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/matrimonio-puzzle-della-solidarieta.jpg","datePublished":"2025-07-03T05:40:18+00:00","dateModified":"2025-07-08T13:10:55+00:00","description":"\u00c8 una bomboniera unica proposta in esclusiva da Ai.Bi. Amici dei Bambini e la soluzione perfetta per un matrimonio: un simbolo d\u2019amore che si protrae nel tempo e che arriva fino a un orfanotrofio in Africa, Bolivia o Ucraina","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/matrimonio-puzzle-della-solidarieta.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/matrimonio-puzzle-della-solidarieta.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bomboniera-solidale-adozione-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Che cosa \u00e8 una Bomboniera Solidale Adozione a Distanza?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:13:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231537"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231538"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}