﻿


{"id":231576,"date":"2025-07-07T08:00:13","date_gmt":"2025-07-07T06:00:13","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231576"},"modified":"2025-07-07T05:42:17","modified_gmt":"2025-07-07T03:42:17","slug":"adozione-internazionale-dipingere-speranza-suresh","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/","title":{"rendered":"Adozione Internazionale. Dipingere la speranza: la storia di Suresh"},"content":{"rendered":"<h2 class=\"ai-optimize-8 ai-optimize-introduction\">Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che &#8220;parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza&#8221;<\/h2>\n<p><!--more--><\/p>\n<p class=\"ai-optimize-9 ai-optimize-introduction\">A 27 anni, Suresh incarna l\u2019incontro tra due mondi: quello remoto e affascinante\u00a0<strong>dell\u2019India<\/strong>, sua terra\u00a0natale, e quello concreto e accogliente\u00a0<strong>dell\u2019Emilia<\/strong>, dove \u00e8 cresciuto dopo l\u2019adozione, a 8 anni, da parte di Elisabetta e Fabio. La sua infanzia ha avuto inizio tra le difficolt\u00e0 di un orfanotrofio a Bangalore, ma \u00e8 rifiorita nella campagna di Campogalliano, tra campi coltivati, animali e l\u2019affetto di una famiglia pronta ad accoglierlo senza riserve.<br \/>\n&#8220;Ci ha detto subito che non avrebbe coltivato la terra&#8221;, ha raccontato la mamma Elisabetta al quotidiano\u00a0<strong>Avvenire<\/strong>.<br \/>\nE infatti, anzich\u00e9 seguire il solco dei genitori,\u00a0<strong>Suresh ha trovato il suo terreno fertile nell\u2019arte<\/strong>. Dopo momenti difficili nell\u2019adolescenza, segnati anche da fragilit\u00e0 psicologiche, ha intrapreso un percorso durante il quale ha scoperto la pittura come via d\u2019espressione e rinascita.<\/p>\n<h3 class=\"ai-optimize-11\">La prima mostra di Suresh<\/h3>\n<p class=\"ai-optimize-12\">E tra pennelli e colori, \u00e8 emerso un talento sorprendente. I suoi quadri sono vortici di emozioni, sovrapposizioni di segni e forme, capaci di catturare e inquietare. Lo ha notato anche Bianca Tosatti, esperta italiana di arte irregolare, che ha curato la sua prima mostra,\u00a0<strong>Spirito e spettri nel colore di Suresh<\/strong>, ospitata a Milano presso la galleria\u00a0<strong>Maroncelli 12,<\/strong>\u00a0dal 28\u00a0maggio\u00a0al 26 settembre.<br \/>\nLe opere di Suresh \u2013 autoritratti, visioni fantastiche, reinterpretazioni \u2013\u00a0<strong>parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza<\/strong>. I suoi quadri, gi\u00e0 tutti prenotati, raccontano una storia senza parole, fatta di dolore e rinascita, come solo l\u2019arte sa fare.<br \/>\n&#8220;Abbiamo adottato un piccolo Van Gogh e non ce n\u2019eravamo accorti&#8221;, dice\u00a0oggi\u00a0con orgoglio la mamma. Una storia d\u2019amore, di talento e di speranza che comincia da lontano, ma ha trovato casa qui.<\/p>\n<h3 class=\"ai-optimize-15\">Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p class=\"ai-optimize-16\">Chiunque, coppie e single, sia interessato ad avere maggiori informazioni sull&#8217;Adozione Internazionale o a intraprendere l&#8217;iter adottivo pu\u00f2 partecipare ai\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/\">tanti webinar e corsi<\/a>\u00a0organizzati da Ai.Bi. Amici dei Bambini. Per informazioni, contattate l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a>.<\/p>\n<p class=\"ai-optimize-17\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p class=\"ai-optimize-18\">Ogni donazione gode delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n<p class=\"ai-optimize-6\"><strong>Foto in alto: courtesy galleria Maroncelli 12<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nato a Bangalore e cresciuto a Campogalliano dopo l&rsquo;adozione, Suresh conquista il pubblico con opere che &ldquo;parlano con la voce di un&rsquo;anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza&rdquo;<\/p>\n","protected":false},"author":133,"featured_media":231587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347],"class_list":["post-231576","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale. Dipingere la speranza: la storia di Suresh,\u00a0<\/title>\n<meta name=\"description\" content=\"Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che &quot;parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale. Dipingere la speranza: la storia di Suresh\" \/>\n<meta property=\"og:description\" content=\"Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che &quot;parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T06:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/Suresh-Galleria-Maroncelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione Internazionale. Dipingere la speranza: la storia di Suresh\",\"datePublished\":\"2025-07-07T06:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/\"},\"wordCount\":400,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/Suresh-Galleria-Maroncelli.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/\",\"name\":\"Adozione Internazionale. Dipingere la speranza: la storia di Suresh,\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/Suresh-Galleria-Maroncelli.jpg\",\"datePublished\":\"2025-07-07T06:00:13+00:00\",\"description\":\"Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che \\\"parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/Suresh-Galleria-Maroncelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/Suresh-Galleria-Maroncelli.jpg\",\"width\":718,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-dipingere-speranza-suresh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale. Dipingere la speranza: la storia di Suresh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale. Dipingere la speranza: la storia di Suresh,\u00a0","description":"Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che \"parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale. Dipingere la speranza: la storia di Suresh","og_description":"Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che \"parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza\"","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-07-07T06:00:13+00:00","og_image":[{"width":718,"height":500,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/Suresh-Galleria-Maroncelli.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione Internazionale. Dipingere la speranza: la storia di Suresh","datePublished":"2025-07-07T06:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/"},"wordCount":400,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/Suresh-Galleria-Maroncelli.jpg","keywords":["Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/","name":"Adozione Internazionale. Dipingere la speranza: la storia di Suresh,\u00a0","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/Suresh-Galleria-Maroncelli.jpg","datePublished":"2025-07-07T06:00:13+00:00","description":"Nato a Bangalore e cresciuto a Campogalliano dopo l\u2019adozione, Suresh conquista il pubblico con opere che \"parlano con la voce di un\u2019anima che ha conosciuto la perdita ma ha saputo trasformarla in bellezza\"","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/Suresh-Galleria-Maroncelli.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/Suresh-Galleria-Maroncelli.jpg","width":718,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-dipingere-speranza-suresh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale. Dipingere la speranza: la storia di Suresh"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:40:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231576"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231587"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}