﻿{"id":231698,"date":"2025-07-09T14:33:35","date_gmt":"2025-07-09T12:33:35","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231698"},"modified":"2025-07-09T14:33:35","modified_gmt":"2025-07-09T12:33:35","slug":"scoprire-scuola-tempo-guerra","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/","title":{"rendered":"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita"},"content":{"rendered":"<h2 class=\"ai-optimize-6 ai-optimize-introduction\">Bogdan, a 15 anni, non era mai stato a scuola, nemmeno quando viveva in Ucraina. Poi, scappato in Moldova a causa della guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi. Amici dei Bambini. E si \u00e8 aperto un mondo nuovo di scoperte e possibilit\u00e0<\/h2>\n<p><!--more--><\/p>\n<p class=\"ai-optimize-7 ai-optimize-introduction\">I genitori di decine di generazioni l\u2019hanno ripetuta allo sfinimento, tanto da farla diventare quasi una frase fatta che, come tale, rischia di perdere il suo significato letterale: <strong>studiare pu\u00f2 cambiare la vita<\/strong>.<br \/>\nMa ci sono storie reali che, se raccontate, fanno ben capire la portata concreta e tangibile dell\u2019affermazione precedente. Come la storia di Bogdan (nome di fantasia), per esempio, un ragazzo di 15 anni <strong>arrivato in Moldova per sfuggire dalla furia della guerra<\/strong> <strong>in Ucraina<\/strong>.<\/p>\n<h3 class=\"ai-optimize-8\">Il \u201cprimo giorno di scuola\u201d<\/h3>\n<p class=\"ai-optimize-9\">A differenza della maggior parte dei coetanei come lui, Bogdan non era mai andato a scuola, nemmeno nel suo Paese d\u2019origine, a causa delle difficolt\u00e0 economiche della sua famiglia.<br \/>\nLe cose sono cambiate quanto Bogdan, che si trovava insieme ad altri minori rifugiati nel centro CPTR di C\u0103rpineni, \u00e8 stato inserito in un programma di educazione non formale portato anche l\u00ec dal <strong>&#8220;Ludobus per la Pace&#8221;<\/strong>, la ludoteca itinerante realizzata da <em>Amici dei Bambini <\/em>nell\u2019ambito del progetto BAMBINIxLAPACE.<br \/>\nIn questo modo Bogdan ha <strong>mosso i suoi primi passi nel mondo dell\u2019educazione<\/strong>, scoprendo un contesto popolato da educatori dedicati, compagni accoglienti e insegnanti comprensivi, e nel quale si impara attraverso i libri e le attivit\u00e0 e non attraverso la violenza, come purtroppo aveva vissuto in passato.<br \/>\nNonostante avesse gi\u00e0 15 anni, Bogdan \u00e8 stato inserito nella classe ottava, insieme ad altri ragazzi rifugiati e locali. Curioso e disciplinato, nonostante tutte le difficolt\u00e0, <strong>ha iniziato a frequentare regolarmente le lezioni<\/strong> e a partecipare con entusiasmo alle attivit\u00e0 di educazione non formale, dove gioco, lavoro di squadra e creativit\u00e0 si intrecciavano con il \u201csapere\u201d, inteso nel senso pi\u00f9 canonico del termine.<\/p>\n<h3 class=\"ai-optimize-10\">L\u2019apprendimento della lingua rumena<\/h3>\n<p class=\"ai-optimize-11\">Per Bogdan, come per molti altri bambini rifugiati, una delle sfide pi\u00f9 grandi \u00e8 stata imparare la lingua rumena. In questo caso, per\u00f2, <strong>tutti partivano dallo stesso livello<\/strong>: zero. E proprio l\u00ec, Bogdan ha saputo distinguersi grazie alla sua perseveranza e a un\u2019innata saggezza.<br \/>\nGrazie alle attivit\u00e0 interattive organizzate dagli animatori di <em>Amici dei Bambini<\/em>, Bogdan ha scoperto <strong>quanto pu\u00f2 essere bello imparare<\/strong>. Con grande impegno, \u00e8 stato l\u2019unico del gruppo a riuscire a memorizzare ogni parola di un dizionario tascabile, ideato appositamente per aiutare i bambini rifugiati ad avvicinarsi alla lingua rumena. Per Bogdan, <strong>ogni parola imparata rappresentava un passo avanti<\/strong> lungo un cammino nuovo, da affrontare con crescente fiducia.<\/p>\n<h3 class=\"ai-optimize-13\">\u201cAdesso so che studiare pu\u00f2 cambiare tutto\u201d<\/h3>\n<p class=\"ai-optimize-14\">Nonostante l\u2019impegno costante e il sincero desiderio di dare il meglio di s\u00e9, Bogdan non \u00e8 riuscito a superare gli esami finali come avrebbe sperato. Gli anni trascorsi lontano dalla scuola e la mancanza di una solida base educativa si sono fatti sentire. Eppure, al di l\u00e0 dei voti e delle valutazioni, Bogdan ha compreso qualcosa di essenziale, che tanti suoi coetanei, formalmente pi\u00f9 \u201cistruiti\u201d non sempre comprendono: <strong>l\u2019educazione \u00e8 la chiave per cambiare la propria vita<\/strong> e costruire un futuro migliore.<br \/>\n\u201c\u00c8 stato un anno faticoso, ma adesso so che studiare pu\u00f2 cambiare tutto \u2013 ha confidato Bogdan. Ho imparato tanto. Non solo dai libri\u2026 Prima non capivo a cosa servisse la scuola. Ora s\u00ec\u201d<br \/>\n\u201cRagazzi come Bogdan se ne incontrano pochi,\u201d racconta la professoressa Olga, una delle sue insegnanti<strong>. <\/strong>\u201c<strong>Non si lasciano sconfiggere dal passato, ma si lasciano ispirare dal futuro.<\/strong> E con questo suo primo anno di scuola, Bogdan ha aperto una porta importante: quella verso una vita in cui l\u2019apprendimento diventa il migliore alleato.\u201d<\/p>\n<h3 class=\"ai-optimize-17\"><strong>La speranza del bambini dell\u2019Ucraina \u00e8 appesa a un filo<\/strong><\/h3>\n<p class=\"ai-optimize-18\">Dallo scoppio della <strong>guerra in Ucraina<\/strong>, sono passati oltre 3 anni. In questo tempo oltre 600 bambini sono morti e oltre 2.000 sono stati feriti.<br \/>\n<strong>Anche la speranza rischia di morire.<br \/>\n<\/strong>Ai.Bi. Amici dei Bambini con il progetto<strong> BAMBINIxLAPACE<\/strong> ogni giorno porta ai minori e le loro famiglie aiuto concreto, supporto psicologico e attimi di\u00a0vita \u201cnormale\u201d, in un tempo che normale non \u00e8.<br \/>\nEcco perch\u00e9 <strong>oggi pi\u00f9 che mai c\u2019\u00e8 bisogno del tuo aiuto:\u00a0<\/strong>per non far spezzare il filo della speranza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bogdan, a 15 anni, non era mai stato a scuola, nemmeno quando viveva in Ucraina. Poi, scappato in Moldova a causa della guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi. Amici dei Bambini. E si &egrave; aperto un mondo nuovo di scoperte e possibilit&agrave;<\/p>\n","protected":false},"author":102,"featured_media":231702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909,5],"tags":[895,530,423],"class_list":["post-231698","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","category-cooperazione-internazionale","tag-bambinixlapace","tag-moldova","tag-ucraina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Scoprire la scuola in tempo di guerra. E cambiare la propria vita<\/title>\n<meta name=\"description\" content=\"Bogdan non era mai stato a scuola, Poi, scappato dall&#039;Ucraina in Moldova in tempo di guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita\" \/>\n<meta property=\"og:description\" content=\"Bogdan non era mai stato a scuola, Poi, scappato dall&#039;Ucraina in Moldova in tempo di guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-09T12:33:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/bogdan-ucraina-scuola-tempo-di-guerra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita\",\"datePublished\":\"2025-07-09T12:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/\"},\"wordCount\":712,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/bogdan-ucraina-scuola-tempo-di-guerra.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\",\"Ucraina\"],\"articleSection\":[\"BAMBINIXLAPACE\",\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/\",\"name\":\"Scoprire la scuola in tempo di guerra. E cambiare la propria vita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/bogdan-ucraina-scuola-tempo-di-guerra.jpg\",\"datePublished\":\"2025-07-09T12:33:35+00:00\",\"description\":\"Bogdan non era mai stato a scuola, Poi, scappato dall'Ucraina in Moldova in tempo di guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/bogdan-ucraina-scuola-tempo-di-guerra.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/bogdan-ucraina-scuola-tempo-di-guerra.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scoprire-scuola-tempo-guerra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Scoprire la scuola in tempo di guerra. E cambiare la propria vita","description":"Bogdan non era mai stato a scuola, Poi, scappato dall'Ucraina in Moldova in tempo di guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita","og_description":"Bogdan non era mai stato a scuola, Poi, scappato dall'Ucraina in Moldova in tempo di guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi.","og_url":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-07-09T12:33:35+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/bogdan-ucraina-scuola-tempo-di-guerra.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita","datePublished":"2025-07-09T12:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/"},"wordCount":712,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/bogdan-ucraina-scuola-tempo-di-guerra.jpg","keywords":["BAMBINIxLAPACE","Moldova","Ucraina"],"articleSection":["BAMBINIXLAPACE","Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/","url":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/","name":"Scoprire la scuola in tempo di guerra. E cambiare la propria vita","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/bogdan-ucraina-scuola-tempo-di-guerra.jpg","datePublished":"2025-07-09T12:33:35+00:00","description":"Bogdan non era mai stato a scuola, Poi, scappato dall'Ucraina in Moldova in tempo di guerra ha incontrato il Ludobus della Pace e i progetti di Ai.Bi.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/bogdan-ucraina-scuola-tempo-di-guerra.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/bogdan-ucraina-scuola-tempo-di-guerra.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/scoprire-scuola-tempo-guerra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"BAMBINIxLAPACE. Scoprire la scuola in tempo di guerra. E cambiare la propria vita"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:29:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231698"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231702"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}