﻿


{"id":231872,"date":"2025-07-18T07:40:30","date_gmt":"2025-07-18T05:40:30","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231872"},"modified":"2025-11-05T15:53:39","modified_gmt":"2025-11-05T14:53:39","slug":"adozione-internazionale-sud-america-johnny","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/","title":{"rendered":"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row el_class=&#8221;wpz-sc-box normal&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;231873&#8243; img_size=&#8221;large&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_message icon_fontawesome=&#8221;&#8221; css=&#8221;&#8221;]Scheda inserita il: 18\/07\/2025[\/vc_message][vc_message icon_fontawesome=&#8221;&#8221; css=&#8221;&#8221;]Anno di nascita: 2022[\/vc_message][vc_message icon_fontawesome=&#8221;fas fa-globe-americas&#8221;]Provenienza: Sud America[\/vc_message][vc_message icon_fontawesome=&#8221;&#8221; css=&#8221;&#8221;]diagnosi di ritardo dello sviluppo, disturbi del linguaggio e motori e sindrome dello spettro autistico in studio[\/vc_message][vc_column_text css=&#8221;&#8221;]\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*142461-start*\/\n#btnsx-142461{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-142461 .btnsx-text-primary{text-transform:uppercase;font-size:17px;line-height:17px;font-weight:bold;font-family:Arial;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-142461:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-142461{background-color:#0f95fc!important;}\n#btnsx-142461:hover{background-color:#3da8fb!important;}\n#btnsx-142461{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-left-radius:6px;border-bottom-right-radius:6px;}\n#btnsx-142461:hover{border-style:none;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-left-radius:6px;border-bottom-right-radius:6px;}\n#btnsx-142461{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-142461:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*142461-end*\/\n<\/style>\n<a href=\"https:\/\/www.aibi.it\/ita\/appelli-adozione\/richiesta-informazioni\/?codice=Johnny+Sud+America\" id=\"btnsx-142461\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Arial\">\n\t<span class=\"btnsx-text-primary \">Richiedi informazioni su questo bambino<\/span><\/a>\n\n<!-- Buttons X - End -->\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<strong>Johnny<\/strong> \u00e8 un bambino sudamericano di due anni e mezzo, accolto in protezione fin dai primi giorni di vita. Proviene da una famiglia allargata di origine materna che, nonostante i tentativi, non \u00e8 riuscita a garantirgli un ambiente sicuro e adeguato. Un iniziale inserimento presso alcuni familiari ha avuto esiti insoddisfacenti.<\/p>\n<h3>Le difficolt\u00e0 del bambino<\/h3>\n<p>La gravidanza non \u00e8 stata monitorata e la condotta materna \u00e8 risultata inadeguata, con conseguente parto leggermente prematuro. Attualmente\u00a0<strong>Johnny presenta un ritardo dello sviluppo, disturbi del linguaggio e motori<\/strong>. \u00c8 in corso una valutazione per una possibile diagnosi di disturbo dello spettro autistico.<br \/>\nIl bambino ha sviluppato un forte legame con la mamma affidataria, che riconosce come principale figura di riferimento e protezione. Tuttavia, tende a non ricambiare le manifestazioni di affetto ed \u00e8 generalmente restio al contatto fisico, come abbracci o baci.<br \/>\nHa iniziato a camminare tardi e mostra ancora difficolt\u00e0 nella coordinazione motoria, con frequenti cadute. Anche sul piano linguistico si evidenziano ritardi: pur comprendendo le istruzioni, comunica prevalentemente in modo non verbale e possiede un vocabolario molto limitato.<br \/>\nDal punto di vista emotivo, Johnny \u00e8 spontaneo e sa esprimere sia gioia che tristezza. Presenta per\u00f2 una bassa tolleranza alla frustrazione e una capacit\u00e0 di concentrazione limitata.<br \/>\n\u00c8 seguito da un\u2019\u00e9quipe multidisciplinare composta da fisioterapisti, psicomotricisti, terapisti occupazionali e logopedisti. Le valutazioni specialistiche evidenziano piccoli ma costanti progressi.<br \/>\nJohnny \u00e8 un bambino attivo ed energico: ama giocare con le moto, le macchinine e, soprattutto, con l\u2019acqua, che esercita su di lui un effetto calmante. Gli piace manipolare la plastilina e preferisce le superfici morbide a quelle ruvide. Non tollera bene i suoni forti, come le sirene delle ambulanze o della polizia.<\/p>\n<h3>Stabilit\u00e0 e affetto per il piccolo Johnny<\/h3>\n<p>Per la sua crescita e il suo benessere, Johnny ha urgente bisogno di una\u00a0<strong>famiglia definitiva<\/strong>\u00a0che possa offrirgli\u00a0<strong>stabilit\u00e0, affetto e stimoli adeguati<\/strong>. Due genitori amorevoli, pazienti e presenti potrebbero rappresentare per lui l\u2019ambiente ideale in cui sviluppare appieno le sue potenzialit\u00e0, anche considerando che la giovane et\u00e0 e le diagnosi in corso lasciano aperto un margine di evoluzione positiva.<br \/>\nIn sede sono disponibili foto e video del bambino.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*142461-start*\/\n#btnsx-142461{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-142461 .btnsx-text-primary{text-transform:uppercase;font-size:17px;line-height:17px;font-weight:bold;font-family:Arial;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-142461:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-142461{background-color:#0f95fc!important;}\n#btnsx-142461:hover{background-color:#3da8fb!important;}\n#btnsx-142461{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-left-radius:6px;border-bottom-right-radius:6px;}\n#btnsx-142461:hover{border-style:none;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-left-radius:6px;border-bottom-right-radius:6px;}\n#btnsx-142461{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-142461:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*142461-end*\/\n<\/style>\n<a href=\"https:\/\/www.aibi.it\/ita\/appelli-adozione\/richiesta-informazioni\/?codice=Johnny+Sud+America\" id=\"btnsx-142461\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Arial\">\n\t<span class=\"btnsx-text-primary \">Richiedi informazioni su questo bambino<\/span><\/a>\n\n<!-- Buttons X - End -->\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p class=\"ai-optimize-6 ai-optimize-introduction\"><strong>Johnny<\/strong><\/p>\n<ul>\n<li class=\"ai-optimize-7\"><strong>Anno di Nascita:\u00a0<\/strong>2022<\/li>\n<li class=\"ai-optimize-8\"><strong>Provenienza:<\/strong> Sud America<\/li>\n<li class=\"ai-optimize-9\"><strong>Diagnosi di ritardo dello sviluppo, disturbi del linguaggio e motori e sindrome dello spettro autistico in studio<\/strong><\/li>\n<\/ul>\n","protected":false},"author":133,"featured_media":231873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[260],"tags":[593,668],"class_list":["post-231872","post","type-post","status-publish","format-standard","has-post-thumbnail","category-appelli-adozione-internazionale","tag-bambini-piccoli","tag-sudamerica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale in Sud America. Johnny<\/title>\n<meta name=\"description\" content=\"Adozione Internazionale in Sud America\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0\" \/>\n<meta property=\"og:description\" content=\"Adozione Internazionale in Sud America\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-18T05:40:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T14:53:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/appello-adozione-internazionale-johnny.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0\",\"datePublished\":\"2025-07-18T05:40:30+00:00\",\"dateModified\":\"2025-11-05T14:53:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/\"},\"wordCount\":540,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/appello-adozione-internazionale-johnny.jpg\",\"keywords\":[\"Bambini Piccoli\",\"sudamerica\"],\"articleSection\":[\"Appelli Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/\",\"name\":\"Adozione Internazionale in Sud America. Johnny\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/appello-adozione-internazionale-johnny.jpg\",\"datePublished\":\"2025-07-18T05:40:30+00:00\",\"dateModified\":\"2025-11-05T14:53:39+00:00\",\"description\":\"Adozione Internazionale in Sud America\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/appello-adozione-internazionale-johnny.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/appello-adozione-internazionale-johnny.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sud-america-johnny\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appelli Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/appelli-adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale in Sud America. Johnny","description":"Adozione Internazionale in Sud America\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0","og_description":"Adozione Internazionale in Sud America\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-07-18T05:40:30+00:00","article_modified_time":"2025-11-05T14:53:39+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/appello-adozione-internazionale-johnny.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0","datePublished":"2025-07-18T05:40:30+00:00","dateModified":"2025-11-05T14:53:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/"},"wordCount":540,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/appello-adozione-internazionale-johnny.jpg","keywords":["Bambini Piccoli","sudamerica"],"articleSection":["Appelli Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/","name":"Adozione Internazionale in Sud America. Johnny","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/appello-adozione-internazionale-johnny.jpg","datePublished":"2025-07-18T05:40:30+00:00","dateModified":"2025-11-05T14:53:39+00:00","description":"Adozione Internazionale in Sud America\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/appello-adozione-internazionale-johnny.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/appello-adozione-internazionale-johnny.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sud-america-johnny\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Appelli Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/appelli-adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale in Sud America.\u00a0Johnny,\u00a0poco pi\u00f9 di due anni ma con il suo sacrosanto diritto di essere figlio\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:59:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231872"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231873"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}