﻿


{"id":231958,"date":"2025-07-23T11:00:37","date_gmt":"2025-07-23T09:00:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=231958"},"modified":"2025-09-16T17:54:32","modified_gmt":"2025-09-16T15:54:32","slug":"adozione-internazionale-ottenere-idoneita-ostacoli","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/","title":{"rendered":"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli"},"content":{"rendered":"<h2>Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato<\/h2>\n<p><!--more--><\/p>\n<p>Affrontare un percorso di adozione internazionale in Italia significa, spesso, ritrovarsi in un\u00a0<strong>labirinto burocratico<\/strong>\u00a0dove ogni passo pu\u00f2 trasformarsi in un ostacolo imprevisto.<br \/>\nLo dimostrano le storie raccontate ad Ai.Bi. Amici dei Bambini da diverse coppie che hanno partecipato ai vari incontri informativi e formativi proposti.<\/p>\n<h3>Le storie raccolte da Ai.Bi.<\/h3>\n<p>C\u2019\u00e8,\u00a0 per esempio, chi ha dovuto\u00a0<strong>attendere dieci anni<\/strong>\u00a0prima di potersi ripresentare al colloquio con i servizi sociali. \u00c8 il caso di una coppia seguita dalla sede di Salerno: nel 2015 la loro domanda era stata respinta perch\u00e9 lavoravano in due citt\u00e0 diverse, sebbene gi\u00e0 allora fossero disponibili a trasferirsi in caso di figli. La paura di un secondo &#8220;no&#8221; li ha paralizzati fino a quando, stabilitisi nella stessa citt\u00e0, si sono ripresentati.\u00a0Oggi\u00a0hanno ritrovato speranza e motivazione per adottare in Per\u00f9 o Honduras.<br \/>\nAltrove, la burocrazia sanitaria complica ulteriormente il quadro. Una coppia, che risiede in Puglia, segnala un\u00a0<strong>ritardo di 2-3 mesi<\/strong>\u00a0nella trasmissione dei documenti a causa della\u00a0<strong>carenza di personale<\/strong> nella loro ASL. La visita psichiatrica \u2013 requisito essenziale per il certificato di &#8220;sana e robusta costituzione&#8221; e il completamento della documentazione da trasmettere \u2013 \u00e8 stata fissata a circa due mesi di distanza rispetto alla richiesta, compromettendo le tempistiche con il Paese straniero.<\/p>\n<h3>Regione che vai, tempi che trovi<\/h3>\n<p>In altri casi, per accelerare il percorso, le famiglie si\u00a0<strong>trasferiscono di regione<\/strong>. \u00c8 accaduto a una coppia formata da un romano e una lituana: pur vivendo a Roma, si sono spostati in Molise, dove la procedura \u00e8 pi\u00f9 snella. Qui, in pochi mesi, hanno ottenuto l\u2019incontro con il giudice.<br \/>\nSingolare anche la storia di Valerio e Daniela, che <strong>ottennero l\u2019idoneit\u00e0 all\u2019Aquila nel 2017<\/strong>\u00a0ma dovettero ricominciare da capo una volta trasferitisi in Trentino. L\u00ec, inizialmente \u201cbocciati\u201d dall\u2019equipe locale, hanno accolto due minori in affido. Questo gesto ha <strong>ribaltato il giudizio dei servizi sociali<\/strong>,\u00a0oggi\u00a0estremamente positivo. In attesa del nuovo decreto di idoneit\u00e0, si sentono finalmente pronti a riprendere il sogno dell\u2019adozione internazionale.<br \/>\nTante storie diverse, ma unite da un filo comune: la volont\u00e0 di diventare genitori in un sistema che, troppo spesso,\u00a0<strong>somiglia pi\u00f9 a una prova di resistenza che a un percorso di accoglienza<\/strong>.<\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chiunque, coppie e single, sia interessato ad avere maggiori informazioni sull\u2019Adozione Internazionale o a intraprendere l\u2019iter adottivo pu\u00f2 partecipare ai\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/\"><strong>tanti webinar e corsi<\/strong><\/a>\u00a0organizzati da Ai.Bi. Amici dei Bambini. Per informazioni, contattate l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a>, telefonando al numero 02988221 o utilizzando la nostra live chat, che si apre automaticamente una volta nella pagina dell&#8217;Adozione Internazionale. Verrai messo direttamente in comunicazione con un nostro operatore.<\/p>\n<p>&nbsp;<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un&rsquo;impresa a tempo indeterminato<\/p>\n","protected":false},"author":133,"featured_media":231959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347],"class_list":["post-231958","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli<\/title>\n<meta name=\"description\" content=\"Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli\" \/>\n<meta property=\"og:description\" content=\"Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-23T09:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T15:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/coppia-genitori.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli\",\"datePublished\":\"2025-07-23T09:00:37+00:00\",\"dateModified\":\"2025-09-16T15:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/coppia-genitori.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/\",\"name\":\"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/coppia-genitori.jpg\",\"datePublished\":\"2025-07-23T09:00:37+00:00\",\"dateModified\":\"2025-09-16T15:54:32+00:00\",\"description\":\"Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/coppia-genitori.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/07\\\/coppia-genitori.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-ottenere-idoneita-ostacoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli","description":"Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli","og_description":"Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-07-23T09:00:37+00:00","article_modified_time":"2025-09-16T15:54:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/coppia-genitori.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli","datePublished":"2025-07-23T09:00:37+00:00","dateModified":"2025-09-16T15:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/"},"wordCount":484,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/coppia-genitori.jpg","keywords":["Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/","name":"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/coppia-genitori.jpg","datePublished":"2025-07-23T09:00:37+00:00","dateModified":"2025-09-16T15:54:32+00:00","description":"Tra trasferimenti di residenza, burocrazia sanitaria e giudizi discordanti, il percorso per diventare genitori adottivi spesso si trasforma in un\u2019impresa a tempo indeterminato","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/coppia-genitori.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/07\/coppia-genitori.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-ottenere-idoneita-ostacoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale. Ottenere l\u2019idoneit\u00e0: una corsa a ostacoli"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:41:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=231958"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/231958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/231959"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=231958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=231958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=231958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}