﻿


{"id":232269,"date":"2025-08-08T14:13:22","date_gmt":"2025-08-08T12:13:22","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=232269"},"modified":"2025-08-09T10:45:48","modified_gmt":"2025-08-09T08:45:48","slug":"niente-cancellazione-tribunali-minorenni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/","title":{"rendered":"Niente cancellazione per i Tribunali dei minorenni"},"content":{"rendered":"<h2>Bloccata la riforma Cartabia nella parte in cui prevedeva la cancellazione dei Tribunali per i Minorenni. Una vittoria del buonsenso. Ma rimane da lavorare per garantire sempre meglio l\u2019interesse superiore dei minori<\/h2>\n<p><!--more--><\/p>\n<p>L\u2019obiettivo era un po\u2019 velleitario e di fatto irrealizzabile \u201ca costo zero\u201d, come invece previsto. Dunque, non stupisce pi\u00f9 di tanto la notizia che la parte della riforma Cartabia, che <strong>prevedeva la cancellazione dei Tribunali per i minorenni<\/strong> e la nascita di 140 sezioni circondariali del nuovo Tribunale unico delle persone e delle famiglie, non si far\u00e0-<br \/>\nAlmeno <strong>fino al 2026<\/strong>, come dovrebbe prevedere la proroga che, sulla linea di quanto successo negli ultimi due anni, arriver\u00e0 a confermare l\u2019attuale situazione, con solo qualche piccola modifica.<\/p>\n<h3>Tribunali dei minorenni: quale futuro?<\/h3>\n<p>A comunicarlo, come riporta il quotidiano <strong>Avvenire<\/strong>, \u00e8 stato il senatore Andrea Ostellari, sottosegretario alla Giustizia, che ha anticipato la creazione di \u201csezioni specializzate per non disperdere le competenze attuali\u201d.<br \/>\nArriva cos\u00ec a una (provvisoria) conclusione una questione che per lungo tempo \u00e8 stata al centro di vibrate e argomentate proteste, ma, come giustamente sottolinea lo stesso giornale della CEI, <strong>la situazione nel suo complesso \u00e8 tutt\u2019altro che risolta<\/strong>, visto che una parte della riforma Cartabia \u00e8 comunque gi\u00e0 in essere e ha gi\u00e0 avuto effetti concreti sulle decisioni dei giudici.<br \/>\nL\u2019esempio riportato da Avvenire \u00e8 quello dell\u2019articolo 403, che \u201clegittima l&#8217;allontanamento urgente del minore dalla propria famiglia disposto dalla pubblica autorit\u00e0, senza tuttavia prevedere adeguate garanzie di controllo\u201d. La riforma Cartabia \u00e8 intervenuta indicando <strong>tempi stringenti da rispettare<\/strong> e step precisi su chi va informato, ma non ha indicato un protocollo sul modo in cui i bambini devono essere allontanati dalle famiglie. Da qui le diverse denunce per soprusi e violenze arrivare in questi anni alle forze dell\u2019ordine, \u201ccolpevoli\u201d di essere intervenute su richiesta dei servizi sociali in molti casi in cui i genitori si opponevano all\u2019allontanamento dei figli.<\/p>\n<h3>23 casi di allontanamento ogni giorno<\/h3>\n<p>Non a caso, anche la garante per l\u2019infanzia e l\u2019adolescenza, Marina Terragni, ha invitato ministero della Giustizia e della Famiglia a mettere a calendario un incontro che <strong>ponga le basi per un protocollo nazionale condiviso<\/strong> da rispettare in casi come questi.<br \/>\nE non si pensi che, in fondo, \u00e8 una questione che riguarda pochi casi, perch\u00e9 i dati pi\u00f9 recenti parlando di 8mila casi all\u2019anno! Quasi uno ogni ora.<br \/>\nC\u2019\u00e8 ancora, e tanto, da lavorare per assicurare il superiore interesse dei minori.<br \/>\nNon a caso, anche il <strong>Forum delle Associazioni Familiari<\/strong> ha definito la decisione, in un comunicato, come &#8220;un atto di realismo, ma anche un\u2019occasione preziosa per ripensare, con coraggio e responsabilit\u00e0, l\u2019intero impianto della giustizia a tutela dei minori e delle famiglie&#8221;<br \/>\n&#8220;\u00c8 positivo &#8211; ha preseguito il presidente <strong>Adriano Bordignon<\/strong> &#8211; che si sia scelta una strada che non smantella, ma valorizza ci\u00f2 che funziona, a partire dal contributo fondamentale dei giudici onorari. Tuttavia, non possiamo ignorare le criticit\u00e0 ancora aperte: la carenza di organico, l\u2019assenza di protocolli chiari per gli allontanamenti, la paralisi dell\u2019attivit\u00e0 ordinaria, il rischio concreto che, senza risorse adeguate, l\u2019urgenza travolga il resto. I minori non possono pagare il prezzo di riforme a costo zero o di scelte legislative affrettate. Decidere della vita di un bambino significa esercitare un potere altissimo che va bilanciato da garanzie forti e da strumenti idonei&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bloccata la riforma Cartabia nella parte in cui prevedeva la cancellazione dei Tribunali per i Minorenni. Una vittoria del buonsenso. Ma rimane da lavorare per garantire sempre meglio l&rsquo;interesse superiore dei minori<\/p>\n","protected":false},"author":102,"featured_media":232271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[457,344],"class_list":["post-232269","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-diritti","tag-tribunale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Niente cancellazione per i Tribunali dei minorenni<\/title>\n<meta name=\"description\" content=\"Bloccata la riforma Cartabia che prevedeva la cancellazione dei Tribunali dei Minorenni. Ma rimane da lavorare per garantire l\u2019interesse superiore dei minori\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Niente cancellazione per i Tribunali dei minorenni\" \/>\n<meta property=\"og:description\" content=\"Bloccata la riforma Cartabia che prevedeva la cancellazione dei Tribunali dei Minorenni. Ma rimane da lavorare per garantire l\u2019interesse superiore dei minori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-08T12:13:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-09T08:45:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Tribunali-dei-minorenni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Niente cancellazione per i Tribunali dei minorenni\",\"datePublished\":\"2025-08-08T12:13:22+00:00\",\"dateModified\":\"2025-08-09T08:45:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Tribunali-dei-minorenni.jpg\",\"keywords\":[\"diritti\",\"tribunale\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/\",\"name\":\"Niente cancellazione per i Tribunali dei minorenni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Tribunali-dei-minorenni.jpg\",\"datePublished\":\"2025-08-08T12:13:22+00:00\",\"dateModified\":\"2025-08-09T08:45:48+00:00\",\"description\":\"Bloccata la riforma Cartabia che prevedeva la cancellazione dei Tribunali dei Minorenni. Ma rimane da lavorare per garantire l\u2019interesse superiore dei minori\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Tribunali-dei-minorenni.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Tribunali-dei-minorenni.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/niente-cancellazione-tribunali-minorenni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Niente cancellazione per i Tribunali dei minorenni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Niente cancellazione per i Tribunali dei minorenni","description":"Bloccata la riforma Cartabia che prevedeva la cancellazione dei Tribunali dei Minorenni. Ma rimane da lavorare per garantire l\u2019interesse superiore dei minori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/","og_locale":"it_IT","og_type":"article","og_title":"Niente cancellazione per i Tribunali dei minorenni","og_description":"Bloccata la riforma Cartabia che prevedeva la cancellazione dei Tribunali dei Minorenni. Ma rimane da lavorare per garantire l\u2019interesse superiore dei minori","og_url":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-08-08T12:13:22+00:00","article_modified_time":"2025-08-09T08:45:48+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Tribunali-dei-minorenni.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Niente cancellazione per i Tribunali dei minorenni","datePublished":"2025-08-08T12:13:22+00:00","dateModified":"2025-08-09T08:45:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/"},"wordCount":560,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Tribunali-dei-minorenni.jpg","keywords":["diritti","tribunale"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/","url":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/","name":"Niente cancellazione per i Tribunali dei minorenni","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Tribunali-dei-minorenni.jpg","datePublished":"2025-08-08T12:13:22+00:00","dateModified":"2025-08-09T08:45:48+00:00","description":"Bloccata la riforma Cartabia che prevedeva la cancellazione dei Tribunali dei Minorenni. Ma rimane da lavorare per garantire l\u2019interesse superiore dei minori","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Tribunali-dei-minorenni.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Tribunali-dei-minorenni.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/niente-cancellazione-tribunali-minorenni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Niente cancellazione per i Tribunali dei minorenni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:25:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/232269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=232269"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/232269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/232271"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=232269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=232269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=232269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}