﻿


{"id":232287,"date":"2025-08-09T08:52:47","date_gmt":"2025-08-09T06:52:47","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=232287"},"modified":"2025-09-16T17:46:12","modified_gmt":"2025-09-16T15:46:12","slug":"adozione-internazionale-cecilia-nuova-figlia-colombia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/","title":{"rendered":"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia"},"content":{"rendered":"<h2>La Cicogna di Amici dei Bambini \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla nel pi\u00f9 dolce viaggio di tutta la vita: quello per rinascere come figlia con la sua nuova famiglia<strong><br \/>\n<\/strong><\/h2>\n<p><!--more--><\/p>\n<p>Se il <a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-nicole-cicogna-honduras\/\">precedente viaggio<\/a> della Cicogna di Ai.Bi. Amici dei Bambini \u00e8 stato un \u201cesordio\u201d in un Paese (l\u2019Honduras) dove mai prima, in oltre 40 anni di storia, era stata per un\u2019Adozione Internazionale, l\u2019ultimo volo verso <strong>la Colombia<\/strong>\u2026 avrebbe potuto farlo a occhi chiusi. La destinazione non era molto distante rispetto alla precedente, con il <strong>Mar dei Caraibi<\/strong> sempre a fare da sfondo, ma il tragitto, in realt\u00e0, \u00e8 ormai collaudato in anni e anni di voli da una parte all\u2019altra dell\u2019Atlantico.<\/p>\n<h3>Adozione Internazionale: un\u2019emozione sempre nuova<\/h3>\n<p>Tutto questo, naturalmente, nulla toglie all\u2019emozione del tragitto, alla gioia di abbracciare con le proprie ali una bambina \u201cnon pi\u00f9 abbandonata\u201d e alla soddisfazione (con immancabile lacrimuccia finale) nel portarla dai suoi genitori, per <strong>tornare finalmente a essere figlia<\/strong> e incamminarsi verso un futuro tante volte immaginato e, ora, finalmente da toccare con mano!<br \/>\nE ancora una volta anche il nostro saluto \u00e8 sempre lo stesso, eppure \u00e8 sempre nuovo e \u201cunico\u201d: <strong>benvenuta Cecilia<\/strong> e grazie ai tuoi genitori Giuseppe e Carmela per la loro splendida accoglienza. La lacrimuccia \u00e8 anche nostra nel vedervi tutti insieme <strong>cominciare questa nuovo capitolo della vostra vita di famiglia<\/strong>.<br \/>\nPer quanto riguarda la cicogna, invece, meglio richiamarla subito all\u2019ordine ed evitare che il sole d\u2019agosto la distragga. Ci sono <strong>nuovi voli all\u2019orizzonte<\/strong>, con l\u2019amata rotta verso la Colombia che torner\u00e0 preso a chiamarla\u2026<\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chiunque, coppie e single, sia interessato ad avere maggiori informazioni sull\u2019Adozione Internazionale o a intraprendere l\u2019iter adottivo pu\u00f2 partecipare ai\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/\"><strong>tanti webinar e corsi<\/strong><\/a>\u00a0organizzati da Ai.Bi. Amici dei Bambini. Per informazioni, contattate l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a>, telefonando al numero 02988221 o utilizzando la nostra live chat, che si apre automaticamente una volta nella pagina dell&#8217;Adozione Internazionale. Verrai messo direttamente in comunicazione con un nostro operatore.<\/p>\n<p>&nbsp;<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*220722-start*\/\n#btnsx-220722{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-220722 .btnsx-text-primary{font-size:21px;line-height:21px;font-weight:700;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-220722:hover .btnsx-text-primary{color:#f4f4f4;}\n#btnsx-220722{background-color:#ee7e0d!important;}\n#btnsx-220722:hover{background-color:#ed650b!important;}\n#btnsx-220722{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-220722{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-220722:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*220722-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/fondo-per-accoglienza\/\" id=\"btnsx-220722\" target=\"_blank\" class=\"btnsx-btn\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Dona per il Fondo Accoglienza Bambini Abbandonati<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>La Cicogna di Amici dei Bambini &egrave; tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla nel pi&ugrave; dolce viaggio di tutta la vita: quello per rinascere come figlia con la sua nuova famiglia<\/p>\n","protected":false},"author":102,"featured_media":232280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,1103,552],"class_list":["post-232287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-cicogna","tag-colombia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia<\/title>\n<meta name=\"description\" content=\"La Cicogna di Ai.Bi. \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla all&#039;adozione internazionale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia\" \/>\n<meta property=\"og:description\" content=\"La Cicogna di Ai.Bi. \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla all&#039;adozione internazionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-09T06:52:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T15:46:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia\",\"datePublished\":\"2025-08-09T06:52:47+00:00\",\"dateModified\":\"2025-09-16T15:46:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg\",\"keywords\":[\"Adozione Internazionale\",\"cicogna\",\"Colombia\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/\",\"name\":\"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg\",\"datePublished\":\"2025-08-09T06:52:47+00:00\",\"dateModified\":\"2025-09-16T15:46:12+00:00\",\"description\":\"La Cicogna di Ai.Bi. \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla all'adozione internazionale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/08\\\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cecilia-nuova-figlia-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia","description":"La Cicogna di Ai.Bi. \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla all'adozione internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia","og_description":"La Cicogna di Ai.Bi. \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla all'adozione internazionale","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-08-09T06:52:47+00:00","article_modified_time":"2025-09-16T15:46:12+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia","datePublished":"2025-08-09T06:52:47+00:00","dateModified":"2025-09-16T15:46:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/"},"wordCount":367,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg","keywords":["Adozione Internazionale","cicogna","Colombia"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/","name":"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg","datePublished":"2025-08-09T06:52:47+00:00","dateModified":"2025-09-16T15:46:12+00:00","description":"La Cicogna di Ai.Bi. \u00e8 tornata a battere la conosciuta rotta verso la Colombia. Per abbracciare Cecilia e accompagnarla all'adozione internazionale","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/08\/Adozione_Internazionale_Colombia-agosto25-NEWS.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cecilia-nuova-figlia-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale. Cecilia: una nuova figlia arrivata dall\u2019amata Colombia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:40:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/232287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=232287"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/232287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/232280"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=232287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=232287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=232287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}