﻿


{"id":232584,"date":"2025-09-04T13:04:43","date_gmt":"2025-09-04T11:04:43","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=232584"},"modified":"2025-09-04T13:04:43","modified_gmt":"2025-09-04T11:04:43","slug":"6-milioni-bambini-scuola","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/","title":{"rendered":"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola"},"content":{"rendered":"<h2>Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso all\u2019istruzione saliranno da 272 a 278 milioni. La situazione pi\u00f9 allarmante in Africa<\/h2>\n<p><!--more--><\/p>\n<p>A volte i numeri, per quanto chiari, non riescono a trasmettere bene ci\u00f2 che rappresentano. Se diciamo \u201c<strong>6 milioni<\/strong>\u201d, per esempio, capiamo subito che si tratta di un a cifra enorme. Ma enorme quanto? Cosa significa, realmente, 6 milioni di bambini?<\/p>\n<h3>Come 75 stadi di San Siro<\/h3>\n<p>Proviamo a fare un piccolo esperimento, allora: immaginiamo lo stadio di San Siro di Milano, gremito di 80mila spettatori. Ogni seggiolino occupato e la percezione, pazzesca, di essere circondato da una folla immensa, urlante, colorata\u2026 \u00c8 una <strong>sensazione quasi fisica<\/strong>, per chi l\u2019ha provata, e molto pi\u00f9 immediata e chiarificatrice di quanto o sia un semplice numero: 80mila.<br \/>\nBene, ora prendiamo quello stadio di San Siro e cloniamolo, mettendo ogni copia una accanto all\u2019altro: per arrivare a 6 milioni, <strong>servono 75 stadi!<\/strong> Tutti strapieni e urlanti allo stesso modo.<br \/>\nSe, poi, immaginiamo quei 75 stadi <strong>pieni solo di bambini<\/strong>, riusciremo forse ad avere un\u2019idea pi\u00f9 chiara di quanto sia terribile la notizia, riportata in una recente analisi di Unicef, che entro la fine del 2026 saranno, per l\u2019appunto, <strong>6 milioni in pi\u00f9 i bambini che non avranno pi\u00f9 la possibilit\u00e0 di frequentare la scuola<\/strong>.<br \/>\nE fermiamoci a questo numero, che gi\u00e0 fa spavento, mettendo tra parentesi che questi 6 milioni di bambini si aggiungono ai <strong>272 milioni che a scuola gi\u00e0 non ci vanno<\/strong> e che, quindi, saliranno a <strong>278 milioni<\/strong>, perch\u00e9 in questo caso di stadi di San Siro ne servirebbero 3.475, e si torna al problema di una grandezza che non si riesce nemmeno a immaginare.<\/p>\n<h3>L\u2019Africa il continente pi\u00f9 colpito<\/h3>\n<p>L\u2019allarme arriva a seguito dei previsti tagli ai fondi destinati agli aiuti umanitari da parte di alcuni governi, Stati Uniti in testa. Ma al di l\u00e0 di chi \u201cabbia lanciato il sasso\u201d, le conseguenze saranno inevitabili per tutti, specie <strong>nei Paesi pi\u00f9 poveri<\/strong> nei quali l\u2019istruzione dipende in maniera massiccia dagli aiuti umanitari.<br \/>\nLo abbiamo <a href=\"https:\/\/www.aibi.it\/ita\/congo-futuro-bambini-goma-scuola\/\">scritto pi\u00f9 volte<\/a>: garantire il diritto all\u2019istruzione \u00e8, per esempio, una delle principali finalit\u00e0 dei progetti \u201c<strong>Adotta a Distanza i bambini di un orfanotrofio<\/strong>\u201d, che Ai.Bi. Amici dei Bambini porta avanti in diversi Paesi, con un\u2019attenzione particolare per quello che riguarda <strong>l\u2019Africa<\/strong>, Continente che sconta una lunga storia di divisioni e difficolt\u00e0 e in cui problemi di questo tipo si manifestano con maggiore veemenza e urgenza.<br \/>\nAmici dei Bambini, attualmente, in Africa, ha attivi progetti di Adozione a Distanza in <strong>Ghana<\/strong>, <strong>Kenya<\/strong>, <strong>Marocco<\/strong>, <strong>Repubblica<\/strong> <strong>Democratica<\/strong> <strong>del<\/strong> <strong>Congo<\/strong>, ma \u00e8 presente anche in <strong>Burundi<\/strong>, <strong>Congo Brazzaville<\/strong>, <strong>Nigeria<\/strong> e <strong>Tunisia<\/strong> con progetti di Cooperazione e con l\u2019Adozione Internazionale.<br \/>\nPerch\u00e9, lo specifica la stessa ricerca, <strong>sar\u00e0 proprio l\u2019Africa a subire l\u2019impatto pi\u00f9 forte<\/strong> per quanto riguarda la perdita di accesso all\u2019istruzione, in particolare negli Stati dell\u2019Africa occidentale e centrale, dove <strong>1,9 milioni<\/strong> di bambini rischiano di perdere la possibilit\u00e0 di andare a scuola, mentre altri <strong>1,4 milioni<\/strong> sono a rischio in Nard Africa e in Medio Oriente.<\/p>\n<h3>Un impegno da condividere<\/h3>\n<p>Ed \u00e8 fondamentale ricordare che perdere l\u2019accesso alla scuola non \u00e8 una questione che riguarda solo l\u2019istruzione e, dunque, il futuro dei bambini (anche se gi\u00e0 questo potrebbe comunque bastare\u2026), perch\u00e9 in molti contesti poveri poter andare a scuola significa anche la <strong>garanzia di almeno un pasto al giorno<\/strong>, significa avere <strong>assistenza<\/strong> e, comunque, entrare in contatto con una realt\u00e0 che \u201csa chi sei\u201d e che, grazie a tutti gli aiuti di operatori, volontari e sostenitori, cerca di <strong>prendersi cura<\/strong> di ogni bambina e ogni bambino, specie i pi\u00f9 soli e abbandonati.<br \/>\nEcco perch\u00e9 l\u2019impegno di Ai.Bi. non verr\u00e0 mai meno, ed ecco perch\u00e9 proprio verso l\u2019Africa si concentrano e si concentreranno i maggiori sforzi e le attenzioni, naturalmente senza dimenticare tutti gli altri contesti in cui Amici dei Bambini \u00e8 attiva e presente da oltre 40 anni.<br \/>\nMa chi conosce Ai.Bi. ormai lo sa: <strong>finch\u00e9 ci sar\u00e0 nel mondo anche un solo bambino abbandonato, Amici dei Bambini sar\u00e0 presente per garantirgli il diritto di essere figlio<\/strong>. E i figli, si sa, devono anche poter andare a scuola!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso all&rsquo;istruzione saliranno da 272 a 278 milioni. La situazione pi&ugrave; allarmante in Africa<\/p>\n","protected":false},"author":102,"featured_media":232586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[472,551,817,545],"class_list":["post-232584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-africa","tag-cooperazione-internazionale","tag-poveri","tag-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nel 2026, altri 6 milioni di bambini non potranno andare a scuola<\/title>\n<meta name=\"description\" content=\"Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso alla scuola saliranno da 272 a 278 milioni entro il 2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola\" \/>\n<meta property=\"og:description\" content=\"Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso alla scuola saliranno da 272 a 278 milioni entro il 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T11:04:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/scuola-Africa-bambini-6-milioni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola\",\"datePublished\":\"2025-09-04T11:04:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/\"},\"wordCount\":702,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/scuola-Africa-bambini-6-milioni.jpg\",\"keywords\":[\"Africa\",\"cooperazione internazionale\",\"poveri\",\"scuola\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/\",\"name\":\"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/scuola-Africa-bambini-6-milioni.jpg\",\"datePublished\":\"2025-09-04T11:04:43+00:00\",\"description\":\"Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso alla scuola saliranno da 272 a 278 milioni entro il 2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/scuola-Africa-bambini-6-milioni.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/scuola-Africa-bambini-6-milioni.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/6-milioni-bambini-scuola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola","description":"Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso alla scuola saliranno da 272 a 278 milioni entro il 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/","og_locale":"it_IT","og_type":"article","og_title":"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola","og_description":"Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso alla scuola saliranno da 272 a 278 milioni entro il 2026","og_url":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-09-04T11:04:43+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/scuola-Africa-bambini-6-milioni.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola","datePublished":"2025-09-04T11:04:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/"},"wordCount":702,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/scuola-Africa-bambini-6-milioni.jpg","keywords":["Africa","cooperazione internazionale","poveri","scuola"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/","url":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/","name":"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/scuola-Africa-bambini-6-milioni.jpg","datePublished":"2025-09-04T11:04:43+00:00","description":"Con i tagli agli aiuti umanitari di diversi Paesi si prevede che i bambini che non avranno accesso alla scuola saliranno da 272 a 278 milioni entro il 2026","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/scuola-Africa-bambini-6-milioni.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/scuola-Africa-bambini-6-milioni.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/6-milioni-bambini-scuola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Nel 2026, altri 6 milioni di bambini non potranno andare a scuola"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:35:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/232584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=232584"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/232584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/232586"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=232584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=232584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=232584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}