﻿{"id":23301,"date":"2011-06-10T15:27:19","date_gmt":"2011-06-10T14:27:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=23301"},"modified":"2011-06-10T15:27:55","modified_gmt":"2011-06-10T14:27:55","slug":"adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/","title":{"rendered":"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-23302\" style=\"margin: 5px;\" title=\"vietnam\" src=\"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/vietnam6-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Il giorno 8 giugno 2011 la Commissione per le Adozioni Internazionali ha ricevuto una delegazione dell\u2019Autorit\u00e0 Centrale del Vietnam, presieduta dal Direttore Nguyen Van Binh.<br \/>\nDurante questo incontro le parti hanno esaminato le prospettive di definizione delle procedure pendenti in Vietnam, depositate prima del 1\u00b0 ottobre 2010, data di sospensione temporanea dei depositi, stabilita dalle autorit\u00e0 vietnamite per poter avviare la transizione al nuovo modello operativo, previsto dalla <strong>legge sulle adozioni entrata in vigore il 1\u00b0 gennaio 2011<\/strong>.<br \/>\nIl Dr. Binh ha confermato quanto gi\u00e0 anticipato nel corso della riunione tenutasi ad Hanoi nel dicembre 2010:<strong> i fascicoli pendenti non decadranno, ma saranno riesaminati per accertare l\u2019eventuale necessit\u00e0 di integrazioni alla luce della nuova legge<\/strong>.<\/p>\n<p>Gli abbinamenti informalmente proposti dalle autorit\u00e0 provinciali prima del 31 dicembre 2010 saranno rispettati, salvo casi di insanabile inadeguatezza del dossier della coppia.<br \/>\nNon appena l\u2019Autorit\u00e0 Centrale vietnamita avr\u00e0 completato (verosimilmente in agosto) la prima raccolta di dossier di minori adottabili all\u2019estero, <strong>gli enti saranno invitati a proporre per l\u2019abbinamento coppie aspiranti all\u2019adozione<\/strong>, individuate tra quelle il cui dossier \u00e8 pendente, seguendo l\u2019ordine temporale del deposito avvenuto prima del 1\u00b0 ottobre 2010.<br \/>\n<strong>Gli enti provvederanno inoltre ad individuare e a segnalare all\u2019Autorit\u00e0 Centrale vietnamita i dossier, tra quelli depositati, relativi a coppie disponibili all\u2019adozione di bambini con \u201cbisogni speciali\u201d<\/strong>. Gli abbinamenti in tal caso saranno decisi dall\u2019Autorit\u00e0 Centrale e non da quelle provinciali.<br \/>\nPer poter far fronte alle necessit\u00e0 dei bambini con \u201cbisogni speciali\u201d in\u00a0attesa di adozione, <strong>l\u2019Autorit\u00e0 Centrale vietnamita ha altres\u00ec deciso di accettare fin da subito il deposito di alcuni dossier di coppie disponibili all\u2019accoglienza di tali bambini<\/strong>, da parte degli enti che non avevano depositato fascicoli nell\u2019imminenza della sospensione.<br \/>\nAll\u2019inizio del 2012 l\u2019Autorit\u00e0 Centrale vietnamita indicher\u00e0 alle Autorit\u00e0 Centrali dei Paesi d\u2019accoglienza il numero di nuovi dossier da presentare nel corso dell\u2019anno. La Commissione e gli enti autorizzati programmeranno insieme le successive attivit\u00e0.<br \/>\n<strong>Il Dr. Binh ha ribadito che, nel giro di qualche mese, sar\u00e0 in grado di dare pi\u00f9 precise indicazioni operative<\/strong>, in corrispondenza al procedere dell\u2019attuazione concreta della nuova legge e all\u2019afflusso presso i Dipartimento di Hanoi delle informazioni sui bambini adottabili nelle varie province.<br \/>\nNello spirito di grande collaborazione ormai da anni consolidato, le due Autorit\u00e0 Centrali italiana e vietnamita hanno valutato insieme alcune ipotesi di cooperazione, anche in vista dell\u2019imminente ratifica, da parte del Vietnam, della Convenzione de L\u2019Aja. Le parti hanno confermato la perdurante applicazione nei loro rapporti della convenzione bilaterale entrata in vigore nel 2004.<br \/>\nNei prossimi giorni la delegazione vietnamita, in attuazione delle nuove disposizioni interne, \u00a0visiter\u00e0 le sedi di tutti gli enti italiani attualmente accreditati nel Paese. La missione si concluder\u00e0 con la partecipazione al <strong>Convegno internazionale che si terr\u00e0 a Firenze nei giorni 13 e 14 giugno<\/strong>, organizzato dalla Commissione, in collaborazione con l\u2019Istituto degli Innocenti, nell\u2019ambito del programma di formazione annuale.<\/p>\n<p>(Fonte: CAI)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il giorno 8 giugno 2011 la CAI ha ricevuto una delegazione dell\u2019Autorit\u00e0 Centrale del Vietnam, presieduta dal Direttore Nguyen Van Binh. Durante questo incontro\u00a0l\u2019Autorit\u00e0 Centrale vietnamita ha deciso di accettare fin da subito il deposito di alcuni dossier di coppie disponibili <strong>all\u2019accoglienza di bambini\u00a0con bisogni particolari<\/strong>.\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/\">LEGGI TUTTO&#8230;<\/a><br \/>\n<\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-23301","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari\" \/>\n<meta property=\"og:description\" content=\"Il giorno 8 giugno 2011 la CAI ha ricevuto una delegazione dell\u2019Autorit\u00e0 Centrale del Vietnam, presieduta dal Direttore Nguyen Van Binh. Durante questo incontro\u00a0l\u2019Autorit\u00e0 Centrale vietnamita ha deciso di accettare fin da subito il deposito di alcuni dossier di coppie disponibili all\u2019accoglienza di bambini\u00a0con bisogni particolari.\u00a0LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-10T14:27:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-06-10T14:27:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari\",\"datePublished\":\"2011-06-10T14:27:19+00:00\",\"dateModified\":\"2011-06-10T14:27:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/vietnam6.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/\",\"name\":\"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/vietnam6.jpg\",\"datePublished\":\"2011-06-10T14:27:19+00:00\",\"dateModified\":\"2011-06-10T14:27:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/vietnam6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/vietnam6.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari","og_description":"Il giorno 8 giugno 2011 la CAI ha ricevuto una delegazione dell\u2019Autorit\u00e0 Centrale del Vietnam, presieduta dal Direttore Nguyen Van Binh. Durante questo incontro\u00a0l\u2019Autorit\u00e0 Centrale vietnamita ha deciso di accettare fin da subito il deposito di alcuni dossier di coppie disponibili all\u2019accoglienza di bambini\u00a0con bisogni particolari.\u00a0LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-06-10T14:27:19+00:00","article_modified_time":"2011-06-10T14:27:55+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari","datePublished":"2011-06-10T14:27:19+00:00","dateModified":"2011-06-10T14:27:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/"},"wordCount":491,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/","name":"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg","datePublished":"2011-06-10T14:27:19+00:00","dateModified":"2011-06-10T14:27:55+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/vietnam6.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-vietnam-accettati-nuovi-dossier-per-i-bambini-con-bisogni-particolari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Internazionali, Vietnam: accettati nuovi dossier per i bambini con bisogni particolari"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:50:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/23301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=23301"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/23301\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=23301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=23301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=23301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}